{"id":1684,"date":"2020-06-18T21:30:33","date_gmt":"2020-06-18T21:30:33","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/?p=1684"},"modified":"2020-09-14T06:06:28","modified_gmt":"2020-09-14T06:06:28","slug":"orientacion-academica-y-profesional","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/2020\/06\/18\/orientacion-academica-y-profesional\/","title":{"rendered":"Orientaci\u00f3n Acad\u00e9mica y Profesional"},"content":{"rendered":"\n<p>\u00bfTienes dudas de c\u00f3mo elegir tu itinerario acad\u00e9mico y profesional?<\/p>\n\n\n\n<p>\u00a1Echa un vistazo a este infograma de Orientaci\u00f3n del #CEPACidCampeador!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2020\/09\/Orientaci\u00f3n-Acad\u00e9mica-y-Profesional-SEPT-20.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"716\" src=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2020\/06\/OAP-JUN-20-1-1024x716.jpg\" alt=\"\" class=\"wp-image-1676\" srcset=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2020\/06\/OAP-JUN-20-1-1024x716.jpg 1024w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2020\/06\/OAP-JUN-20-1-300x210.jpg 300w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2020\/06\/OAP-JUN-20-1-768x537.jpg 768w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2020\/06\/OAP-JUN-20-1.jpg 1080w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfTienes dudas de c\u00f3mo elegir tu itinerario acad\u00e9mico y profesional? \u00a1Echa un vistazo a este infograma de Orientaci\u00f3n del #CEPACidCampeador!<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[82],"post_folder":[],"class_list":["post-1684","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-orientacion"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cepa.cidcampeador.madrid","author_link":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/author\/cuenta_cepa-cidcampeador-madrid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"\u00bfTienes dudas de c\u00f3mo elegir tu itinerario acad\u00e9mico y profesional? \u00a1Echa un vistazo a este infograma de Orientaci\u00f3n del #CEPACidCampeador!","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/posts\/1684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=1684"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/posts\/1684\/revisions"}],"predecessor-version":[{"id":1980,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/posts\/1684\/revisions\/1980"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=1684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=1684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=1684"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=1684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}