{"id":2873,"date":"2021-07-08T11:44:07","date_gmt":"2021-07-08T11:44:07","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/?p=2873"},"modified":"2021-07-29T06:39:15","modified_gmt":"2021-07-29T06:39:15","slug":"la-zapatera-prodigiosa","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/2021\/07\/08\/la-zapatera-prodigiosa\/","title":{"rendered":"La zapatera prodigiosa"},"content":{"rendered":"\n<p>De mano de la profesora y destacable directora teatral, Antonia S\u00e1nchez, con la ilusi\u00f3n y esfuerzo de profesorado y alumnado del <strong>#CEPACidCampeador<\/strong>, disfrutamos el pasado 30 de junio de la representaci\u00f3n de <strong>La zapatera prodigiosa<\/strong>, de Federico Garc\u00eda Lorca.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_CARTEL-724x1024.jpg\" alt=\"\" class=\"wp-image-2870\" width=\"316\" height=\"446\" srcset=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_CARTEL-724x1024.jpg 724w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_CARTEL-212x300.jpg 212w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_CARTEL-768x1087.jpg 768w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_CARTEL-1085x1536.jpg 1085w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_CARTEL.jpg 1240w\" sizes=\"auto, (max-width: 316px) 100vw, 316px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_1-819x1024.jpg\" alt=\"\" class=\"wp-image-2868\" width=\"465\" height=\"581\" srcset=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_1-819x1024.jpg 819w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_1-240x300.jpg 240w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_1-768x960.jpg 768w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_1-1229x1536.jpg 1229w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_1-1638x2048.jpg 1638w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_1.jpg 1920w\" sizes=\"auto, (max-width: 465px) 100vw, 465px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_2-1024x1024.jpg\" alt=\"\" class=\"wp-image-2869\" width=\"502\" height=\"502\" srcset=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_2-1024x1024.jpg 1024w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_2-300x300.jpg 300w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_2-150x150.jpg 150w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_2-768x768.jpg 768w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_2-1536x1536.jpg 1536w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_2-100x100.jpg 100w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_2.jpg 1920w\" sizes=\"auto, (max-width: 502px) 100vw, 502px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/Personajes-La-Zapatera-Prodigiosa-724x1024.jpg\" alt=\"\" class=\"wp-image-2906\" srcset=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/Personajes-La-Zapatera-Prodigiosa-724x1024.jpg 724w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/Personajes-La-Zapatera-Prodigiosa-212x300.jpg 212w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/Personajes-La-Zapatera-Prodigiosa-768x1086.jpg 768w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/Personajes-La-Zapatera-Prodigiosa-1086x1536.jpg 1086w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/Personajes-La-Zapatera-Prodigiosa.jpg 1414w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_sinopsis_.jpg\" alt=\"\" class=\"wp-image-2874\" width=\"396\" height=\"396\" srcset=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_sinopsis_.jpg 480w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_sinopsis_-300x300.jpg 300w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_sinopsis_-150x150.jpg 150w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2021\/07\/La-zapatera-prodigiosa_sinopsis_-100x100.jpg 100w\" sizes=\"auto, (max-width: 396px) 100vw, 396px\" \/><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"2021-06-30_La Zapatera Prodigiosa en CEPA Cid Campeador\" width=\"525\" height=\"394\" src=\"https:\/\/www.youtube.com\/embed\/lxbsTJJpSss?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>De mano de la profesora y destacable directora teatral, Antonia S\u00e1nchez, con la ilusi\u00f3n y esfuerzo de profesorado y alumnado del #CEPACidCampeador, disfrutamos el pasado 30 de junio de la representaci\u00f3n de La zapatera prodigiosa, de Federico Garc\u00eda Lorca.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[15,126,16,41],"post_folder":[],"class_list":["post-2873","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-actividades-complementarias","tag-profesorado","tag-secundaria","tag-teatro"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cepa.cidcampeador.madrid","author_link":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/author\/cuenta_cepa-cidcampeador-madrid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"De mano de la profesora y destacable directora teatral, Antonia S\u00e1nchez, con la ilusi\u00f3n y esfuerzo de profesorado y alumnado del #CEPACidCampeador, disfrutamos el pasado 30 de junio de la representaci\u00f3n de La zapatera prodigiosa, de Federico Garc\u00eda Lorca.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/posts\/2873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=2873"}],"version-history":[{"count":5,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/posts\/2873\/revisions"}],"predecessor-version":[{"id":2907,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/posts\/2873\/revisions\/2907"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=2873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=2873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=2873"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=2873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}