{"id":5644,"date":"2024-03-06T13:38:53","date_gmt":"2024-03-06T12:38:53","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/?p=5644"},"modified":"2024-03-06T13:47:11","modified_gmt":"2024-03-06T12:47:11","slug":"en-el-botanico","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/2024\/03\/06\/en-el-botanico\/","title":{"rendered":"En el Bot\u00e1nico"},"content":{"rendered":"\n<p>Ayer, l@s alumn@s de Secundaria del<strong> #CEPACidCampeador<\/strong> disfrutamos de una soleada ma\u00f1ana en el <strong>Jard\u00edn Bot\u00e1nico<\/strong>, aprendiendo curiosidades sobre camelias, visitando un invernadero de plantas carn\u00edvoras, observando una huerta a\u00fan incipiente y degustando el aroma de la lavanda y la menta. Seguro que volvemos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2024\/03\/1000025363-1024x1024.jpg\" alt=\"\" class=\"wp-image-5645\" width=\"549\" height=\"549\" srcset=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2024\/03\/1000025363-1024x1024.jpg 1024w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2024\/03\/1000025363-300x300.jpg 300w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2024\/03\/1000025363-150x150.jpg 150w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2024\/03\/1000025363-768x768.jpg 768w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2024\/03\/1000025363-1536x1536.jpg 1536w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2024\/03\/1000025363-2048x2048.jpg 2048w, https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/\/wp-content\/uploads\/cepa.cidcampeador.madrid\/2024\/03\/1000025363-100x100.jpg 100w\" sizes=\"auto, (max-width: 549px) 100vw, 549px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ayer, l@s alumn@s de Secundaria del #CEPACidCampeador disfrutamos de una soleada ma\u00f1ana en el Jard\u00edn Bot\u00e1nico, aprendiendo curiosidades sobre camelias, visitando un invernadero de plantas carn\u00edvoras, observando una huerta a\u00fan incipiente y degustando el aroma de la lavanda y la menta. Seguro que volvemos.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[34,232,23],"post_folder":[],"class_list":["post-5644","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-actividades-extraescolares","tag-botanlco","tag-visitas"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cepa.cidcampeador.madrid","author_link":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/author\/cuenta_cepa-cidcampeador-madrid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"Ayer, l@s alumn@s de Secundaria del #CEPACidCampeador disfrutamos de una soleada ma\u00f1ana en el Jard\u00edn Bot\u00e1nico, aprendiendo curiosidades sobre camelias, visitando un invernadero de plantas carn\u00edvoras, observando una huerta a\u00fan incipiente y degustando el aroma de la lavanda y la menta. Seguro que volvemos.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/posts\/5644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=5644"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/posts\/5644\/revisions"}],"predecessor-version":[{"id":5648,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/posts\/5644\/revisions\/5648"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=5644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=5644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=5644"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.cidcampeador.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=5644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}