{"id":2238,"date":"2024-02-26T10:52:05","date_gmt":"2024-02-26T09:52:05","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/?p=2238"},"modified":"2024-07-22T01:06:09","modified_gmt":"2024-07-21T23:06:09","slug":"preparacion-de-la-prueba-de-conocimientos-constitucionales-y-socioculturales-de-espana-ccse","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/2024\/02\/26\/preparacion-de-la-prueba-de-conocimientos-constitucionales-y-socioculturales-de-espana-ccse\/","title":{"rendered":"Conocimientos Constitucionales y Socioculturales de Espa\u00f1a (CCSE)"},"content":{"rendered":"\n<p>En el CEPA Paracuellos de Jarama preparamos la&nbsp;prueba de Conocimientos constitucionales y socioculturales de Espa\u00f1a (CCSE). Esta&nbsp;prueba es un examen elaborado por el Instituto Cervantes que eval\u00faa, por medio de distintas tareas, el conocimiento de la Constituci\u00f3n y de la realidad sociocultural espa\u00f1ola.<\/p>\n\n\n\n<p>La superaci\u00f3n de esta prueba es uno de los requisitos establecidos en las leyes para la adquisici\u00f3n de la nacionalidad para residentes en Espa\u00f1a.<\/p>\n\n\n\n<p>Para la selecci\u00f3n de contenidos de la prueba CCSE, el Instituto Cervantes toma como referencia los siguientes documentos:<\/p>\n\n\n\n<p>Las directrices establecidas en el Marco com\u00fan europeo de referencia (MCER)&nbsp;del Consejo de Europa.<br>La Constituci\u00f3n espa\u00f1ola y otras fuentes de Administraci\u00f3n P\u00fablica de Espa\u00f1a.<br>Los inventarios de \u00abReferentes culturales\u00bb y de \u00abSaberes y comportamientos socioculturales\u00bb del Plan curricular del Instituto Cervantes.<br>El Instituto Cervantes ofrece una aplicaci\u00f3n gratuita para dispositivos m\u00f3viles que permite preparar y practicar con garant\u00edas la prueba CCSE. Se trata de la \u00fanica app oficial CCSE y est\u00e1 totalmente actualizada, por lo que asegura la total correspondencia entre sus preguntas y las incluidas en las pruebas oficiales. La aplicaci\u00f3n puede descargarse tanto desde Google Play como desde App Store de Apple.<\/p>\n\n\n\n<p>Puede consultarse toda la informaci\u00f3n sobre las pruebas CCSE para la obtenci\u00f3n de la nacionalidad espa\u00f1ola por residencia en el portal de Ex\u00e1menes del Instituto Cervantes, en&nbsp;<a href=\"https:\/\/examenes.cervantes.es\/es\/ccse\/que-es\" target=\"_blank\" rel=\"noopener\">https:\/\/examenes.cervantes.es\/es\/ccse\/que-es<\/a>.<\/p>\n\n\n\n<p><strong>\u00bfD\u00f3nde y cu\u00e1ndo se imparten<\/strong><strong>?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>El Curso de Preparaci\u00f3n de la\u00a0Prueba de Conocimientos constitucionales y socioculturales de Espa\u00f1a (CCSE) se imparte en horario de tarde en:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/donde-estamos-en-paracuellos\/\">AULA de Paracuellos<\/a>\u00a0(horario de tarde)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En el CEPA Paracuellos de Jarama preparamos la&nbsp;prueba de Conocimientos constitucionales y socioculturales de Espa\u00f1a (CCSE). Esta&nbsp;prueba es un examen elaborado por el Instituto Cervantes que eval\u00faa, por medio de distintas tareas, el conocimiento de la Constituci\u00f3n y de la realidad sociocultural espa\u00f1ola. La superaci\u00f3n de esta prueba es uno de los requisitos establecidos en<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/2024\/02\/26\/preparacion-de-la-prueba-de-conocimientos-constitucionales-y-socioculturales-de-espana-ccse\/\" class=\"home-blog-btn\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":3,"featured_media":2217,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"post_folder":[],"class_list":["post-2238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-oferta-formativa"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE.jpg",888,600,false],"landscape":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE.jpg",888,600,false],"portraits":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE.jpg",888,600,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE-300x203.jpg",300,203,true],"large":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE.jpg",696,470,false],"thumblist":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE.jpg",500,338,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE.jpg",888,600,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE.jpg",888,600,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE.jpg",360,243,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE.jpg",355,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2024\/02\/Prueba-CCSE.jpg",888,600,false]},"rttpg_author":{"display_name":"cepa.paracuellos","author_link":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/author\/cuenta_cepa-paracuellos\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/category\/oferta-formativa\/\" rel=\"category tag\">Oferta formativa<\/a>","rttpg_excerpt":"En el CEPA Paracuellos de Jarama preparamos la&nbsp;prueba de Conocimientos constitucionales y socioculturales de Espa\u00f1a (CCSE). Esta&nbsp;prueba es un examen elaborado por el Instituto Cervantes que eval\u00faa, por medio de distintas tareas, el conocimiento de la Constituci\u00f3n y de la realidad sociocultural espa\u00f1ola. La superaci\u00f3n de esta prueba es uno de los requisitos establecidos enLeer&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/posts\/2238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/comments?post=2238"}],"version-history":[{"count":4,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/posts\/2238\/revisions"}],"predecessor-version":[{"id":2960,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/posts\/2238\/revisions\/2960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/media\/2217"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/media?parent=2238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/categories?post=2238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/tags?post=2238"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/post_folder?post=2238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}