{"id":3246,"date":"2025-01-10T12:56:42","date_gmt":"2025-01-10T11:56:42","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/?p=3246"},"modified":"2025-01-20T14:54:36","modified_gmt":"2025-01-20T13:54:36","slug":"aula-mentor","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/2025\/01\/10\/aula-mentor\/","title":{"rendered":"Aula Mentor"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"463\" height=\"166\" src=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/imagen_mentor.png\" alt=\"\" class=\"wp-image-3258\" srcset=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/imagen_mentor.png 463w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/imagen_mentor-300x108.png 300w\" sizes=\"auto, (max-width: 463px) 100vw, 463px\" \/><\/figure>\n<\/div>\n\n\n<p>Aula Mentor es un programa de&nbsp;<strong>formaci\u00f3n online no reglada, flexible y con tutorizaci\u00f3n personalizada.<\/strong>&nbsp;Dirigido a personas adultas mayores de 18 a\u00f1os con un extenso cat\u00e1logo de cursos con los que ampliar sus competencias personales y profesionales que les permitan&nbsp;<strong>reforzar las posibilidades de empleabilidad.<\/strong><\/p>\n\n\n\n<p>Actualmente, cuenta con m\u00e1s de 240 cursos de peque\u00f1a duraci\u00f3n, organizados en&nbsp;<a href=\"https:\/\/www.aulamentor.es\/cursos-acceso\/catalogo-de-formacion\/competencias-profesionales\/\" target=\"_blank\" rel=\"noreferrer noopener\">14 \u00c1reas Formativas<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.aulamentor.es\/cursos-acceso\/catalogo-de-formacion\/competencias-profesionales\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"481\" src=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/iti_mentor-1024x481.png\" alt=\"\" class=\"wp-image-3262\" srcset=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/iti_mentor-1024x481.png 1024w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/iti_mentor-300x141.png 300w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/iti_mentor-768x361.png 768w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/iti_mentor-1536x722.png 1536w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/iti_mentor.png 1759w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">A quien va dirigido<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Personas que deseen mejorar su cualificaci\u00f3n profesional .<\/li>\n\n\n\n<li>Personas interesados en iniciarse en campos de conocimiento actuales.&nbsp;<\/li>\n\n\n\n<li>Profesionales que concursan, opositan.<\/li>\n\n\n\n<li>Profesorado que necesita horas de formaci\u00f3n para sexenios (ver convocatoria anual).&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Funcionamiento aula mentor<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"835\" src=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/func_aula_mentor.png\" alt=\"\" class=\"wp-image-3251\" srcset=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/func_aula_mentor.png 730w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/func_aula_mentor-262x300.png 262w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n<\/div>\n\n\n<p>La duraci\u00f3n del curso es variable para cada alumno en funci\u00f3n de la dedicaci\u00f3n y experiencia previa, pero cada uno tiene una duraci\u00f3n m\u00ednima en funci\u00f3n del n\u00famero de entregas al tutor. Una vez que el alumno finaliza todas las actividades del curso, previa autorizaci\u00f3n de su tutor, puede presentarse a examen y obtener un certificado de aprovechamiento si lo supera.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Matr\u00edcula y contacto<\/strong><\/h2>\n\n\n\n<p>La matr\u00edcula est\u00e1 abierta durante todo el a\u00f1o excepto el mes de agosto.<\/p>\n\n\n\n<p>Informaci\u00f3n y documentaci\u00f3n sobre el proceso de matriculaci\u00f3n <a href=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/documentacion-matriculacion\/\" target=\"_blank\" rel=\"noreferrer noopener\">pinchando aqu\u00ed.<\/a><\/p>\n\n\n\n<p>Para contactar con el Administrador del Aula Mentor de Rivas Vaciamadrid:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"mailto:paracuellosdejarama.madrid@aula.mentor.es\" target=\"_blank\" rel=\"noreferrer noopener\">paracuellosdejarama.madrid@aula.mentor.es<\/a><\/li>\n\n\n\n<li><a href=\"mailto:cepa.paracuellos@cuenta_cepa-paracuellos\" target=\"_blank\" rel=\"noreferrer noopener\">cepa.paracuellos@cuenta_cepa-paracuellos<\/a><\/li>\n\n\n\n<li>Tel\u00e9fono: <a href=\"tel:+34916582253\">91 658 22 53<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Requisitos<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tener m\u00e1s de 18 a\u00f1os de edad.&nbsp;<\/li>\n\n\n\n<li>Una fotograf\u00eda.&nbsp;<\/li>\n\n\n\n<li>Fotocopia del DNI.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Calendario de ex\u00e1menes<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"251\" src=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/cal_aula_mentor-1024x251.png\" alt=\"\" class=\"wp-image-3252\" srcset=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/cal_aula_mentor-1024x251.png 1024w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/cal_aula_mentor-300x73.png 300w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/cal_aula_mentor-768x188.png 768w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/cal_aula_mentor-1536x376.png 1536w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/cal_aula_mentor.png 1541w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Si deseas m\u00e1s informaci\u00f3n visita el sitio web de <a href=\"https:\/\/www.aulamentor.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aula Mentor<\/a>.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/08-CURSOS-AULAMENTOR-CISCO-FEB25-724x1024.png\" alt=\"\" class=\"wp-image-3300\" srcset=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/08-CURSOS-AULAMENTOR-CISCO-FEB25-724x1024.png 724w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/08-CURSOS-AULAMENTOR-CISCO-FEB25-212x300.png 212w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/08-CURSOS-AULAMENTOR-CISCO-FEB25-768x1086.png 768w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/08-CURSOS-AULAMENTOR-CISCO-FEB25-1086x1536.png 1086w, https:\/\/site.educa.madrid.org\/cepa.paracuellos\/\/wp-content\/uploads\/cepa.paracuellos\/2025\/01\/08-CURSOS-AULAMENTOR-CISCO-FEB25.png 1414w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Aula Mentor es un programa de&nbsp;formaci\u00f3n online no reglada, flexible y con tutorizaci\u00f3n personalizada.&nbsp;Dirigido a personas adultas mayores de 18 a\u00f1os con un extenso cat\u00e1logo de cursos con los que ampliar sus competencias personales y profesionales que les permitan&nbsp;reforzar las posibilidades de empleabilidad. Actualmente, cuenta con m\u00e1s de 240 cursos de peque\u00f1a duraci\u00f3n, organizados en&nbsp;14<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/2025\/01\/10\/aula-mentor\/\" class=\"home-blog-btn\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"post_folder":[],"class_list":["post-3246","post","type-post","status-publish","format-standard","hentry","category-oferta-formativa"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cepa.paracuellos","author_link":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/author\/cuenta_cepa-paracuellos\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/category\/oferta-formativa\/\" rel=\"category tag\">Oferta formativa<\/a>","rttpg_excerpt":"Aula Mentor es un programa de&nbsp;formaci\u00f3n online no reglada, flexible y con tutorizaci\u00f3n personalizada.&nbsp;Dirigido a personas adultas mayores de 18 a\u00f1os con un extenso cat\u00e1logo de cursos con los que ampliar sus competencias personales y profesionales que les permitan&nbsp;reforzar las posibilidades de empleabilidad. Actualmente, cuenta con m\u00e1s de 240 cursos de peque\u00f1a duraci\u00f3n, organizados en&nbsp;14Leer&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/posts\/3246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/comments?post=3246"}],"version-history":[{"count":17,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/posts\/3246\/revisions"}],"predecessor-version":[{"id":3304,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/posts\/3246\/revisions\/3304"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/media?parent=3246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/categories?post=3246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/tags?post=3246"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cepa.paracuellos\/index.php\/wp-json\/wp\/v2\/post_folder?post=3246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}