{"id":1559,"date":"2013-01-19T10:04:12","date_gmt":"2013-01-19T09:04:12","guid":{"rendered":"http:\/\/cifp.joseluisgarci.alcobendas.educa.madrid.org\/?p=1559"},"modified":"2013-01-19T10:04:12","modified_gmt":"2013-01-19T09:04:12","slug":"jesus-i-garcia-flores-alumno-de-produccion-el-curso-2011-12-gana-un-premio-ondas","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/2013\/01\/19\/jesus-i-garcia-flores-alumno-de-produccion-el-curso-2011-12-gana-un-premio-ondas\/","title":{"rendered":"Jes\u00fas I. Garc\u00eda Flores, alumno de producci\u00f3n el curso 2011-12 GANA UN PREMIO ONDAS!!!!"},"content":{"rendered":"<h3 itemprop=\"name\">Jes\u00fas I. Garc\u00eda Flores, alumno de producci\u00f3n el curso 2011-12 GANA UN PREMIO ONDAS!!!!<\/h3>\n<div><\/div>\n<div id=\"post-body-1615970684810058982\" itemprop=\"description articleBody\">\n<div><a href=\"http:\/\/3.bp.blogspot.com\/-Hqrwl43CruY\/Uoq5CVC3GKI\/AAAAAAAABng\/0Iu4PvYNQ5M\/s1600\/Captura+de+pantalla+2013-11-19+a+las+02.02.57.png\"><img decoding=\"async\" alt=\"\" src=\"http:\/\/3.bp.blogspot.com\/-Hqrwl43CruY\/Uoq5CVC3GKI\/AAAAAAAABng\/0Iu4PvYNQ5M\/s1600\/Captura+de+pantalla+2013-11-19+a+las+02.02.57.png\" border=\"0\" \/><\/a><\/div>\n<div>El 30 de octubre se dio a conocer el fallo del jurado de la 60\u00aa edici\u00f3n de los Premios Ondas en Barcelona, que celebran este a\u00f1o su 60 Aniversario siendo el referente y un observatorio privilegiado del talento del sector audiovisual espa\u00f1ol e internacional.<\/div>\n<div><\/div>\n<div>Radio Barcelona de la SER otorg\u00f3 22 premios a los profesionales, empresas y trabajos nacionales e internacionales m\u00e1s sobresalientes de radio, publicidad radiof\u00f3nica, televisi\u00f3n y m\u00fasica. Y uno de esos 22 premios fue el premio PREMIO ONDAS NACIONAL DE RADIO <strong>a la innovaci\u00f3n radiof\u00f3nica <\/strong>y estamos muy contentos porque ese premio ha sido para el programa <a href=\"http:\/\/www.elextrarradio.com\/que-es-el-extrarradio\/\" target=\"_blank\" rel=\"noopener noreferrer\">El extrarradio. Vida en las afueras<\/a>. Y una de las personas que hace posible cada d\u00eda ese programa es Jes\u00fas I. Garc\u00eda Flores, que hasta Junio del 2012 fue alumno nuestro del ciclo de producci\u00f3n. Asi que podemos presumir de que un alumno nuestro HA GANADO UN PREMIO ONDAS!!!!<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/2.bp.blogspot.com\/-f-4j9CH1BxM\/Uoq2ZPoEXjI\/AAAAAAAABnM\/3E9ZdULY6Hc\/s1600\/fotogrupo.jpg\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"http:\/\/2.bp.blogspot.com\/-f-4j9CH1BxM\/Uoq2ZPoEXjI\/AAAAAAAABnM\/3E9ZdULY6Hc\/s640\/fotogrupo.jpg\" width=\"640\" height=\"426\" border=\"0\" \/><\/a><\/div>\n<div><\/div>\n<div><\/div>\n<div>Para los que no lo sepais los Premios Ondas, decanos y m\u00e1s prestigiosos galardones de radio y televisi\u00f3n que se conceden en Espa\u00f1a, premian cada a\u00f1o a los profesionales, empresas y trabajos nacionales e internacionales m\u00e1s sobresalientes en radio, publicidad radiof\u00f3nica y televisi\u00f3n..En esta edici\u00f3n de los Premios Ondas, que cuentan con el apoyo oficial de la Uni\u00f3n Europea de Radiodifusi\u00f3n (UER), han sido presentadas m\u00e1s de 200 candidaturas de m\u00e1s de 20 pa\u00edses de todo el mundo.En las pr\u00f3ximas semanas se dar\u00e1n a conocer los finalistas de los Premios Ondas por votaci\u00f3n popular; los ganadores se anunciar\u00e1n en la ceremonia de entrega que tendr\u00e1 lugar en el transcurso de la Gran Galaque se celebrar\u00e1 en Barcelona el pr\u00f3ximo 20 de noviembre en el Gran Teatre del Liceu.<\/div>\n<div><\/div>\n<div>Y si quereis saber un poco m\u00e1s sobre el proyecto en el que trabaja Jes\u00fas, al que podeis felicitar en su twitter (@flores_29) os contamos un poco sobre su proyecto:<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/3.bp.blogspot.com\/-wbTnSAIMdnc\/Uoq47amTZ_I\/AAAAAAAABnY\/ZpseR-js-JU\/s1600\/Captura+de+pantalla+2013-11-19+a+las+02.02.46.png\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"http:\/\/3.bp.blogspot.com\/-wbTnSAIMdnc\/Uoq47amTZ_I\/AAAAAAAABnY\/ZpseR-js-JU\/s640\/Captura+de+pantalla+2013-11-19+a+las+02.02.46.png\" width=\"640\" height=\"230\" border=\"0\" \/><\/a><\/div>\n<div><\/div>\n<div><\/div>\n<div>\n<h2><a title=\"Qu\u00e9 es El Extrarradio\" href=\"http:\/\/www.elextrarradio.com\/que-es-el-extrarradio\/\">Qu\u00e9 es El Extrarradio<\/a><\/h2>\n<p> Hacemos las maletas. Tras comprobar el p\u00e9simo momento que vive el periodismo por la actual crisis econ\u00f3mica, nos mudamos a las afueras.  <a href=\"https:\/\/www.lastage.fr\/collections\/coque-samsung-a10\">coque samsung a10<\/a> Dicen que hay un sitio para crear, para tener voz propia, para arriesgar.  <a href=\"https:\/\/www.lastage.fr\/collections\/coque-huawei-p20\">coque huawei p20<\/a> Un lugar donde crecer profesionalmente es posible. Un espacio para pensar, informar y experimentar. Sabemos que el lugar no es c\u00e9ntrico y que costar\u00e1 que nuestra voz llegue a todos los rincones. La vida en las afueras es dura pero nos da igual, necesitamos aire, necesitamos radio. Nos mudamos a <strong>El Extrarradio<\/strong>.<\/div>\n<div><\/div>\n<div><strong>\u00bfQUI\u00c9NES SOMOS?<\/strong> Somos un grupo ecl\u00e9ctico: periodistas, creativos, comunicadores y profesionales de diferentes \u00e1mbitos que compartimos un objetivo: crear un nuevo canal de comunicaci\u00f3n independiente, comprometido y original que arriesgue en sus contenidos y la forma de abordarlos.<\/div>\n<div><\/div>\n<div><strong>\u00bfQU\u00c9 HACEMOS?<\/strong> Periodismo que se aleja de la redacci\u00f3n y se acerca a la calle.  <a href=\"https:\/\/www.lastage.fr\/collections\/coque-autres-huawei\">coque autres huawei<\/a> Reportajes en los que nos metemos en la piel de quienes no somos. Reflexiones para otro mundo posible y necesario. Literatura exquisita para lectores rigurosos. Risas urgentes para realidades malhumoradas.<\/div>\n<div><\/div>\n<div><strong>\u00bfQU\u00c9 QUEREMOS?<\/strong>  Que nos oigas y nos escuches.  <a href=\"https:\/\/www.lastage.fr\/collections\/coque-samsung-a5\">coque samsung a5<\/a> Que nos mires y nos veas. Que nos ayudes y te impliques. Que nos critiques y nos construyas. Que nos creas y nos cuestiones.  Que te emociones y te incomodes.  <a href=\"https:\/\/www.lastage.fr\/collections\/coque-iphone-xs\">coque iphone xs<\/a> Que te entretengas y te enganches. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas I. Garc\u00eda Flores, alumno de producci\u00f3n el curso 2011-12 GANA UN PREMIO ONDAS!!!! El 30 de octubre se dio a conocer el fallo del jurado de la 60\u00aa edici\u00f3n de los Premios Ondas en Barcelona, que celebran este a\u00f1o su 60 Aniversario siendo el referente y un observatorio privilegiado del talento del sector audiovisual<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/2013\/01\/19\/jesus-i-garcia-flores-alumno-de-produccion-el-curso-2011-12-gana-un-premio-ondas\/\" class=\"home-blog-btn\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[99],"class_list":["post-1559","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cifp.joseluisgarci.alcobendas","author_link":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/author\/cuenta_cifp-joseluisgarci-alcobendas\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"Jes\u00fas I. Garc\u00eda Flores, alumno de producci\u00f3n el curso 2011-12 GANA UN PREMIO ONDAS!!!! El 30 de octubre se dio a conocer el fallo del jurado de la 60\u00aa edici\u00f3n de los Premios Ondas en Barcelona, que celebran este a\u00f1o su 60 Aniversario siendo el referente y un observatorio privilegiado del talento del sector audiovisualLeer&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/posts\/1559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/comments?post=1559"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/posts\/1559\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/media?parent=1559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/categories?post=1559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/tags?post=1559"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/post_folder?post=1559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}