{"id":2246,"date":"2015-01-08T17:30:56","date_gmt":"2015-01-08T16:30:56","guid":{"rendered":"http:\/\/cifp.joseluisgarci.alcobendas.educa.madrid.org\/?p=2246"},"modified":"2015-01-08T17:30:56","modified_gmt":"2015-01-08T16:30:56","slug":"cursos-de-empleo-abierto-el-plazo-de-inscripcion-para-los-nuevos-cursos-que-se-impartiran-tras-el-verano","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/2015\/01\/08\/cursos-de-empleo-abierto-el-plazo-de-inscripcion-para-los-nuevos-cursos-que-se-impartiran-tras-el-verano\/","title":{"rendered":"Cursos de Empleo: abierto el plazo de inscripci\u00f3n para los nuevos cursos que se impartir\u00e1n tras el verano"},"content":{"rendered":"<p>Se abre el plazo de preinscripci\u00f3n para los Certificados de Profesionalidad y Cursos para desempleados,  <a href=\"https:\/\/www.sushicube.fr\/collections\/coque-samsung-a5\">coque samsung a5<\/a> que dar\u00e1n comienzo despu\u00e9s del verano.  <a href=\"https:\/\/www.lastage.fr\/collections\/coque-autres-galaxy-samsung\">coque autres galaxy samsung<\/a> Se trata de actividades formativas gratuitas,  <a href=\"https:\/\/www.sushicube.fr\/collections\/coque-huawei-pro\">coque huawei pro<\/a> de especializaci\u00f3n en el \u00e1mbito de lo audiovisual.  <a href=\"https:\/\/www.lastage.fr\/collections\/coque-samsung-a70\">coque samsung a70<\/a> Concretamente dos Certificados de Profesionalidad,\u201c<em>Desarrollo de Productos Audiovisuales Multimedia\u201d y \u201cAsistencia a la producci\u00f3n en televisi\u00f3n\u201d,  <a href=\"https:\/\/www.lastage.fr\/collections\/coque-iphone-6\">coque iphone 6<\/a> <\/em>y un curso largo de \u201c<em>Modelador-texturizador 3D\u201d.<\/em> Los interesados pueden presentar sus solicitudes en la Secretar\u00eda del centro,  <a href=\"https:\/\/www.lastage.fr\/collections\/coque-samsung-a40\">coque samsung a40<\/a> entre las 10:30 h.  <a href=\"https:\/\/www.sushicube.fr\/collections\/coque-iphone-11\">coque iphone 11<\/a> y las  13:30 h., en las fecha concretas que se especifica para cada acci\u00f3n formativa. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se abre el plazo de preinscripci\u00f3n para los Certificados de Profesionalidad y Cursos para desempleados, coque samsung a5 que dar\u00e1n comienzo despu\u00e9s del verano. coque autres galaxy samsung Se trata de actividades formativas gratuitas, coque huawei pro de especializaci\u00f3n en el \u00e1mbito de lo audiovisual. coque samsung a70 Concretamente dos Certificados de Profesionalidad,\u201cDesarrollo de Productos<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/2015\/01\/08\/cursos-de-empleo-abierto-el-plazo-de-inscripcion-para-los-nuevos-cursos-que-se-impartiran-tras-el-verano\/\" class=\"home-blog-btn\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[99],"class_list":["post-2246","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cifp.joseluisgarci.alcobendas","author_link":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/author\/cuenta_cifp-joseluisgarci-alcobendas\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"Se abre el plazo de preinscripci\u00f3n para los Certificados de Profesionalidad y Cursos para desempleados, coque samsung a5 que dar\u00e1n comienzo despu\u00e9s del verano. coque autres galaxy samsung Se trata de actividades formativas gratuitas, coque huawei pro de especializaci\u00f3n en el \u00e1mbito de lo audiovisual. coque samsung a70 Concretamente dos Certificados de Profesionalidad,\u201cDesarrollo de ProductosLeer&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/posts\/2246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/comments?post=2246"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/posts\/2246\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/media?parent=2246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/categories?post=2246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/tags?post=2246"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cifp.joseluisgarci.alcobendas\/index.php\/wp-json\/wp\/v2\/post_folder?post=2246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}