{"id":1844,"date":"2022-09-16T13:05:38","date_gmt":"2022-09-16T11:05:38","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/?p=1844"},"modified":"2022-09-16T13:05:38","modified_gmt":"2022-09-16T11:05:38","slug":"como-cambiar-la-contrasena-de-educamadrid","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/2022\/09\/16\/como-cambiar-la-contrasena-de-educamadrid\/","title":{"rendered":"C\u00f3mo cambiar la contrase\u00f1a de Educamadrid"},"content":{"rendered":"\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/\/wp-content\/uploads\/cp.blasdelezo.parla\/2022\/09\/Pasos-a-seguir-para-cambiar-la-contrasena-de-educamadrid.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Incrustado de Pasos-a-seguir-para-cambiar-la-contrasena-de-educamadrid..\"><\/object><a id=\"wp-block-file--media-13098332-62e9-4162-b76e-2bd93a4d0095\" href=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/\/wp-content\/uploads\/cp.blasdelezo.parla\/2022\/09\/Pasos-a-seguir-para-cambiar-la-contrasena-de-educamadrid.pdf\">Pasos-a-seguir-para-cambiar-la-contrasena-de-educamadrid<\/a><a href=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/\/wp-content\/uploads\/cp.blasdelezo.parla\/2022\/09\/Pasos-a-seguir-para-cambiar-la-contrasena-de-educamadrid.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-13098332-62e9-4162-b76e-2bd93a4d0095\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-1844","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Blas de Lezo","author_link":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/author\/cuenta_tic-cp-blasdelezo-parla\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":null,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/posts\/1844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/comments?post=1844"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/posts\/1844\/revisions"}],"predecessor-version":[{"id":1847,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/posts\/1844\/revisions\/1847"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/media?parent=1844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/categories?post=1844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/tags?post=1844"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/post_folder?post=1844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}