{"id":2833,"date":"2024-02-02T18:45:43","date_gmt":"2024-02-02T17:45:43","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/?p=2833"},"modified":"2024-02-02T18:49:03","modified_gmt":"2024-02-02T17:49:03","slug":"guia-roble-raices-familias","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/2024\/02\/02\/guia-roble-raices-familias\/","title":{"rendered":"Gu\u00eda ROBLE\/RA\u00cdCES: FAMILIAS"},"content":{"rendered":"\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>A la atenci\u00f3n de las familias del CIP Blas de Lezo:<\/p>\n\n\n\n<p>Sois muchos los que nos solicit\u00e1is c\u00f3mo solucionar que no os llegan comunicados desde el centro a trav\u00e9s de Ra\u00edces \/Roble.<\/p>\n\n\n\n<p>Por una parte, os adjuntamos a este comunicado una <a href=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/\/wp-content\/uploads\/cp.blasdelezo.parla\/2024\/02\/Circular-uso-ROBLESRAICES.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>gu\u00eda<\/strong> <\/a>que se ha elaborado desde el profesorado del centro. En ella se especifica los pasos que hay que dar para descargar, instalar y acceder a Roble por parte de las familias.<\/p>\n\n\n\n<p>Adem\u00e1s, hay un apartado que explica c\u00f3mo suscribirse a los diferentes tipos de comunicados que dispone el centro.<\/p>\n\n\n\n<p>Todos los canales que dispone el centro se encuentran activos; pero s\u00ed que hay un tipo de comunicado (Aviso General&gt; Notificaci\u00f3n Roble) que, aunque se encuentra activo y las familias solicitan suscribirse, no permite la suscripci\u00f3n.<\/p>\n\n\n\n<p>Esta incidencia no est\u00e1 en manos del centro, sino que corresponde al sistema Ra\u00edces darle soluci\u00f3n.<\/p>\n\n\n\n<p>Para cualquier duda o consulta, el correo del colegio est\u00e1 disponible: <a href=\"mailto:cp.blasdelezo.parla@educa.madrid.org\">cp.blasdelezo.parla@educa.madrid.org<\/a><\/p>\n\n\n\n<p>Un saludo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Descargas:<\/h4>\n\n\n\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/\/wp-content\/uploads\/cp.blasdelezo.parla\/2024\/02\/Circular-uso-ROBLESRAICES.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Gu\u00eda uso ROBLE\/RA\u00cdCES<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la atenci\u00f3n de las familias del CIP Blas de Lezo: Sois muchos los que nos solicit\u00e1is c\u00f3mo solucionar que no os llegan comunicados desde el centro a trav\u00e9s de &#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,3],"tags":[],"post_folder":[],"class_list":["post-2833","post","type-post","status-publish","format-standard","hentry","category-centro","category-circulares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Blas de Lezo","author_link":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/author\/cuenta_tic-cp-blasdelezo-parla\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/category\/centro\/\" rel=\"category tag\">Centro<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/category\/circulares\/\" rel=\"category tag\">Circulares<\/a>","rttpg_excerpt":"A la atenci\u00f3n de las familias del CIP Blas de Lezo: Sois muchos los que nos solicit\u00e1is c\u00f3mo solucionar que no os llegan comunicados desde el centro a trav\u00e9s de ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/posts\/2833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/comments?post=2833"}],"version-history":[{"count":4,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/posts\/2833\/revisions"}],"predecessor-version":[{"id":2839,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/posts\/2833\/revisions\/2839"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/media?parent=2833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/categories?post=2833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/tags?post=2833"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/post_folder?post=2833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}