{"id":3812,"date":"2025-01-09T23:55:35","date_gmt":"2025-01-09T22:55:35","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/?p=3812"},"modified":"2025-01-09T23:56:14","modified_gmt":"2025-01-09T22:56:14","slug":"aprobacion-consejo-escolar-no-recogida-objetos-olvidados-alumnos","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/2025\/01\/09\/aprobacion-consejo-escolar-no-recogida-objetos-olvidados-alumnos\/","title":{"rendered":"APROBACI\u00d3N CONSEJO ESCOLAR NO RECOGIDA DE CUALQUIER OBJETO OLVIDADO POR LOS ALUMNOS"},"content":{"rendered":"<p>El pasado<strong> 12 de diciembre e 2024<\/strong>, en el pleno del <strong>Consejo Escolar<\/strong>, se <strong>aprob\u00f3 por mayor\u00eda<\/strong> que, <strong>a partir del curso 2025\/2026<\/strong>, una vez los alumnos hayan entrado al centro, <strong>NO se recoger\u00e1n ni se llevar\u00e1n a las aulas ning\u00fan objeto olvidado por estos (desayunos, estuches, botellas de agua, material escolar, materiales de actividades extraescolares &#8230;)<\/strong><\/p>\n<p>Toda la informaci\u00f3n relacionada a este respecto la pod\u00e9is encontrar en:<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/convivencia\/#recogida-objetos\" target=\"_blank\" rel=\"noopener\">CEIP BLAS DE LEZO &gt; CONVIVENCIA &gt; Recogida de materiales o cualquier objeto olvidado por los alumnos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 12 de diciembre e 2024, en el pleno del Consejo Escolar, se aprob\u00f3 por mayor\u00eda que, a partir del curso 2025\/2026, una vez los alumnos hayan entrado al &#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,26,3,31],"tags":[77,130,129,131,128],"post_folder":[],"class_list":["post-3812","post","type-post","status-publish","format-standard","hentry","category-admision","category-centro","category-circulares","category-informacion-a-las-familias","tag-alumnos","tag-materiales","tag-objetos","tag-olvidados","tag-recogida"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Blas de Lezo","author_link":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/author\/cuenta_tic-cp-blasdelezo-parla\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/category\/admision\/\" rel=\"category tag\">Admisi\u00f3n<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/category\/centro\/\" rel=\"category tag\">Centro<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/category\/circulares\/\" rel=\"category tag\">Circulares<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/category\/informacion-a-las-familias\/\" rel=\"category tag\">Informaci\u00f3n a las familias<\/a>","rttpg_excerpt":"El pasado 12 de diciembre e 2024, en el pleno del Consejo Escolar, se aprob\u00f3 por mayor\u00eda que, a partir del curso 2025\/2026, una vez los alumnos hayan entrado al ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/posts\/3812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/comments?post=3812"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/posts\/3812\/revisions"}],"predecessor-version":[{"id":3816,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/posts\/3812\/revisions\/3816"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/media?parent=3812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/categories?post=3812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/tags?post=3812"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.blasdelezo.parla\/index.php\/wp-json\/wp\/v2\/post_folder?post=3812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}