{"id":10089,"date":"2021-12-21T14:56:48","date_gmt":"2021-12-21T12:56:48","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=10089"},"modified":"2021-12-21T14:56:48","modified_gmt":"2021-12-21T12:56:48","slug":"recaudacion-una-ilusion-por-la-palma","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/12\/21\/recaudacion-una-ilusion-por-la-palma\/","title":{"rendered":"RECAUDACI\u00d3N UNA ILUSI\u00d3N POR LA PALMA"},"content":{"rendered":"<div>Una vez m\u00e1s, agradeceros en nombre de Cruz Roja, toda la solidaridad que hab\u00e9is recaudado.<\/div>\n<div><\/div>\n<div>Te adjuntamos el recibo del ingreso a la cuenta de Cruz Roja especifica de la Palma.<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10090 size-full\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/12\/UNA-ILUSION-PARA-PALMA-CHEQUE.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/12\/UNA-ILUSION-PARA-PALMA-CHEQUE.jpg 960w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/12\/UNA-ILUSION-PARA-PALMA-CHEQUE-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/12\/UNA-ILUSION-PARA-PALMA-CHEQUE-768x576.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/div>\n<div><\/div>\n<div>Como siempre quedamos a vuestra disposici\u00f3n para cualquier iniciativa que pueda surgir.<\/div>\n<div><\/div>\n<div>Un abrazo muy muy\u00a0 fuerte.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una vez m\u00e1s, agradeceros en nombre de Cruz Roja, toda la solidaridad que hab\u00e9is recaudado. Te adjuntamos el recibo del ingreso a la cuenta de Cruz Roja especifica de la Palma. Como siempre quedamos a vuestra disposici\u00f3n para cualquier iniciativa que pueda surgir. Un abrazo muy muy\u00a0 fuerte.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,29],"tags":[],"post_folder":[],"class_list":["post-10089","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Una vez m\u00e1s, agradeceros en nombre de Cruz Roja, toda la solidaridad que hab\u00e9is recaudado. Te adjuntamos el recibo del ingreso a la cuenta de Cruz Roja especifica de la Palma. Como siempre quedamos a vuestra disposici\u00f3n para cualquier iniciativa que pueda surgir. Un abrazo muy muy\u00a0 fuerte.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=10089"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10089\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=10089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=10089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=10089"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=10089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}