{"id":10147,"date":"2022-01-23T09:19:04","date_gmt":"2022-01-23T07:19:04","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=10147"},"modified":"2022-01-23T09:19:04","modified_gmt":"2022-01-23T07:19:04","slug":"ruta-guiada-para-personal-del-centro-con-el-escritor-jose-antonio-lopez-medina-viernes-4-de-febrero","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/01\/23\/ruta-guiada-para-personal-del-centro-con-el-escritor-jose-antonio-lopez-medina-viernes-4-de-febrero\/","title":{"rendered":"RUTA GUIADA PARA PERSONAL DEL CENTRO CON EL ESCRITOR JOS\u00c9 ANTONIO L\u00d3PEZ MEDINA (VIERNES 4 DE FEBRERO)"},"content":{"rendered":"<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">Ya tenemos fecha, para la 2\u00aa ruta guiada de Leyendas de Aranjuez con Jos\u00e9 Antonio L\u00f3pez Medina,<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">\u00a0para el personal del Centro, para descubrir la H\u00aa y leyendas de <\/span><span class=\"r-18u37iz\"><a class=\"css-4rbku5 css-18t94o4 css-901oao css-16my406 r-1cvl2hr r-1loqt21 r-poiln3 r-bcqeeo r-qvutc0\" dir=\"ltr\" role=\"link\" href=\"https:\/\/twitter.com\/hashtag\/Aranjuez?src=hashtag_click\">#Aranjuez<\/a><\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">, muchas gracias Jos\u00e9 Antonio L\u00f3pez Medina por ense\u00f1arnos y mostrarnos nuestro Real Sitio y Villa.<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/FJdvM6qWYAExiUX?format=jpg&amp;name=small\" alt=\"Imagen\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya tenemos fecha, para la 2\u00aa ruta guiada de Leyendas de Aranjuez con Jos\u00e9 Antonio L\u00f3pez Medina,\u00a0para el personal del Centro, para descubrir la H\u00aa y leyendas de #Aranjuez, muchas gracias Jos\u00e9 Antonio L\u00f3pez Medina por ense\u00f1arnos y mostrarnos nuestro Real Sitio y Villa.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,68],"tags":[],"post_folder":[],"class_list":["post-10147","post","type-post","status-publish","format-standard","hentry","category-actividades","category-actividades-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"Ya tenemos fecha, para la 2\u00aa ruta guiada de Leyendas de Aranjuez con Jos\u00e9 Antonio L\u00f3pez Medina,\u00a0para el personal del Centro, para descubrir la H\u00aa y leyendas de #Aranjuez, muchas gracias Jos\u00e9 Antonio L\u00f3pez Medina por ense\u00f1arnos y mostrarnos nuestro Real Sitio y Villa.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=10147"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10147\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=10147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=10147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=10147"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=10147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}