{"id":10239,"date":"2022-02-20T09:05:35","date_gmt":"2022-02-20T07:05:35","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=10239"},"modified":"2022-02-20T09:05:35","modified_gmt":"2022-02-20T07:05:35","slug":"broadway-in-carlos-iii-los-pasillos-de-los-musicales","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/02\/20\/broadway-in-carlos-iii-los-pasillos-de-los-musicales\/","title":{"rendered":"BROADWAY IN CARLOS III \u00abLOS PASILLOS DE LOS MUSICALES\u00bb"},"content":{"rendered":"<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">Poco a poco los pasillos del Colegio <\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"> se van llenando de color, luces, m\u00fasica, focos y arte. Cada clase est\u00e1 ha elegido un musical para decorar su puerta, aqu\u00ed os ense\u00f1amos la galer\u00eda que est\u00e1n creando.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/pbs.twimg.com\/media\/FL8ThW4XsAQqseI?format=jpg&amp;name=large\" alt=\"Imagen\" width=\"206\" height=\"275\" \/><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/pbs.twimg.com\/media\/FL8Z35qWYAI4i40?format=jpg&amp;name=small\" alt=\"Imagen\" width=\"206\" height=\"275\" \/><\/p>\n<p>4\u00baA\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 KINDERVILLA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poco a poco los pasillos del Colegio se van llenando de color, luces, m\u00fasica, focos y arte. Cada clase est\u00e1 ha elegido un musical para decorar su puerta, aqu\u00ed os ense\u00f1amos la galer\u00eda que est\u00e1n creando. 4\u00baA\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/02\/20\/broadway-in-carlos-iii-los-pasillos-de-los-musicales\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abBROADWAY IN CARLOS III \u00abLOS PASILLOS DE LOS MUSICALES\u00bb\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63,3,21,23],"tags":[],"post_folder":[],"class_list":["post-10239","post","type-post","status-publish","format-standard","hentry","category-4-primaria","category-actividades","category-infantil","category-kindervilla"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/4-primaria\/\" rel=\"category tag\">4\u00ba Primaria<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/\" rel=\"category tag\">Infantil<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/kindervilla\/\" rel=\"category tag\">KINDERVILLA<\/a>","rttpg_excerpt":"Poco a poco los pasillos del Colegio se van llenando de color, luces, m\u00fasica, focos y arte. Cada clase est\u00e1 ha elegido un musical para decorar su puerta, aqu\u00ed os ense\u00f1amos la galer\u00eda que est\u00e1n creando. 4\u00baA\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=10239"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10239\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=10239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=10239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=10239"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=10239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}