{"id":10253,"date":"2022-02-23T23:43:49","date_gmt":"2022-02-23T21:43:49","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=10253"},"modified":"2022-02-23T23:43:49","modified_gmt":"2022-02-23T21:43:49","slug":"comunicado-ayuntamineto-carnaval-sabado-26-de-febrero-de-2022","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/02\/23\/comunicado-ayuntamineto-carnaval-sabado-26-de-febrero-de-2022\/","title":{"rendered":"COMUNICADO AYUNTAMINETO: CARNAVAL S\u00c1BADO 26 DE FEBRERO DE 2022"},"content":{"rendered":"<p><u>EL PR\u00d3XIMO S\u00c1BADO 26 DE FEBRERO, A PARTIR DE LAS 17,00 HORAS, TENDR\u00c1 LUGAR EL DESFILE DE COMPARSAS<\/u><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>EL CARNAVAL REGRESA A LAS CALLES DE ARANJUEZ TRAS UN A\u00d1O DE PAR\u00d3N<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Aranjuez, 23 de febrero de 2022<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>El pr\u00f3ximo s\u00e1bado 26 de febrero regresan los Carnavales a Aranjuez despu\u00e9s de un a\u00f1o sin poder celebrarse debido a la pandemia. El pre\u00e1mbulo a la fiesta correr\u00e1 a cargo del Combo de la Escuela Municipal de M\u00fasica Joaqu\u00edn Rodrigo, a las 13,00 horas, en la Plaza de la Constituci\u00f3n. A las 17,00 horas, el colorido y la fantas\u00eda del desfile de Comparsas del Carnaval de Aranjuez 2022 marcar\u00e1n el punto \u00e1lgido de esta celebraci\u00f3n que culminar\u00e1 con el entierro de la sardina, el pr\u00f3ximo mi\u00e9rcoles d\u00eda 2 de marzo, a partir de las 19,00 horas.<\/p>\n<p>&nbsp;<\/p>\n<p>El desfile de Comparsas dar\u00e1 inicio en la Plaza de la Constituci\u00f3n y recorrer\u00e1 las calles Stuart, Real y Alm\u00edbar hasta llegar a la Plaza de Toros. Una vez all\u00ed, las comparsas podr\u00e1n llevar a cabo una animaci\u00f3n por un tiempo l\u00edmite de dos minutos.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/FMUAXklXoAYrgun?format=jpg&amp;name=900x900\" alt=\"Imagen\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La entrega de premios est\u00e1 prevista tenga lugar a las 19.00 horas. Las Comparsas participantes deber\u00e1n estar compuestas por un m\u00ednimo de 8 personas y habr\u00e1 dos modalidades: la infantil, cuyos integrantes deber\u00e1n ser menores de 14 a\u00f1os en un 80% del total y la modalidad de adultos, integradas por mayores de 14 a\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<p>Respecto a los premios, se han establecido un total de seis; tres para las mejores comparsas infantiles y otros tres para la modalidad de adultos. En ambas modalidades la valoraci\u00f3n se realizar\u00e1 en base a los siguientes conceptos: DISFRAZ donde se premiar\u00e1 la originalidad, creatividad, complejidad del dise\u00f1o, vistosidad, colorido y riqueza de detalles; COREOGRAF\u00cdA que premiar\u00e1 la coordinaci\u00f3n, complejidad y vistosidad; y M\u00daSICA donde se premiar\u00e1 la animaci\u00f3n y el ritmo.<\/p>\n<p>&nbsp;<\/p>\n<p>Tras la entrega de premios tendr\u00e1 lugar la actuaci\u00f3n de Dj Miguel Dejota, con el que disfrutaremos hasta las 22.00 horas.<\/p>\n<p>&nbsp;<\/p>\n<p>Por otro lado, un a\u00f1o m\u00e1s, los alumnos y profesores de Bellas Artes, Dise\u00f1o y Moda de la URJC y la Uni\u00f3n de Estudiantes por Aranjuez (UEPA) organizar\u00e1n el tradicional Entierro de la Sardina que tendr\u00e1 lugar el pr\u00f3ximo mi\u00e9rcoles 2 de marzo, a las 19,00 horas, y cuya salida partir\u00e1 de la calle Guardias de Corps.<\/p>\n<p>&nbsp;<\/p>\n<p>El Concejal Delegado de Fiestas, Miguel G\u00f3mez Herrero, ha animado a los ribere\u00f1os <strong>\u201ca participar en el pr\u00f3ximo Carnaval que <\/strong><strong>despu\u00e9s de todo el sufrimiento de estos dos \u00faltimos a\u00f1os ya toca un poco de esparcimiento y de alegr\u00eda y con ese \u00e1nimo hemos organizado estos Carnavales, que no ser\u00edan posible sin el esfuerzo de los diferentes colectivos de nuestra ciudad\u201d<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Miguel G\u00f3mez Herrero ha aconsejado que <strong>\u201ces importante la responsabilidad individual porque, aunque los datos del Covid hayan mejorado, el virus sigue estando presente y por ello se aconseja el uso de mascarilla cuando no se puedan mantener las distancias m\u00ednimas de seguridad\u201d.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u201cAgradecemos la colaboraci\u00f3n de toda la ciudadan\u00eda para que estos Carnavales se desarrollen con la m\u00e1xima seguridad y os deseamos un feliz Carnaval\u201d,<\/strong> ha finalizado Miguel G\u00f3mez Herrero.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/02\/NOTA-AYTO-INFORMATIVA-PASACALLES-CARNAVAL-2022.pdf\">NOTA AYTO INFORMATIVA PASACALLES CARNAVAL 2022<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL PR\u00d3XIMO S\u00c1BADO 26 DE FEBRERO, A PARTIR DE LAS 17,00 HORAS, TENDR\u00c1 LUGAR EL DESFILE DE COMPARSAS \u00a0 EL CARNAVAL REGRESA A LAS CALLES DE ARANJUEZ TRAS UN A\u00d1O DE PAR\u00d3N \u00a0 Aranjuez, 23 de febrero de 2022 \u00a0 El pr\u00f3ximo s\u00e1bado 26 de febrero regresan los Carnavales a Aranjuez despu\u00e9s de un a\u00f1o &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/02\/23\/comunicado-ayuntamineto-carnaval-sabado-26-de-febrero-de-2022\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO AYUNTAMINETO: CARNAVAL S\u00c1BADO 26 DE FEBRERO DE 2022\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,30],"tags":[],"post_folder":[],"class_list":["post-10253","post","type-post","status-publish","format-standard","hentry","category-actividades","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"EL PR\u00d3XIMO S\u00c1BADO 26 DE FEBRERO, A PARTIR DE LAS 17,00 HORAS, TENDR\u00c1 LUGAR EL DESFILE DE COMPARSAS \u00a0 EL CARNAVAL REGRESA A LAS CALLES DE ARANJUEZ TRAS UN A\u00d1O DE PAR\u00d3N \u00a0 Aranjuez, 23 de febrero de 2022 \u00a0 El pr\u00f3ximo s\u00e1bado 26 de febrero regresan los Carnavales a Aranjuez despu\u00e9s de un a\u00f1o&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=10253"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10253\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=10253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=10253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=10253"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=10253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}