{"id":10260,"date":"2022-02-26T16:21:27","date_gmt":"2022-02-26T14:21:27","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=10260"},"modified":"2022-02-26T16:21:27","modified_gmt":"2022-02-26T14:21:27","slug":"comunicado-urgente-aplazado-el-desfile-del-carnaval","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/02\/26\/comunicado-urgente-aplazado-el-desfile-del-carnaval\/","title":{"rendered":"COMUNICADO URGENTE: APLAZADO EL DESFILE DEL CARNAVAL"},"content":{"rendered":"<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">MUY URGENTE: desde la Delegaci\u00f3n de Festejos del Ayuntamiento de Aranjuez<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"> nos acaban de comunicar, que por motivos meteorol\u00f3gicos, el desfile de carnaval por las calles de Aranjuez, previsto para esta tarde queda aplazado para ma\u00f1ana, domingo 27 de febrero a las 17:00, misma hora, mismo recorrido. Seg\u00fan nos informa el AMPA nuestra comparsa est\u00e1 convocada para el domingo 27 de febrero a las 16:30 en la puerta del Ayuntamiento.<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/FMh1SZ2XIAACVJi?format=jpg&amp;name=medium\" alt=\"Imagen\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MUY URGENTE: desde la Delegaci\u00f3n de Festejos del Ayuntamiento de Aranjuez nos acaban de comunicar, que por motivos meteorol\u00f3gicos, el desfile de carnaval por las calles de Aranjuez, previsto para esta tarde queda aplazado para ma\u00f1ana, domingo 27 de febrero a las 17:00, misma hora, mismo recorrido. Seg\u00fan nos informa el AMPA nuestra comparsa est\u00e1 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/02\/26\/comunicado-urgente-aplazado-el-desfile-del-carnaval\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO URGENTE: APLAZADO EL DESFILE DEL CARNAVAL\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,3,29],"tags":[],"post_folder":[],"class_list":["post-10260","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias","category-actividades","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"MUY URGENTE: desde la Delegaci\u00f3n de Festejos del Ayuntamiento de Aranjuez nos acaban de comunicar, que por motivos meteorol\u00f3gicos, el desfile de carnaval por las calles de Aranjuez, previsto para esta tarde queda aplazado para ma\u00f1ana, domingo 27 de febrero a las 17:00, misma hora, mismo recorrido. Seg\u00fan nos informa el AMPA nuestra comparsa est\u00e1&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=10260"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10260\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=10260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=10260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=10260"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=10260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}