{"id":10290,"date":"2022-03-04T08:01:15","date_gmt":"2022-03-04T06:01:15","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=10290"},"modified":"2022-03-04T08:01:15","modified_gmt":"2022-03-04T06:01:15","slug":"recordatorio-historias-y-leyendas-para-familias-curiosas-sabados-5-marzo-y-2-de-abril","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/03\/04\/recordatorio-historias-y-leyendas-para-familias-curiosas-sabados-5-marzo-y-2-de-abril\/","title":{"rendered":"RECORDATORIO HISTORIAS Y LEYENDAS PARA FAMILIAS CURIOSAS (S\u00c1BADOS 5 MARZO Y 2 DE ABRIL)"},"content":{"rendered":"<div>\n<p>Estimadas familias:<\/p>\n<p>La actividad ambos d\u00edas (<strong>s\u00e1bados 5 de marzo y 2 de abril) comenzar\u00e1 a las 17:00 horas, en la Plaza El\u00edptica del Palacio Real<\/strong> (situada junto al patio de armas) y concluir\u00e1 aproximadamente a las 19:00 horas.<\/p>\n<p>Consiste en un paseo guiado por el casco hist\u00f3rico de Aranjuez, donde Jos\u00e9 Antonio L\u00f3pez Medina, escritor local, nos ir\u00e1 descubriendo parte de la Historia de Espa\u00f1a a trav\u00e9s de la narraci\u00f3n de los acontecimientos m\u00e1s importantes ocurridos en Aranjuez, aderezado con alguna leyenda fant\u00e1stica de nuestra localidad o relacionada con ella.<\/p>\n<\/div>\n<p>Recordamos que los que todav\u00eda no han realizado el pagado de la actividad, deben realizarlo a trav\u00e9s de la app bizum, al siguiente n\u00famero de tel\u00e9fono 622474529, indicando al menos el nombre de alguno de los alumnos\/as, para saber de qui\u00e9n es el dinero. El dinero recaudado ser\u00e1 para adquirir libros para la Biblioteca Escolar del Centro.<\/p>\n<p>Socios del AMPA: 1\u20ac\/persona.<\/p>\n<p>No socios del AMPA: 2\u20ac\/persona.<\/p>\n<p>Quedan plazas para el d\u00eda 2 de abril.<\/p>\n<p>No esperes a que te lo cuente, ven y disfr\u00fatalo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10214\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/02\/CARTEL-HISTORIA-DE-ARANJUEZ-FAMILIAS-MODIFICACION-DE-FECHAS-1.jpg\" alt=\"\" width=\"2000\" height=\"1600\" \/><\/p>\n<p>Y os dejamos el siguiente enlace, con toda la informaci\u00f3n sobre estas visitas guiadas, con el escritor Jos\u00e9 Antonio L\u00f3pez Medina.<\/p>\n<p><a href=\"https:\/\/colegiocarlosiii.com\/ii-carlos-iii-happy-days-rutas-guiadas-por-aranjuez-con-jose-luis-lopez-medina\/\">https:\/\/colegiocarlosiii.com\/ii-carlos-iii-happy-days-rutas-guiadas-por-aranjuez-con-jose-luis-lopez-medina\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: La actividad ambos d\u00edas (s\u00e1bados 5 de marzo y 2 de abril) comenzar\u00e1 a las 17:00 horas, en la Plaza El\u00edptica del Palacio Real (situada junto al patio de armas) y concluir\u00e1 aproximadamente a las 19:00 horas. Consiste en un paseo guiado por el casco hist\u00f3rico de Aranjuez, donde Jos\u00e9 Antonio L\u00f3pez Medina, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/03\/04\/recordatorio-historias-y-leyendas-para-familias-curiosas-sabados-5-marzo-y-2-de-abril\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abRECORDATORIO HISTORIAS Y LEYENDAS PARA FAMILIAS CURIOSAS (S\u00c1BADOS 5 MARZO Y 2 DE ABRIL)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,3,69,29,30],"tags":[],"post_folder":[],"class_list":["post-10290","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias","category-actividades","category-ampa","category-noticias","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/ampa\/\" rel=\"category tag\">AMPA<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"Estimadas familias: La actividad ambos d\u00edas (s\u00e1bados 5 de marzo y 2 de abril) comenzar\u00e1 a las 17:00 horas, en la Plaza El\u00edptica del Palacio Real (situada junto al patio de armas) y concluir\u00e1 aproximadamente a las 19:00 horas. Consiste en un paseo guiado por el casco hist\u00f3rico de Aranjuez, donde Jos\u00e9 Antonio L\u00f3pez Medina,&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=10290"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10290\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=10290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=10290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=10290"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=10290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}