{"id":10346,"date":"2022-03-16T16:09:51","date_gmt":"2022-03-16T14:09:51","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=10346"},"modified":"2022-03-16T16:09:51","modified_gmt":"2022-03-16T14:09:51","slug":"normativa-xi-cross-escolar-urbano-carlos-iii-27-de-marzo-de-2022","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/03\/16\/normativa-xi-cross-escolar-urbano-carlos-iii-27-de-marzo-de-2022\/","title":{"rendered":"NORMATIVA XI CROSS ESCOLAR URBANO \u201cCARLOS III\u201d (27 DE MARZO DE 2022)"},"content":{"rendered":"<p>El pr\u00f3ximo d\u00eda 27 de marzo vamos a celebrar el <strong>XI<\/strong> <strong>CROSS ESCOLAR URBANO \u201cCARLOS III\u201d. <\/strong>El AMPA del colegio<strong>\u00a0\u00a0 <\/strong>tiene el honor de invitar a todos los Colegios y A.M.P.A.s para que participen en este acontecimiento deportivo. Este a\u00f1o de nuevo tendremos una competici\u00f3n de Marcha N\u00f3rdica.<\/p>\n<p>Al igual que en a\u00f1os anteriores, continuaremos con la iniciativa que pusimos en marcha en 2019, <strong><u>DORSAL SOLIDARIO<\/u><\/strong>\u00a0 que este a\u00f1o recaer\u00e1 en la <strong>FundAME<\/strong> (Fundaci\u00f3n Atrofia Muscular Espinal). El mismo d\u00eda de la carrera se puede adquirir el dorsal, por un <strong>1\u20ac.<\/strong> En las carreras <strong><em>de Marcha N\u00f3rdica, Open y Mini Carlitos<\/em><\/strong> para participar se podr\u00e1 recoger el dorsal solidario por 1\u20ac el mismo d\u00eda de la carrera, adem\u00e1s quien quiera colaborar podr\u00e1 adquirir el dorsal solidario el mismo d\u00eda de la prueba.<\/p>\n<p><strong><u>N O R M A S:<\/u><\/strong><\/p>\n<ul>\n<li>Pueden participar todos los alumnos\/as que est\u00e9n incluidos en las edades comprendidas en las categor\u00edas que a continuaci\u00f3n se detallan:<\/li>\n<li>Todos los alumnos participantes deber\u00e1n estar con sus monitores.<\/li>\n<li>Las pruebas comenzaran a las 09:30 horas guardando el siguiente orden:<\/li>\n<\/ul>\n<table width=\"882\">\n<tbody>\n<tr>\n<td colspan=\"6\" width=\"882\"><strong><em>RELACI\u00d3N DE HORARIOS Y CATEGOR\u00cdAS<\/em><\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>CATEGOR\u00cdA<\/em><\/strong><\/td>\n<td width=\"241\"><strong><em>A\u00d1O NACIMIENTO<\/em><\/strong><\/td>\n<td colspan=\"2\" width=\"210\"><strong><em>MASCULINO<\/em><\/strong><\/td>\n<td colspan=\"2\" width=\"207\"><strong><em>FEMENINO<\/em><\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>\u00a0<\/em><\/strong><\/td>\n<td width=\"241\"><strong><em>\u00a0<\/em><\/strong><\/td>\n<td width=\"113\"><strong><em>Distancia<\/em><\/strong><\/td>\n<td width=\"96\"><strong><em>Salida<\/em><\/strong><\/td>\n<td width=\"114\"><strong><em>Distancia<\/em><\/strong><\/td>\n<td width=\"94\"><strong><em>Salida<\/em><\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>MARCHA N\u00d3RDICA <\/em><\/strong><strong><em>(adultos)<\/em><\/strong><\/td>\n<td width=\"241\"><strong><em>Nacidos antes del 2006<\/em><\/strong><\/td>\n<td width=\"113\"><em>2000 m<\/em><\/td>\n<td width=\"96\"><em>09:30 h<\/em><\/td>\n<td width=\"114\"><em>\u00a0<\/em><\/td>\n<td width=\"94\"><em>\u00a0<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>INFANTIL &#8211; CADETE<\/em><\/strong><\/td>\n<td width=\"241\"><em>2006\/07\/08\/09<\/em><\/td>\n<td width=\"113\"><em>1200 m<\/em><\/td>\n<td width=\"96\"><em>10:00 h<\/em><\/td>\n<td width=\"114\"><em>1200 m<\/em><\/td>\n<td width=\"94\"><em>10:10 h<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>ALEV\u00cdN<\/em><\/strong><\/td>\n<td width=\"241\"><em>2010\/2011<\/em><\/td>\n<td width=\"113\"><em>900 m<\/em><\/td>\n<td width=\"96\"><em>10:20 h<\/em><\/td>\n<td width=\"114\"><em>900m<\/em><\/td>\n<td width=\"94\"><em>10:30 h<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>BENJAM\u00cdN<\/em><\/strong><\/td>\n<td width=\"241\"><em>2012\/2013<\/em><\/td>\n<td width=\"113\"><em>700 m<\/em><\/td>\n<td width=\"96\"><em>10:40 h<\/em><\/td>\n<td width=\"114\"><em>700 m<\/em><\/td>\n<td width=\"94\"><em>10:50 h<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>RENACUAJO COMPETICI\u00d3N<\/em><\/strong><\/td>\n<td width=\"241\"><em>2014<\/em><\/td>\n<td width=\"113\"><em>450 m<\/em><\/td>\n<td width=\"96\"><em>11:00 h<\/em><\/td>\n<td width=\"114\"><em>450 m<\/em><\/td>\n<td width=\"94\"><em>11:10 h<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>RENACUAJO INICIACI\u00d3N<\/em><\/strong><\/td>\n<td width=\"241\"><em>2015<\/em><\/td>\n<td width=\"113\"><em>400 m<\/em><\/td>\n<td width=\"96\"><em>11.20 h<\/em><\/td>\n<td width=\"114\"><em>400 m<\/em><\/td>\n<td width=\"94\"><em>11.30 h<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>CARRERA POR LA INCLUSION<\/em><\/strong><\/td>\n<td width=\"241\"><em>SIN L\u00cdMITE DE EDAD<\/em><\/td>\n<td width=\"113\"><em>200 m<\/em><\/td>\n<td width=\"96\"><em>11.50 h<\/em><\/td>\n<td width=\"114\"><em>200 m<\/em><\/td>\n<td width=\"94\"><em>11.50 h<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>CARLOTES<\/em><\/strong><\/td>\n<td width=\"241\"><em>2016<\/em><\/td>\n<td width=\"113\"><em>200 m<\/em><\/td>\n<td width=\"96\"><em>12:00 h<\/em><\/td>\n<td width=\"114\"><em>200 m<\/em><\/td>\n<td width=\"94\"><em>12:05 h<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>CARLI\u00d1OS<\/em><\/strong><\/td>\n<td width=\"241\"><em>2017<\/em><\/td>\n<td width=\"113\"><em>150 m<\/em><\/td>\n<td width=\"96\"><em>12:10 h<\/em><\/td>\n<td width=\"114\"><em>150 m<\/em><\/td>\n<td width=\"94\"><em>12:15 h<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>CARLITOS<\/em><\/strong><\/td>\n<td width=\"241\"><em>2018<\/em><\/td>\n<td width=\"113\"><em>100 m<\/em><\/td>\n<td width=\"96\"><em>12:20 h<\/em><\/td>\n<td width=\"114\"><em>100 m<\/em><\/td>\n<td width=\"94\"><em>12:25 h<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>OPEN<\/em><\/strong><\/td>\n<td width=\"241\"><strong><em>Nacidos antes del 2006<\/em><\/strong><\/td>\n<td width=\"113\"><em>1000 m<\/em><\/td>\n<td width=\"96\"><em>12:30 h<\/em><\/td>\n<td width=\"114\"><em>700 m<\/em><\/td>\n<td width=\"94\"><em>12.40 h<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"224\"><strong><em>MINI-CARLITOS<\/em><\/strong><\/td>\n<td width=\"241\">2019\/2020\/2021\u2026.<\/td>\n<td width=\"113\"><em>100 m<\/em><\/td>\n<td width=\"96\"><em>12:45 h<\/em><\/td>\n<td width=\"114\"><em>\u00a0<\/em><\/td>\n<td width=\"94\"><em>\u00a0<\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<ul>\n<li>Todo participante deber\u00e1 llevar el dorsal en el pecho con los siguientes datos:<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><em><u>NOMBRE Y APELLIDOS, CATEGOR\u00cdA, A\u00d1O DE NACIMIENTO Y COLEGIO<\/u><\/em><\/strong><strong><em>\u00ad<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Todo aquel que desee participar en el Cross, debe inscribirse en las A.M.P.A.s de sus colegios\/institutos, o en el A.M.P.A. del Colegio CARLOS III desde el <strong>d\u00eda 14 de marzo <\/strong>y hasta el d\u00eda <strong>24 de marzo.<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Los participantes que no se hayan podido inscribirse en el A.M.P.A de su colegio\/institutos lo pueden hacer el d\u00eda del CROSS, 30 minutos antes de su prueba. Hay l\u00edmite de 1000 inscripciones.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>En las pruebas de <strong>marcha n\u00f3rdica<\/strong> es imprescindible el uso de <strong>DOS bastones<\/strong> y hacer buen uso de ellos. No se puede correr, solo marchar o andar manteniendo siempre un pie en contacto con el suelo.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Las hojas de inscripci\u00f3n y los dorsales que no se hayan repartido en su centro deber\u00e1n ser entregadas en el AMPA CARLOS III, o al monitor deportivo (Samuel) <strong>antes del d\u00eda 24 de Marzo<\/strong>. Tambi\u00e9n en el correo <strong>ampacarlosiii@hotmail.es<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>El Comit\u00e9 organizador no se hace responsable de cualquier posible accidente.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Premios de las pruebas:<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Trofeo a los tres clasificados de cada prueba. Medallas a partir del cuarto clasificado hasta el 15\u00ba clasificado.<\/li>\n<li>Bolsa del corredor a todos los participantes inscritos.<\/li>\n<li>Las categor\u00edas carlotes, carli\u00f1os ,carlitos y carrera por la inclusi\u00f3n tendr\u00e1n todos medalla.<\/li>\n<li>En la categor\u00eda mini\u2013carlitos se les dar\u00e1 un peque\u00f1o obsequio y un diploma por su participaci\u00f3n.<\/li>\n<li>En la carrera de marcha n\u00f3rdica, se dar\u00e1 trofeo a los 3 primeros clasificados y un peque\u00f1o avituallamiento.<\/li>\n<\/ul>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<ul>\n<li>La entrega de trofeos y medallas se realizar\u00e1 al finalizar las pruebas.<\/li>\n<\/ul>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em><\/p>\n<p><em>M\u00e1s informaci\u00f3n Ampa: <\/em><a href=\"mailto:ampacarlosiii@hotmail.es\"><em>ampacarlosiii@hotmail.es<\/em><\/a><em> o tel\u00e9fono Samuel \u00darsula (monitor deportivo del CEIP Carlos III: 677445419).<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><strong><em>Gracias y nos vemos en la SALIDA.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo d\u00eda 27 de marzo vamos a celebrar el XI CROSS ESCOLAR URBANO \u201cCARLOS III\u201d. El AMPA del colegio\u00a0\u00a0 tiene el honor de invitar a todos los Colegios y A.M.P.A.s para que participen en este acontecimiento deportivo. Este a\u00f1o de nuevo tendremos una competici\u00f3n de Marcha N\u00f3rdica. Al igual que en a\u00f1os anteriores, continuaremos &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/03\/16\/normativa-xi-cross-escolar-urbano-carlos-iii-27-de-marzo-de-2022\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNORMATIVA XI CROSS ESCOLAR URBANO \u201cCARLOS III\u201d (27 DE MARZO DE 2022)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,69,14],"tags":[],"post_folder":[],"class_list":["post-10346","post","type-post","status-publish","format-standard","hentry","category-actividades","category-ampa","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/ampa\/\" rel=\"category tag\">AMPA<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"El pr\u00f3ximo d\u00eda 27 de marzo vamos a celebrar el XI CROSS ESCOLAR URBANO \u201cCARLOS III\u201d. El AMPA del colegio\u00a0\u00a0 tiene el honor de invitar a todos los Colegios y A.M.P.A.s para que participen en este acontecimiento deportivo. Este a\u00f1o de nuevo tendremos una competici\u00f3n de Marcha N\u00f3rdica. Al igual que en a\u00f1os anteriores, continuaremos&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=10346"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10346\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=10346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=10346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=10346"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=10346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}