{"id":10571,"date":"2022-05-18T17:43:14","date_gmt":"2022-05-18T15:43:14","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=10571"},"modified":"2022-05-18T17:43:14","modified_gmt":"2022-05-18T15:43:14","slug":"dia-del-reciclaje-viernes-21-de-mayo","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/05\/18\/dia-del-reciclaje-viernes-21-de-mayo\/","title":{"rendered":"D\u00cdA DEL RECICLAJE VIERNES 20 DE MAYO"},"content":{"rendered":"<p style=\"text-align: right;\">Aranjuez, 18 de mayo de 2022<\/p>\n<p>A propuesta de la Coordinadora del Proyecto de Escuelas Sostenibles,\u00a0 con el visto bueno del Equipo Directivo y escuchado a la Asamblea de Pitufos, se invita a la Comunidad Educativa del CEIP Carlos III a la \u201c<strong>CELEBRACI\u00d3N DEL D\u00cdA DEL RECICLAJE\u201d el viernes 20 de mayo para concienciar a la Comunidad Educativa sobre la importancia de tratar los residuos como corresponde.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Para ello se propone a toda la Comunidad Educativa (alumnado, personal y familias) a dos acciones simb\u00f3licas:<\/p>\n<ul>\n<li><strong>Pintarse una R en un lugar visible<\/strong>, en la frente, en la mano, en la mejilla, para dar visibilidad a una de las 5 R (reutilizar, reducir, reparar, recuperar y reciclar), y recordarnos que tenemos que intentar cumplirlas a la hora de consumir cualquier tipo de producto.<\/li>\n<li>Tambi\u00e9n animamos a nuestro alumnado para \u201ccelebrar\u201d el d\u00eda del reciclaje <strong>acudiendo ese d\u00eda al colegio con una camiseta de un color distinto al del uniforme escolar<\/strong>, con el fin de dar mayor trascendencia al d\u00eda.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Esta celebraci\u00f3n tiene como finalidad, ser conscientes de que debemos reducir el volumen de los residuos generados y minimizar nuestra huella de carbono.<\/p>\n<p>&nbsp;<\/p>\n<p>Iniciamos con la\u00a0regla de las 3 R\u00a0y aprendimos a\u00a0reducir, luego a\u00a0reciclar\u00a0y finalmente a\u00a0reutilizar. En el tiempo vimos que serv\u00eda esta f\u00f3rmula pero gradualmente se fue volviendo insuficiente. Tuvimos que reconsiderar la\u00a0regla de las tres erres\u00a0y decidimos agregar 2 elementos m\u00e1s: reparar y recuperar.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/as1.ftcdn.net\/v2\/jpg\/02\/64\/14\/94\/1000_F_264149455_QRaFjk4yiGv6bpfnGkECtTX2ScMIN3nd.jpg\" alt=\"5R Chart (Reduce ,Reuse ,Recycle, Repair, Reject ) with leaf icon sign and Mathematical symbol in circle line block diagram Vector illustration design vector de Stock | Adobe Stock\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Si tienes que tirar separa los residuos y depos\u00edtalos en el contenedor correspondiente:<\/p>\n<ul>\n<li>Contenedor\u00a0<strong>azul<\/strong>: Papel y cart\u00f3n.<\/li>\n<li>Contenedor\u00a0<strong>amarillo<\/strong>: Envases (botellas, bolsas, latas) Limpia antes los envases y, en lo posible, apl\u00e1stalos para disminuir su volumen.<\/li>\n<li>Contenedor\u00a0<strong>verde claro<\/strong>: Vidrio. Limpia antes los envases y quita las tapas.<\/li>\n<li>Contenedor\u00a0<strong>verde oscuro<\/strong>: Resto de residuos: materia org\u00e1nica.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Gracias por vuestra colaboraci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 18 de mayo de 2022 A propuesta de la Coordinadora del Proyecto de Escuelas Sostenibles,\u00a0 con el visto bueno del Equipo Directivo y escuchado a la Asamblea de Pitufos, se invita a la Comunidad Educativa del CEIP Carlos III a la \u201cCELEBRACI\u00d3N DEL D\u00cdA DEL RECICLAJE\u201d el viernes 20 de mayo para concienciar a &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/05\/18\/dia-del-reciclaje-viernes-21-de-mayo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abD\u00cdA DEL RECICLAJE VIERNES 20 DE MAYO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,42],"tags":[],"post_folder":[],"class_list":["post-10571","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias","category-stem-destacado"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/stem-destacado\/\" rel=\"category tag\">STEM<\/a>","rttpg_excerpt":"Aranjuez, 18 de mayo de 2022 A propuesta de la Coordinadora del Proyecto de Escuelas Sostenibles,\u00a0 con el visto bueno del Equipo Directivo y escuchado a la Asamblea de Pitufos, se invita a la Comunidad Educativa del CEIP Carlos III a la \u201cCELEBRACI\u00d3N DEL D\u00cdA DEL RECICLAJE\u201d el viernes 20 de mayo para concienciar a&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=10571"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10571\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=10571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=10571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=10571"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=10571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}