{"id":10599,"date":"2022-05-31T10:40:03","date_gmt":"2022-05-31T08:40:03","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=10599"},"modified":"2022-05-31T10:40:03","modified_gmt":"2022-05-31T08:40:03","slug":"entrenamientos-de-balonmano","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/05\/31\/entrenamientos-de-balonmano\/","title":{"rendered":"ENTRENAMIENTOS DE BALONMANO"},"content":{"rendered":"<p style=\"text-align: right;\">Aranjuez, 31 de mayo de 2022<\/p>\n<p>&nbsp;<\/p>\n<p>Esta semana, el jueves 2 de junio, comienzan los entrenamientos de balonmano, para todos aquellos ni\u00f1os\/as del Colegio que quieran practicar y aprender un deporte nuevo. Los entrenamientos se llevar\u00e1n acabo en el pabell\u00f3n del Colegio, los jueves 2, 9 y 16 de junio, de 15:05 a 16:15, los ni\u00f1os y ni\u00f1as acceder\u00e1n al Centro, tras la salida de los alumnos\/as usuarios del servicio de\u00a0 Comedor Escolar.<\/p>\n<p>Es necesario que los ni\u00f1os\/as acudan con una botella de agua, con su nombre. El Club de Balonmano Ap\u00f3stol Santiago pondr\u00e1 a disposici\u00f3n de los ni\u00f1os y ni\u00f1as desde 1\u00ba a 5\u00ba de Primaria que quieran participar, entrenadores y todo el material necesario.<br \/>\nEl s\u00e1bado 18 de junio, en horario de ma\u00f1ana, tendr\u00e1 lugar un torneo de balonmano escolar, donde participaremos juntos a otros colegios de Aranjuez, en las instalaciones del Colegio Ap\u00f3stol Santiago.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10600\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/05\/CARTEL-ENTRENAMIENTOS-DE-BALONMANO.jpg\" alt=\"\" width=\"720\" height=\"960\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/05\/CARTEL-ENTRENAMIENTOS-DE-BALONMANO.jpg 720w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/05\/CARTEL-ENTRENAMIENTOS-DE-BALONMANO-225x300.jpg 225w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/05\/CARTEL-ENTRENAMIENTOS-DE-BALONMANO-300x400.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 31 de mayo de 2022 &nbsp; Esta semana, el jueves 2 de junio, comienzan los entrenamientos de balonmano, para todos aquellos ni\u00f1os\/as del Colegio que quieran practicar y aprender un deporte nuevo. Los entrenamientos se llevar\u00e1n acabo en el pabell\u00f3n del Colegio, los jueves 2, 9 y 16 de junio, de 15:05 a 16:15, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/05\/31\/entrenamientos-de-balonmano\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abENTRENAMIENTOS DE BALONMANO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,68,14],"tags":[],"post_folder":[],"class_list":["post-10599","post","type-post","status-publish","format-standard","hentry","category-actividades","category-actividades-noticias","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"Aranjuez, 31 de mayo de 2022 &nbsp; Esta semana, el jueves 2 de junio, comienzan los entrenamientos de balonmano, para todos aquellos ni\u00f1os\/as del Colegio que quieran practicar y aprender un deporte nuevo. Los entrenamientos se llevar\u00e1n acabo en el pabell\u00f3n del Colegio, los jueves 2, 9 y 16 de junio, de 15:05 a 16:15,&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=10599"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10599\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=10599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=10599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=10599"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=10599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}