{"id":1076,"date":"2016-09-12T11:16:51","date_gmt":"2016-09-12T11:16:51","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1076"},"modified":"2016-09-12T11:16:51","modified_gmt":"2016-09-12T11:16:51","slug":"informacion-de-principios-de-curso-2016-17","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/09\/12\/informacion-de-principios-de-curso-2016-17\/","title":{"rendered":"INFORMACI\u00d3N DE PRINCIPIOS DE CURSO 2016\/17"},"content":{"rendered":"<p>A continuaci\u00f3n adjuntamos informaci\u00f3n sobre horarios de entradas y salidas de alumnos\/as, ausencias del alumnado, salud, agendas escolares, uniforme escolar, atenci\u00f3n a familias, acceso de adultos al centro (en horario escolar), uso de internet para los comunicados del Centro y fotos.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci\u00f3n adjuntamos informaci\u00f3n sobre horarios de entradas y salidas de alumnos\/as, ausencias del alumnado, salud, agendas escolares, uniforme escolar, atenci\u00f3n a familias, acceso de adultos al centro (en horario escolar), uso de internet para los comunicados del Centro y fotos.\u00a0<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"post_folder":[],"class_list":["post-1076","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"A continuaci\u00f3n adjuntamos informaci\u00f3n sobre horarios de entradas y salidas de alumnos\/as, ausencias del alumnado, salud, agendas escolares, uniforme escolar, atenci\u00f3n a familias, acceso de adultos al centro (en horario escolar), uso de internet para los comunicados del Centro y fotos.\u00a0","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1076"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1076\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1076"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}