{"id":10775,"date":"2022-08-22T11:13:52","date_gmt":"2022-08-22T09:13:52","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=10775"},"modified":"2022-08-22T11:13:52","modified_gmt":"2022-08-22T09:13:52","slug":"comunicado-ampa-agenda-escolar-para-primaria-curso-2022-2023","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/08\/22\/comunicado-ampa-agenda-escolar-para-primaria-curso-2022-2023\/","title":{"rendered":"COMUNICADO AMPA AGENDA ESCOLAR PRIMARIA CURSO 2022-2023"},"content":{"rendered":"<p>Estimadas familias,<\/p>\n<div>Ya queda poco para empezar el nuevo curso escolar 2022\/23 y os queremos comunicar que volveremos a tener la agenda escolar del AMPA para los alumnos\/as de primaria.<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10776\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.56.08-1.jpeg\" alt=\"\" width=\"1080\" height=\"1528\" \/><\/div>\n<div>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0(PORTADA AGENDA ESCOLAR AMPA CARLOS III)<\/div>\n<div><\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10777\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.56.26.jpeg\" alt=\"\" width=\"1080\" height=\"1540\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.56.26.jpeg 1080w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.56.26-210x300.jpeg 210w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.56.26-718x1024.jpeg 718w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.56.26-768x1095.jpeg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.56.26-1077x1536.jpeg 1077w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/div>\n<div>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 (CONTRAPORTADA AGENDA ESCOLAR AMPA III)<\/div>\n<div><\/div>\n<div>Los <strong>socios tendr\u00e1n una agenda escolar por familia al precio de 1\u20ac.<\/strong><\/div>\n<div><\/div>\n<div>Tambi\u00e9n dispondremos\u00a0 de agendas para la venta:<\/div>\n<div><strong>Los no socios podr\u00e1n conseguirla por 4,50\u20ac.<\/strong><\/div>\n<div><strong>Si alg\u00fan socio quiere alguna agenda m\u00e1s, el precio tambi\u00e9n ser\u00e1 de 4,50\u20ac.<\/strong><\/div>\n<div><\/div>\n<div>Las agendas son de tama\u00f1o A5, de una p\u00e1gina por d\u00eda, a petici\u00f3n del equipo docente de primaria.<\/div>\n<div><\/div>\n<div>Para <strong>encargar las agendas<\/strong> pod\u00e9is hacerlo enviando un correo electr\u00f3nico al m<strong>ail del AMPA ampacarlosiii@hotmail.es y por whatsapp al tel\u00e9fono 693005635<\/strong> (indicado en el asunto AGENDA ESCOLAR. nombre del alumno\/a, curso, si es socio o no y n\u00famero de agendas).<\/div>\n<div><\/div>\n<div>La oficina del AMPA estar\u00e1 abierta, <strong>desde el 7 de septiembre, para recoger y hacer el pago de las agendas escolares,<\/strong> en el siguiente horario de lunes a viernes de 9:10 a 10:00 horas durante los 15 primeros d\u00edas, y despu\u00e9s en su horario habitual martes, jueves y viernes de 9:10 a 10:00 horas.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Os recordamos que desde el primer d\u00eda del curso pod\u00e9is haceros socios del AMPA. La cuota es de 30\u20ac anual por familia y su forma de pago es domiciliaci\u00f3n, efectivo o transferencia.<\/div>\n<div dir=\"ltr\"><\/div>\n<div>Un saludo y nos vemos pronto.<\/div>\n<div><\/div>\n<div style=\"text-align: right;\">JUNTA DIRECTIVA AMPA CARLOS III<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias, Ya queda poco para empezar el nuevo curso escolar 2022\/23 y os queremos comunicar que volveremos a tener la agenda escolar del AMPA para los alumnos\/as de primaria. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/08\/22\/comunicado-ampa-agenda-escolar-para-primaria-curso-2022-2023\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO AMPA AGENDA ESCOLAR PRIMARIA CURSO 2022-2023\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,29],"tags":[],"post_folder":[],"class_list":["post-10775","post","type-post","status-publish","format-standard","hentry","category-ampa","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/ampa\/\" rel=\"category tag\">AMPA<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Estimadas familias, Ya queda poco para empezar el nuevo curso escolar 2022\/23 y os queremos comunicar que volveremos a tener la agenda escolar del AMPA para los alumnos\/as de primaria. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=10775"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10775\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=10775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=10775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=10775"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=10775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}