{"id":10851,"date":"2022-09-09T14:06:30","date_gmt":"2022-09-09T12:06:30","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=10851"},"modified":"2022-09-09T14:06:30","modified_gmt":"2022-09-09T12:06:30","slug":"fe-de-erratas-activity-book-3o-de-primaria","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/09\/09\/fe-de-erratas-activity-book-3o-de-primaria\/","title":{"rendered":"FE DE ERRATAS: ACTIVITY BOOK 3\u00ba DE PRIMARIA"},"content":{"rendered":"<p style=\"text-align: right;\">Aranjuez, 9 de septiembre de 2022<\/p>\n<p>Estimadas familias:<\/p>\n<p>Rogamos que nos disculpen, estos son los datos correctos:<\/p>\n<p><strong>NEW HIGH FIVE 3 ACTIVITY BOOK\u00a0<\/strong><\/p>\n<p><strong>ISBN 978-1-380-01385-9<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Si la licencia del libro digital no ha sido activada, es posible cambiar el activity book.<\/p>\n<p>Si alguna familia, la hubiera activado, que, por favor, lo comunique al siguiente correo:<\/p>\n<p><strong>concepcion.tierra@educa.madrid.org<\/strong> indicando CURSO Y NOMBRE DEL ALUMNO\/A.<\/p>\n<p>Lamentamos las molestias.<\/p>\n<p>Gracias por su compresi\u00f3n.<\/p>\n<p style=\"text-align: right;\">Tutores de 3\u00ba de Primaria.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 9 de septiembre de 2022 Estimadas familias: Rogamos que nos disculpen, estos son los datos correctos: NEW HIGH FIVE 3 ACTIVITY BOOK\u00a0 ISBN 978-1-380-01385-9 &nbsp; Si la licencia del libro digital no ha sido activada, es posible cambiar el activity book. Si alguna familia, la hubiera activado, que, por favor, lo comunique al siguiente &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/09\/09\/fe-de-erratas-activity-book-3o-de-primaria\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abFE DE ERRATAS: ACTIVITY BOOK 3\u00ba DE PRIMARIA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"post_folder":[],"class_list":["post-10851","post","type-post","status-publish","format-standard","hentry","category-3-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/3-primaria\/\" rel=\"category tag\">3\u00ba Primaria<\/a>","rttpg_excerpt":"Aranjuez, 9 de septiembre de 2022 Estimadas familias: Rogamos que nos disculpen, estos son los datos correctos: NEW HIGH FIVE 3 ACTIVITY BOOK\u00a0 ISBN 978-1-380-01385-9 &nbsp; Si la licencia del libro digital no ha sido activada, es posible cambiar el activity book. Si alguna familia, la hubiera activado, que, por favor, lo comunique al siguiente&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=10851"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10851\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=10851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=10851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=10851"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=10851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}