{"id":10861,"date":"2022-09-16T12:47:52","date_gmt":"2022-09-16T10:47:52","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=10861"},"modified":"2022-09-16T12:47:52","modified_gmt":"2022-09-16T10:47:52","slug":"10861-2","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/09\/16\/10861-2\/","title":{"rendered":"INFORMACI\u00d3N DEPORTE ESCOLAR CURSO 2022-2023"},"content":{"rendered":"<p style=\"text-align: right;\">Aranjuez, 19 de septiembre de 2022<\/p>\n<p>Estimadas familias:<\/p>\n<p>Un a\u00f1o m\u00e1s con el inicio del curso escolar la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez pone en marcha las competiciones de los Juegos Escolares, con la finalidad de poder formar los equipos que representen a nuestro colegio os animamos a que apunt\u00e9is a vuestros hijos\/as al deporte que le guste de los que ofertamos. A continuaci\u00f3n, os indicamos los horarios de entrenamiento (Provisionales, quedando sujetos a modificaciones acorde con las actividades extraescolares,, disponibilidad horaria de los entrenadores\/as o a petici\u00f3n de la mayor\u00eda de los alumnos\/as del equipo).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10863\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/09\/Diapositiva1-1-1.jpg\" alt=\"\" width=\"705\" height=\"529\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/09\/Diapositiva1-1-1.jpg 960w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/09\/Diapositiva1-1-1-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/09\/Diapositiva1-1-1-768x576.jpg 768w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/p>\n<p><iframe loading=\"lazy\" title=\"CLAUSURA DE LOS JUEGOS ESCOLARES CURSO 2021-2022 (VIERNES 3 DE JUNIO DE 2022).\" width=\"525\" height=\"394\" src=\"https:\/\/www.youtube.com\/embed\/0k2fk3SZgag?start=282&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>BALONCESTO:<\/p>\n<p>Mini-micro (mixto) Renacuajo 1\u00ba y 2\u00ba Primaria (martes y jueves de 16:00 a 17:00).<\/p>\n<p>Micro Benjam\u00edn Femenino y Masculino 3\u00ba y 4\u00ba Primaria (lunes y mi\u00e9rcoles 16:00 a 17:00).<\/p>\n<p>Mini Alev\u00edn Masculino y Femenino 5\u00ba y 6\u00ba de Primaria (martes y jueves de 16:00 a 17:00 y viernes 17:00 a 18:00).<\/p>\n<p>&nbsp;<\/p>\n<p>F\u00daTBOL<\/p>\n<p>F\u00fatbol Sala Iniciaci\u00f3n (1\u00ba Primaria) Lunes y mi\u00e9rcoles 16:00 a 17:00.<\/p>\n<p>F\u00fatbol Sala Competici\u00f3n (2\u00ba Primaria) Martes y jueves 17:00 a 18:00.<\/p>\n<p>F\u00fatbol Sala (3\u00ba Primaria) Lunes y mi\u00e9rcoles 17:00 a 18:00.<\/p>\n<p>F\u00fatbol Sala (4\u00ba Primaria) Martes y jueves 16:00 a 17:00.<\/p>\n<p>F\u00fatbol 7 (5\u00ba y 6\u00ba Primaria) Lunes y Mi\u00e9rcoles 17:00 a 18:00 (depende de la asignaci\u00f3n de campos de la Delegaci\u00f3n de Deportes de Ayuntamiento de Aranjuez).<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Si est\u00e1is interesados (y todav\u00eda no lo hab\u00e9is hecho) en que vuestro hijo\/a participe en alguno de estos deportes, tan solo ten\u00e9is que rellenar la ficha de inscripci\u00f3n y entregarla en el AMPA o en la secretar\u00eda del Centro (en el horario establecido). Deber\u00e9is adjuntar <strong>una fotograf\u00eda tama\u00f1o carnet<\/strong>, con el nombre y apellidos del ni\u00f1o\/a y el curso por detr\u00e1s. Es muy importante <strong>rellenar todos los datos y apuntarse para poder confeccionar los equipos lo antes posible.<\/strong><\/p>\n<p style=\"text-align: justify;\">A propuesta de los entrenadores\/as (f\u00fatbol y baloncesto) con el fin de que cada equipo pueda disponer de balones, red, petos, botiqu\u00edn, &#8230;. Habr\u00e1 una <strong>cuota anual de 10\u20ac para los NO SOCIOS del AMPA y 5\u20ac para los socios.\u00a0<\/strong><\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/09\/INSCRIPCION-JUEGOS-ESCOLARES-2022-2023.pdf\">INSCRIPCI\u00d3N JUEGOS ESCOLARES 2022-2023<\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">JUNTA DIRECTIVA DEL AMPA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 19 de septiembre de 2022 Estimadas familias: Un a\u00f1o m\u00e1s con el inicio del curso escolar la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez pone en marcha las competiciones de los Juegos Escolares, con la finalidad de poder formar los equipos que representen a nuestro colegio os animamos a que apunt\u00e9is a vuestros hijos\/as &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/09\/16\/10861-2\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abINFORMACI\u00d3N DEPORTE ESCOLAR CURSO 2022-2023\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,68,69,14,43],"tags":[],"post_folder":[],"class_list":["post-10861","post","type-post","status-publish","format-standard","hentry","category-actividades","category-actividades-noticias","category-ampa","category-deportes","category-uncategorized"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/ampa\/\" rel=\"category tag\">AMPA<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","rttpg_excerpt":"Aranjuez, 19 de septiembre de 2022 Estimadas familias: Un a\u00f1o m\u00e1s con el inicio del curso escolar la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez pone en marcha las competiciones de los Juegos Escolares, con la finalidad de poder formar los equipos que representen a nuestro colegio os animamos a que apunt\u00e9is a vuestros hijos\/as&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=10861"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/10861\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=10861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=10861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=10861"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=10861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}