{"id":11176,"date":"2022-11-07T17:09:50","date_gmt":"2022-11-07T15:09:50","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=11176"},"modified":"2022-11-07T17:09:50","modified_gmt":"2022-11-07T15:09:50","slug":"resumen-del-tercer-cross-escolar-raso-de-la-estrela-sabado-5-de-noviembre-de-2022","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/11\/07\/resumen-del-tercer-cross-escolar-raso-de-la-estrela-sabado-5-de-noviembre-de-2022\/","title":{"rendered":"RESUMEN DEL TERCER CROSS ESCOLAR: RASO DE LA ESTRELA (S\u00c1BADO 5 DE NOVIEMBRE DE 2022)"},"content":{"rendered":"<div class=\"MOdxS \"><span class=\"_7UhW9   xLCgt      MMzan   KV-D4            se6yk       T0kll \">El s\u00e1bado 5 de noviembre de 2022 se celebr\u00f3 la tercera jornada de Cross Escolar en el Raso de la Estrella, \u00faltima prueba organizada por la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez. Hemos disfrutado de una ma\u00f1ana espectacular viendo a los ni\u00f1os\/as y j\u00f3venes de Aranjuez corriendo cerca del Palacio Real de Aranjuez. Felicidades y gracias a todos los alumnos\/as del Colegio que participaron. Enhorabuena a:<\/span><\/div>\n<div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><strong>Benjam\u00edn masculino<\/strong><\/div>\n<div dir=\"auto\">Samuel 6<\/div>\n<div dir=\"auto\">Dani 7<\/div>\n<div dir=\"auto\">Iv\u00e1n 15<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><strong>Benjam\u00edn femenino<\/strong><\/div>\n<div dir=\"auto\">Claudia 10<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><strong>Renacuajo masculino<\/strong><\/div>\n<div dir=\"auto\">Yassin 1<\/div>\n<div dir=\"auto\">Pablo 6<\/div>\n<div dir=\"auto\">Hugo 14<\/div>\n<div dir=\"auto\">Ra\u00fal 15<\/div>\n<\/div>\n<div class=\"             qF0y9          Igw0E     IwRSH      eGOV_       acqo5   _4EzTm   pjcA_                                                         aGBdT                                                  \">\n<div class=\"_7UhW9  PIoXz       MMzan    _0PwGv          uL8Hv         \"><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/scontent-ecv1-1.xx.fbcdn.net\/v\/t39.30808-6\/313417455_420788853599855_3437047035727898363_n.jpg?stp=dst-jpg_p720x720&amp;_nc_cat=106&amp;ccb=1-7&amp;_nc_sid=8bfeb9&amp;_nc_ohc=Nu6z1oJk__oAX-dT68X&amp;_nc_ht=scontent-ecv1-1.xx&amp;oh=00_AfC2jR5aKKVQEL6LnICF0xESf4MrqGJKCFbIfdCIsODYEQ&amp;oe=636D2742\" \/><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/scontent-ecv1-1.xx.fbcdn.net\/v\/t39.30808-6\/312631693_420788860266521_5708074822322083088_n.jpg?stp=dst-jpg_p720x720&amp;_nc_cat=111&amp;ccb=1-7&amp;_nc_sid=8bfeb9&amp;_nc_ohc=GguYDdnOBHwAX814q4X&amp;_nc_ht=scontent-ecv1-1.xx&amp;oh=00_AfAhl-OkKIu1HApxNS0LyuhlHCVkI81AfbCYrw-HfVjNaA&amp;oe=636DB654\" \/><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/scontent-ecv1-1.xx.fbcdn.net\/v\/t39.30808-6\/313426980_420788870266520_1956091111559343326_n.jpg?stp=dst-jpg_p600x600&amp;_nc_cat=101&amp;ccb=1-7&amp;_nc_sid=8bfeb9&amp;_nc_ohc=TaF60f05pvIAX-ojsN4&amp;_nc_ht=scontent-ecv1-1.xx&amp;oh=00_AfCKHIZSKKz2dbtUxKA0yuRcZXdCKx3oNIGLhVzr4pBnIQ&amp;oe=636EE91F\" \/><\/div>\n<div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado 5 de noviembre de 2022 se celebr\u00f3 la tercera jornada de Cross Escolar en el Raso de la Estrella, \u00faltima prueba organizada por la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez. Hemos disfrutado de una ma\u00f1ana espectacular viendo a los ni\u00f1os\/as y j\u00f3venes de Aranjuez corriendo cerca del Palacio Real de Aranjuez. Felicidades &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/11\/07\/resumen-del-tercer-cross-escolar-raso-de-la-estrela-sabado-5-de-noviembre-de-2022\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abRESUMEN DEL TERCER CROSS ESCOLAR: RASO DE LA ESTRELA (S\u00c1BADO 5 DE NOVIEMBRE DE 2022)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"post_folder":[],"class_list":["post-11176","post","type-post","status-publish","format-standard","hentry","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"El s\u00e1bado 5 de noviembre de 2022 se celebr\u00f3 la tercera jornada de Cross Escolar en el Raso de la Estrella, \u00faltima prueba organizada por la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez. Hemos disfrutado de una ma\u00f1ana espectacular viendo a los ni\u00f1os\/as y j\u00f3venes de Aranjuez corriendo cerca del Palacio Real de Aranjuez. Felicidades&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=11176"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11176\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=11176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=11176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=11176"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=11176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}