{"id":11195,"date":"2022-11-13T22:32:02","date_gmt":"2022-11-13T20:32:02","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=11195"},"modified":"2022-11-13T22:32:02","modified_gmt":"2022-11-13T20:32:02","slug":"comunicado-a-las-familias-del-centro-brote-de-pediculosis-noviembre-2022","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/11\/13\/comunicado-a-las-familias-del-centro-brote-de-pediculosis-noviembre-2022\/","title":{"rendered":"COMUNICADO A LAS FAMILIAS DEL CENTRO: BROTE DE PEDICULOSIS (NOVIEMBRE 2022)"},"content":{"rendered":"<p style=\"text-align: right;\">Aranjuez, 13 de noviembre de 2022<\/p>\n<p>Estimadas familias:<\/p>\n<p>En determinadas \u00e9pocas del a\u00f1o, pueden surgir brotes de\u00a0<span class=\"x_markk31fybs0a\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\"><span class=\"markicfd27gap\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\">pediculosis<\/span><\/span>\u00a0(piojos). Hemos tenido constancia de que est\u00e1n habiendo algunos casos de nuevo, por lo que rogamos extrem\u00e9is el cuidado y vigilancia en vuestros hijos\/as. Aplicadles los tratamientos preventivos.<\/p>\n<p>Se debe avisar al Tutor\/a y mantener al alumno\/a en casa aplic\u00e1ndole un tratamiento espec\u00edfico para evitar contagios, reincorpor\u00e1ndose cuando se compruebe que ha desaparecido el brote por completo, puesto que mantenerlos en clase, da lugar a contagios continuos.<\/p>\n<p>Un saludo y gracias por vuestra colaboraci\u00f3n.<\/p>\n<p style=\"text-align: right;\">EQUIPO DIRECTIVO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 13 de noviembre de 2022 Estimadas familias: En determinadas \u00e9pocas del a\u00f1o, pueden surgir brotes de\u00a0pediculosis\u00a0(piojos). Hemos tenido constancia de que est\u00e1n habiendo algunos casos de nuevo, por lo que rogamos extrem\u00e9is el cuidado y vigilancia en vuestros hijos\/as. Aplicadles los tratamientos preventivos. Se debe avisar al Tutor\/a y mantener al alumno\/a en casa &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/11\/13\/comunicado-a-las-familias-del-centro-brote-de-pediculosis-noviembre-2022\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO A LAS FAMILIAS DEL CENTRO: BROTE DE PEDICULOSIS (NOVIEMBRE 2022)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"post_folder":[],"class_list":["post-11195","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Aranjuez, 13 de noviembre de 2022 Estimadas familias: En determinadas \u00e9pocas del a\u00f1o, pueden surgir brotes de\u00a0pediculosis\u00a0(piojos). Hemos tenido constancia de que est\u00e1n habiendo algunos casos de nuevo, por lo que rogamos extrem\u00e9is el cuidado y vigilancia en vuestros hijos\/as. Aplicadles los tratamientos preventivos. Se debe avisar al Tutor\/a y mantener al alumno\/a en casa&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=11195"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11195\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=11195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=11195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=11195"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=11195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}