{"id":11213,"date":"2022-11-22T11:10:50","date_gmt":"2022-11-22T09:10:50","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=11213"},"modified":"2022-11-22T11:10:50","modified_gmt":"2022-11-22T09:10:50","slug":"3a-jornada-de-los-juegos-escolares-curso-2022-2023-26-de-noviembre-de-2022","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/11\/22\/3a-jornada-de-los-juegos-escolares-curso-2022-2023-26-de-noviembre-de-2022\/","title":{"rendered":"3\u00aa JORNADA DE LOS JUEGOS ESCOLARES CURSO 2022-2023 (26 DE NOVIEMBRE DE 2022)"},"content":{"rendered":"<p>Este s\u00e1bado se celebra la 3\u00aa Jornada de los Juegos Escolares, para nuestro equipo alev\u00edn de F\u00fatbol 7 (5\u00ba y 6\u00ba de Primaria), y la primera jornada par el resto de nuestros equipos. A continuaci\u00f3n os dejamos el calendario de partidos del 26 de noviembre.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11214\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/11\/WhatsApp-Image-2022-11-22-at-07.27.41.jpeg\" alt=\"\" width=\"1600\" height=\"975\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/11\/WhatsApp-Image-2022-11-22-at-07.27.41.jpeg 1600w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/11\/WhatsApp-Image-2022-11-22-at-07.27.41-300x183.jpeg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/11\/WhatsApp-Image-2022-11-22-at-07.27.41-1024x624.jpeg 1024w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/11\/WhatsApp-Image-2022-11-22-at-07.27.41-768x468.jpeg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2022\/11\/WhatsApp-Image-2022-11-22-at-07.27.41-1536x936.jpeg 1536w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este s\u00e1bado se celebra la 3\u00aa Jornada de los Juegos Escolares, para nuestro equipo alev\u00edn de F\u00fatbol 7 (5\u00ba y 6\u00ba de Primaria), y la primera jornada par el resto de nuestros equipos. A continuaci\u00f3n os dejamos el calendario de partidos del 26 de noviembre.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,14],"tags":[],"post_folder":[],"class_list":["post-11213","post","type-post","status-publish","format-standard","hentry","category-ampa","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/ampa\/\" rel=\"category tag\">AMPA<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"Este s\u00e1bado se celebra la 3\u00aa Jornada de los Juegos Escolares, para nuestro equipo alev\u00edn de F\u00fatbol 7 (5\u00ba y 6\u00ba de Primaria), y la primera jornada par el resto de nuestros equipos. A continuaci\u00f3n os dejamos el calendario de partidos del 26 de noviembre.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=11213"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11213\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=11213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=11213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=11213"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=11213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}