{"id":11264,"date":"2022-12-14T14:11:01","date_gmt":"2022-12-14T12:11:01","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=11264"},"modified":"2022-12-14T14:11:01","modified_gmt":"2022-12-14T12:11:01","slug":"vii-semana-de-la-convivencia-ceip-carlos-iii-del-16-al-22-de-diciembre-2022-juntos-convivimos-para-aprender-y-disfrutar","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/12\/14\/vii-semana-de-la-convivencia-ceip-carlos-iii-del-16-al-22-de-diciembre-2022-juntos-convivimos-para-aprender-y-disfrutar\/","title":{"rendered":"VII SEMANA DE LA CONVIVENCIA CEIP CARLOS III (DEL 16 AL 22 DE DICIEMBRE 2022) \u201cJUNTOS CONVIVIMOS PARA APRENDER Y DISFRUTAR\u201d"},"content":{"rendered":"<p>Desde la Comunidad Docente del CEIP CARLOS III, os informamos que en estos d\u00edas celebraremos la VII edici\u00f3n de la SEMANA DE LA CONVIVENCIA, se ha elaborado una planificaci\u00f3n de actividades, todas ellas con un \u00fanico objetivo:<\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\"><em style=\"font-weight: inherit;\"><strong>\u201cFomentar, desde la experiencia, la mejora de la convivencia escolar, social. Desarrollar los valores del respeto, la cooperaci\u00f3n, la solidaridad y la empat\u00eda.\u201d<\/strong><\/em><\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\">En esta VII Semana de la Convivencia, nos hemos propuesto docentes y alumnos\/as, fundamentalmente, compartir momentos con nuestras familias, con nuestros compa\u00f1eros\/as del Centro, con compa\u00f1eros\/as de otros Centros de la localidad, conociendo otras realidades, siendo protagonistas de la campa\u00f1a de recogida de alimentos para entregarlos e informarnos de la labor social y de voluntariado de una ONG Local, realizando charlas para fomentar valores de respeto y la no discriminaci\u00f3n y tertulias para prevenir, detectar y corregir peligros que pueden ocasionar el mal uso de la tecnolog\u00eda.<\/p>\n<p>Para ello hemos elaborado una serie de actividades para fomentar la Convivencia Escolar que pasamos a describir a continuaci\u00f3n:<\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\"><span style=\"font-style: inherit; font-weight: inherit;\"><strong style=\"font-style: inherit;\"><u>PROGRAMA COMPLETO DE LA VII SEMANA DE LA CONVIVENCIA COLEGIO CARLOS III<\/u><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-style: inherit; font-weight: inherit; text-align: center;\"><span style=\"font-size: 12pt;\"><strong>VIERNES 16 DE DICIEMBRE<\/strong><\/span><\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\">12:30 <strong>ACTO INAGURAL DE LA SEMANA VII SEMANA DE LA CONVIVENCIA COLEGIO CARLOS III: \u201cJUNTOS APRENDEMOS JUNTOS DISFRUTAMOS\u201d<\/strong><\/p>\n<p>\u00a0Comenzamos la semana de la Convivencia con un acto todos juntos en la pista (si las condiciones meteorol\u00f3gicas lo permiten), en el cual tambi\u00e9n vamos a poner el broche a todas las actividades realizadas en el Proyecto de Bienvenida del Curso, para ello vamos a representar muestro logo entre todos, cada nivel\/tramo llevar\u00e1 una camiseta\/sudadera\/abrigo de un color distinto, tambi\u00e9n cantaremos y bailaremos con nuestros himno y daremos la bienvenida a Charlie en este curso escolar.<\/p>\n<p>Infantil: azul.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1\u00ba y 2\u00ba: Amarillo.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3\u00ba y 4\u00ba Rojo. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5\u00ba y 6\u00ba negro<\/p>\n<p>Tras esto realizaremos por clases actividades propuestas por el equipo de integraci\u00f3n sobre la diversidad, que posterior ser\u00e1 expuestas en un mural.<\/p>\n<p><strong>17:00 \u2013 20:00 FIESTA DE NAVIDAD COLEGIO CARLOS III \u201cRUTA POR LOS CUENTOS DE NAVIDAD\u201d<\/strong><\/p>\n<p>Jornada de convivencia para toda la Comunidad Educativa (CARLOS III HAPPY DAYS) en beneficio viaje de fin de curso y graduaci\u00f3n alumnos\/as 6\u00ba de Primaria y Proyectos y material de Centro. Animamos a todos los asistentes a venir con motivos navide\u00f1os.<\/p>\n<p><strong>OPERACI\u00d3N KILO: DEL VIERNES 16 AL 20 DE DICIEMBRE<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td>Una vez m\u00e1s nos acercamos al tiempo en el que el valor de la SOLIDARIDAD cobra m\u00e1s fuerza. Es por ello, por lo que en nuestro centro llevaremos a cabo, como en a\u00f1os anteriores, la\u00a0<strong style=\"font-style: inherit;\">campa\u00f1a de recogida de alimentos para los m\u00e1s necesitados: \u201cOPERACI\u00d3N KILO\u201d.<\/strong>\u00a0<strong style=\"font-style: inherit;\">Este a\u00f1o, una vez m\u00e1s, se dedicar\u00e1 a BASIDA.<\/strong>\u00a0BASIDA, es una asociaci\u00f3n de car\u00e1cter ben\u00e9fico y asistencial, sin \u00e1nimo de lucro y Declarada de Utilidad P\u00fablica, tiene como objetivo general la atenci\u00f3n a personas necesitadas desde el punto de vista biopsicosocial. Tiene una trayectoria de m\u00e1s de 25 a\u00f1os, avalados por su ayuda a los m\u00e1s necesitados de la Sociedad.<\/p>\n<p>Para la recogida de los productos, se colocar\u00e1n cajas junto a los accesos al Centro. Para los alumnos\/as usuarios del servicio de los Primeros del Cole y Comedor Escolar las monitoras de esta ampliaci\u00f3n escolar colocar\u00e1n las cajas para que los miembros de la Comunidad Educativa de horario ampliado puedan dejar sus donaciones.<\/p>\n<p><strong>FECHAS DE RECOGIDA:\u00a0<strong style=\"font-style: inherit;\">16, 19 y 20 de diciembre del 2022<\/strong><\/strong>.<\/p>\n<p>Los productos deben ser no perecederos; nos hemos puesto en contacto con BASIDA, para preguntarles qu\u00e9 productos, en la actualidad, les son m\u00e1s necesarios, su respuesta ha sido que agradecen toda ayuda, pero que est\u00e1n m\u00e1s necesitados de los siguientes y con la finalidad de cubrir todas las necesidades hemos asignado un producto a cada curso (es una recomendaci\u00f3n, lo importante es cubrir las necesidades de esta Casa de Acogida):<\/p>\n<p>6\u00ba Primaria: tomate frito\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5\u00ba Primaria: az\u00facar\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 4\u00ba Primaria: leche<\/p>\n<p>3\u00ba Primaria: cereales\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a02\u00ba Primaria: caf\u00e9\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1\u00ba Primaria: latas de conservas<\/p>\n<p>5 a\u00f1os: k\u00e9tchup\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 4 a\u00f1os: mayonesa\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3 a\u00f1os: fideos finos<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><strong>LUNES 19 DE DICIEMBRE<\/strong><\/span><\/p>\n<p><strong>Elaboraci\u00f3n de felicitaciones navide\u00f1as<\/strong> para EEI Jardines de Aranjuez, CEIP San Isidro, Hospital del Tajo, IES Domenico Scarlatti, AMAFI, EE Pr\u00edncipe de Asturias, Basida, Centro de Salud de las Olivas, Residencia \u201cEl Deliete\u201d y CEIPSO Maestro Rodrigo.<\/p>\n<p><strong>VISITA DE LOS ALUMNOS\/AS DEL IES DOMENICO SCARLATTI del Programa Profesional Modalidad Especial (PPME) y elaboraci\u00f3n de un taller de c\u00f3mics a las clases de 3\u00ba de Primaria.<\/strong><\/p>\n<p><strong>SALIDA DE LAS CLASES DE 4\u00ba DE PRIMARIA A LA RESIDENCIA PARA MAYORES \u201cREAL DELEITE\u201d.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 12pt;\">MARTES 20 DE DICIEMBRE<\/span><\/strong><\/p>\n<p><strong>JUMPER\u00b4S DAY (JERSEY NAVIDE\u00d1O)<\/strong> \u00a0Es una actividad did\u00e1ctica, en un momento tan entra\u00f1able y familiar como es la Navidad. El Christmas Jumper\u00b4s Day es una tradici\u00f3n brit\u00e1nica navide\u00f1a, de no hace mucho tiempo, que cada vez est\u00e1 m\u00e1s extendida en otros pa\u00edses. Los d\u00edas previos a la Nochebuena (viernes anterior), algunos\/as brit\u00e1nicos\/as se visten con un jersey de lana que destaca por su multitud de detalles llamativos, horteras y por supuesto navide\u00f1os. Todos juntos celebran estas fechas con el jersey original y divertido.<\/p>\n<p>El alumnado de cada nivel, vendr\u00e1 ataviado con un Christmas Jumper (Jersey navide\u00f1o) cuya decoraci\u00f3n, se recomienda, que sea elaborada por ellos mismos. Se tomar\u00e1n fotos de cada Aula en un photocall realizado para esta actividad.<\/p>\n<p><strong>VISITA DE LOS ALUMNOS\/AS DEL EEI PR\u00cdNCIPE DE ASTURIAS DE ARANJUEZ a las clases de 5\u00ba de Primaria. <\/strong><\/p>\n<p><strong>SALIDA DE LAS CLASES DE 6\u00ba DE PRIMARIA A LA CASA DE ACOGIDA DE BASIDA. <\/strong>Los alumnos\/as de 6\u00ba de Primaria entregar\u00e1n los alimentos y productos \u00a0recogidos en la campa\u00f1a de Operaci\u00f3n Kilo y visitar\u00e1n la casa de acogida \u00a0 de Aranjuez.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><strong>MI\u00c9RCOLES 21 DE DICIEMBRE<\/strong><\/span><\/p>\n<p><strong>VISITA DE AMAFI a las clases de 4\u00ba de Primaria para realizar un taller de Huerto Escolar. <\/strong><\/p>\n<p>ASAMBLEA DE PITUFOS 12:00 \u2013 12:30 (FIN DE CURSO): Revisi\u00f3n y despedida del trimestre.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><strong>JUEVES 22 DE DICIEMBRE (\u00daltimo d\u00eda del trimestre)<\/strong><\/span><\/p>\n<p>VISITA DE SUS MAJESTADES DE RRMM Y CHOCOLATADA<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Durante toda la semana se har\u00e1n actividades de convivencia entre las clases y los cursos.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11267\" src=\"https:\/\/colegiocarlosiii.com\/wp-content\/uploads\/2022\/12\/CARTEL-VII-SEMANA-DE-LA-CONVIVENCIA.jpg\" alt=\"\" width=\"720\" height=\"960\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\">\n","protected":false},"excerpt":{"rendered":"<p>Desde la Comunidad Docente del CEIP CARLOS III, os informamos que en estos d\u00edas celebraremos la VII edici\u00f3n de la SEMANA DE LA CONVIVENCIA, se ha elaborado una planificaci\u00f3n de actividades, todas ellas con un \u00fanico objetivo: \u201cFomentar, desde la experiencia, la mejora de la convivencia escolar, social. Desarrollar los valores del respeto, la cooperaci\u00f3n, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2022\/12\/14\/vii-semana-de-la-convivencia-ceip-carlos-iii-del-16-al-22-de-diciembre-2022-juntos-convivimos-para-aprender-y-disfrutar\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abVII SEMANA DE LA CONVIVENCIA CEIP CARLOS III (DEL 16 AL 22 DE DICIEMBRE 2022) \u201cJUNTOS CONVIVIMOS PARA APRENDER Y DISFRUTAR\u201d\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,68,29],"tags":[],"post_folder":[],"class_list":["post-11264","post","type-post","status-publish","format-standard","hentry","category-actividades","category-actividades-noticias","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Desde la Comunidad Docente del CEIP CARLOS III, os informamos que en estos d\u00edas celebraremos la VII edici\u00f3n de la SEMANA DE LA CONVIVENCIA, se ha elaborado una planificaci\u00f3n de actividades, todas ellas con un \u00fanico objetivo: \u201cFomentar, desde la experiencia, la mejora de la convivencia escolar, social. Desarrollar los valores del respeto, la cooperaci\u00f3n,&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=11264"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11264\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=11264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=11264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=11264"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=11264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}