{"id":11378,"date":"2023-02-10T11:59:45","date_gmt":"2023-02-10T09:59:45","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=11378"},"modified":"2023-02-10T11:59:45","modified_gmt":"2023-02-10T09:59:45","slug":"ensayo-baile-de-carnaval-15-de-febrero-1605","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/02\/10\/ensayo-baile-de-carnaval-15-de-febrero-1605\/","title":{"rendered":"ENSAYO BAILE DE CARNAVAL 15 DE FEBRERO (16:05)"},"content":{"rendered":"<div style=\"text-align: right;\">Aranjuez, 10 de febrero de 2023<\/div>\n<div><\/div>\n<div>Estimadas familias:<\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">El desfile de Carnaval, organizado por la Delegaci\u00f3n de Fiestas del Ayuntamiento del Real Sitio y Villa de Aranjuez, tendr\u00e1 lugar el s\u00e1bado 18 de febrero de 2023 a las 17,00 horas y saldr\u00e1 de la Plaza de la Constituci\u00f3n (Recorrido: C\/ Stuart, C\/ Real, C\/ Alm\u00edbar hasta llegar a la Plaza de Toros), la Delegaci\u00f3n de Festejos, organizadora del evento, ha convocado a todas las comparsas participantes a las 16:15 en la Plaza de la Constituci\u00f3n. Una vez las comparsas lleguen a la Plaza de Toros podr\u00e1n llevar a cabo una animaci\u00f3n por un tiempo l\u00edmite de 2 minutos. El pr\u00f3ximo <strong>mi\u00e9rcoles d\u00eda 15 de febrero de 2023 a las 16:05 horas ser\u00e1 el ensayo del baile de nuestra comparsa para el carnaval<\/strong> de este a\u00f1o, ser\u00e1 har\u00e1 en el patio de 1\u00ba y 2\u00ba de Primaria. Por eso animamos a todas las familias que os est\u00e1is inscribiendo para el desfile del 18 de febrero, que acud\u00e1is a ensayar.<\/div>\n<div style=\"text-align: justify;\">Se grabar\u00e1 un v\u00eddeo para las personas que no puedan acudir y para que podamos practicar en casa en familia.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Os esperamos.<\/div>\n<div style=\"text-align: justify;\"><a href=\"https:\/\/www.aranjuez.es\/actualidad\/el-ayuntamiento-hace-publicas-las-bases-para-participar-en-los-carnavales-2023\/\">INFORMACI\u00d3N AYUNTAMIENTO PASACALLES DE CARNAVAL 2023<\/a><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/www.aranjuez.es\/wp-content\/uploads\/2023\/01\/CARNAVAL-DE-ARANJUEZ.png\" alt=\"EL AYUNTAMIENTO HACE P\u00daBLICAS LAS BASES PARA PARTICIPAR EN LOS CARNAVALES 2023 - noticieromadrid.es\" \/><\/div>\n<div><\/div>\n<div><\/div>\n<div><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/02\/Bases-Carnaval-2023-AYUNTAMIENTO.pdf\">Bases Carnaval 2023 AYUNTAMIENTO<\/a><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/FK0JM_PXsAQm0P7?format=jpg&amp;name=medium\" alt=\"Imagen\" \/><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/ampacarlosiii.es\/wp-content\/uploads\/2019\/03\/35B67CFC-A5E1-4ED3-A84E-144DE4409C2E-720x340.jpeg\" alt=\"Carnaval \u2013 AMPA Carlos III\" \/><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/FK0JM_NXwAEI2pr?format=jpg&amp;name=medium\" alt=\"Imagen\" \/><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/ampacarlosiii.es\/wp-content\/uploads\/2017\/02\/AP16-720x340.jpg\" alt=\"Carnaval \u2013 AMPA Carlos III\" \/><\/div>\n<div><\/div>\n<div>Gracias por vuestra colaboraci\u00f3n.<\/div>\n<div><\/div>\n<div style=\"text-align: right;\">JUNTA DIRECTIVA AMPA<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 10 de febrero de 2023 Estimadas familias: El desfile de Carnaval, organizado por la Delegaci\u00f3n de Fiestas del Ayuntamiento del Real Sitio y Villa de Aranjuez, tendr\u00e1 lugar el s\u00e1bado 18 de febrero de 2023 a las 17,00 horas y saldr\u00e1 de la Plaza de la Constituci\u00f3n (Recorrido: C\/ Stuart, C\/ Real, C\/ Alm\u00edbar &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/02\/10\/ensayo-baile-de-carnaval-15-de-febrero-1605\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abENSAYO BAILE DE CARNAVAL 15 DE FEBRERO (16:05)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,3,69,29],"tags":[],"post_folder":[],"class_list":["post-11378","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias","category-actividades","category-ampa","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/ampa\/\" rel=\"category tag\">AMPA<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Aranjuez, 10 de febrero de 2023 Estimadas familias: El desfile de Carnaval, organizado por la Delegaci\u00f3n de Fiestas del Ayuntamiento del Real Sitio y Villa de Aranjuez, tendr\u00e1 lugar el s\u00e1bado 18 de febrero de 2023 a las 17,00 horas y saldr\u00e1 de la Plaza de la Constituci\u00f3n (Recorrido: C\/ Stuart, C\/ Real, C\/ Alm\u00edbar&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=11378"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11378\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=11378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=11378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=11378"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=11378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}