{"id":11632,"date":"2023-05-09T20:56:56","date_gmt":"2023-05-09T18:56:56","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=11632"},"modified":"2023-05-09T20:56:56","modified_gmt":"2023-05-09T18:56:56","slug":"comunicado-a-la-comunidad-educatica-del-ceip-carlos-iii-huelga-de-personal-no-docente-de-la-comunidad-de-madrid-mayo-2023","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/05\/09\/comunicado-a-la-comunidad-educatica-del-ceip-carlos-iii-huelga-de-personal-no-docente-de-la-comunidad-de-madrid-mayo-2023\/","title":{"rendered":"COMUNICADO A LA COMUNIDAD EDUCATICA DEL CEIP CARLOS III: HUELGA DE PERSONAL NO DOCENTE DE LA COMUNIDAD DE MADRID (MAYO 2023)"},"content":{"rendered":"<p style=\"text-align: right;\">Aranjuez, 09 de mayo del 2023.<\/p>\n<p>Estimadas familias y equipo docente:<\/p>\n<p>Por la presente os comunicamos las \u00faltimas noticias recibidas en la ma\u00f1ana de ayer, desde la Direcci\u00f3n de \u00c1rea Territorial Madrid-Sur, acerca de la convocatoria de huelga desde La Organizaci\u00f3n Sindical Central Sindical Independiente y de Funcionarios (CSIF), que ha comunicado la convocatoria de una huelga en la Administraci\u00f3n General de la Comunidad de Madrid, para el personal incluido en el \u00e1mbito de aplicaci\u00f3n del Acuerdo Sectorial sobre condiciones de trabajo del personal funcionario de administraci\u00f3n y servicios y el personal incluido en el \u00e1mbito de aplicaci\u00f3n del Convenio Colectivo \u00danico del personal laboral al servicio de la Administraci\u00f3n de la Comunidad de Madrid (Personal laboral y Personal funcionario de administraci\u00f3n y servicios), cuyas fechas de celebraci\u00f3n ser\u00e1n los d\u00edas 8, 9, 10, 11 y 12 de mayo de 2023. Dicha huelga se concreta en la franja horaria que transcurre de 11:00 a 11:30 horas, en turno de ma\u00f1ana, y de 18:00 a 18:30 horas, en turno de tarde, durante los d\u00edas mencionados.<\/p>\n<p>&nbsp;<\/p>\n<p>En el d\u00eda de ayer se ha publicado en el BOCM el ACUERDO de 3 de mayo de 2023, del Consejo de Gobierno, por el que se fijan los servicios m\u00ednimos con ocasi\u00f3n de la huelga convocada entre los d\u00edas 8 y 12 de mayo de 2023 y que establece los siguientes:<\/p>\n<p>&nbsp;<\/p>\n<p>\u00b7 1. Para todos los centros docentes: Un Graduado\/a en Enfermer\u00eda, en aquellos centros donde exista este personal por contar con alumnos\/as con necesidades sanitarias, un auxiliar de control e informaci\u00f3n por cada turno del centro y el 50 por 100 de la plantilla del personal que realice tareas de limpieza en aquellos centros docentes donde la prestaci\u00f3n del servicio se lleve a cabo con personal propio de la Comunidad de Madrid.<\/p>\n<p>\u00b7 2. En centros ordinarios que atiendan a alumnos con necesidades educativas especiales: Adem\u00e1s de los establecidos con car\u00e1cter general para todos los centros, un tercio del personal no docente con atenci\u00f3n directa a los alumnos\/as, excluidos los de las categor\u00edas de Fisioterapeuta y Terapia Ocupacional.<\/p>\n<p>Por ello os comunico a continuaci\u00f3n el personal que queda establecido como Servicios m\u00ednimos:<\/p>\n<p>Con respecto al punto 1. queda nombrada como servicios m\u00ednimos: D\u00aa. SARA GONZ\u00c1LEZ MAZA (DUE)<\/p>\n<p>Con respecto al punto.2. queda nombrado como servicios m\u00ednimos D. MARIO MART\u00cdN TORRES (TIS)<\/p>\n<p style=\"text-align: right;\">EQUIPO DIRECTIVO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 09 de mayo del 2023. Estimadas familias y equipo docente: Por la presente os comunicamos las \u00faltimas noticias recibidas en la ma\u00f1ana de ayer, desde la Direcci\u00f3n de \u00c1rea Territorial Madrid-Sur, acerca de la convocatoria de huelga desde La Organizaci\u00f3n Sindical Central Sindical Independiente y de Funcionarios (CSIF), que ha comunicado la convocatoria de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/05\/09\/comunicado-a-la-comunidad-educatica-del-ceip-carlos-iii-huelga-de-personal-no-docente-de-la-comunidad-de-madrid-mayo-2023\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO A LA COMUNIDAD EDUCATICA DEL CEIP CARLOS III: HUELGA DE PERSONAL NO DOCENTE DE LA COMUNIDAD DE MADRID (MAYO 2023)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"post_folder":[],"class_list":["post-11632","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Aranjuez, 09 de mayo del 2023. Estimadas familias y equipo docente: Por la presente os comunicamos las \u00faltimas noticias recibidas en la ma\u00f1ana de ayer, desde la Direcci\u00f3n de \u00c1rea Territorial Madrid-Sur, acerca de la convocatoria de huelga desde La Organizaci\u00f3n Sindical Central Sindical Independiente y de Funcionarios (CSIF), que ha comunicado la convocatoria de&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=11632"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11632\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=11632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=11632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=11632"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=11632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}