{"id":117,"date":"2013-09-27T08:45:24","date_gmt":"2013-09-27T08:45:24","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=117"},"modified":"2013-09-27T08:45:24","modified_gmt":"2013-09-27T08:45:24","slug":"circular-comunicados-centro-a-familias","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2013\/09\/27\/circular-comunicados-centro-a-familias\/","title":{"rendered":"Circular comunicados centro a familias"},"content":{"rendered":"<p>Estimadas familias:<\/p>\n<p><span style=\"line-height: 1.3em;\">Continuando con la l\u00ednea de comunicaci\u00f3n Centro-Familias, que se inici\u00f3 en los cursos anteriores, hemos contribuido de forma significativa a un alto nivel de consecuci\u00f3n de los objetivos que se plantearon en su momento.<\/span><\/p>\n<p>\u00a0<\/p>\n<p>Entre todos conseguimos:<\/p>\n<p>\u2022 Ahorrar en el gasto de papel contribuyendo con ello a la conservaci\u00f3n del medio ambiente.<br \/>\u2022 Facilitar el trabajo del personal del centro.<br \/>\u2022 Garantizar, sobre todo para los padres\/madres la recepci\u00f3n de dichos comunicados.<\/p>\n<p>Pero una vez m\u00e1s, necesitamos de vuestra colaboraci\u00f3n para que resulte eficaz, procurando actualizar los correos y accediendo al Blog para dar nuevas altas. <br \/>(FECHA L\u00cdMITE 30-SEPTIEMBRE-2013)<\/p>\n<p>Desde esta circular os explicamos paso a paso c\u00f3mo hacerlo:<\/p>\n<p>1. A trav\u00e9s de un buscador (Google, Mozilla\u2026) entrad en el Blog del colegio: http:\/\/colegiocarlostercero.wordpress.com\/<br \/>2. En la columna de la derecha hay un apartado que pone : \u201cSuscripci\u00f3n por correo electr\u00f3nico\u201d<br \/>3. En dicho apartado existe una celda donde deb\u00e9is escribir la direcci\u00f3n de correo en el que quer\u00e9is recibir los comunicados del Centro.<br \/>4. Pinchar con el rat\u00f3n donde pone \u201cSign me up\u201d. <br \/>5. Recibir\u00e9is un correo electr\u00f3nico con el asunto \u201cSeguir Carlos III\u201d. En dicho correo ten\u00e9is que pinchar donde pone \u201cConfirm Follow\u201d<\/p>\n<p>A\u00fan as\u00ed, el Centro expondr\u00e1 en los tablones de informaci\u00f3n, de las puertas de acceso, aquellos comunicados relevantes que procedan de Secretar\u00eda y Direcci\u00f3n.<\/p>\n<p>De igual forma a aquellas familias que no tengan acceso a internet se les seguir\u00e1 entregando los comunicados en papel.<\/p>\n<p>Aranjuez, 20 de septiembre de 2013.<br \/> EQUIPO DIRECTIVO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias:<\/p>\n<p><span style=\"line-height: 1.3em;\">Continuando con la l\u00ednea de comunicaci\u00f3n Centro-Familias, que se inici\u00f3 en los cursos anteriores, hemos contribuido de forma significativa a un alto nivel de consecuci\u00f3n de los objetivos que se plantearon en su momento.<\/span><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"post_folder":[],"class_list":["post-117","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Estimadas familias: Continuando con la l\u00ednea de comunicaci\u00f3n Centro-Familias, que se inici\u00f3 en los cursos anteriores, hemos contribuido de forma significativa a un alto nivel de consecuci\u00f3n de los objetivos que se plantearon en su momento.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=117"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/117\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=117"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}