{"id":11710,"date":"2023-06-06T17:01:34","date_gmt":"2023-06-06T15:01:34","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=11710"},"modified":"2023-06-06T17:01:34","modified_gmt":"2023-06-06T15:01:34","slug":"comunicado-a-las-familias-de-6o-de-e-primaria-ensayo-general","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/06\/06\/comunicado-a-las-familias-de-6o-de-e-primaria-ensayo-general\/","title":{"rendered":"COMUNICADO A LAS FAMILIAS DE 6\u00ba DE E. PRIMARIA.  ENSAYO GENERAL"},"content":{"rendered":"<p style=\"text-align: right;\">Aranjuez, 6 de junio de 2023.<\/p>\n<p>Estimadas familias:<\/p>\n<p>Como ya les hemos comunicado al alumnado, a trav\u00e9s de sus Tutores\/as y en una \u00faltima reuni\u00f3n en el d\u00eda de hoy, con todo el nivel de 6\u00ba de E. Primaria, ma\u00f1ana d\u00eda 07 de junio por la ma\u00f1ana tendr\u00e1 lugar el ensayo general del Teatro Musical y Acto de Graduaci\u00f3n.<\/p>\n<p>Cada grupo de 6\u00ba de E. Primaria, ir\u00e1n desde el Centro con sus Tutores \/as hasta el Centro Cultural Isabel de Farnesio, donde tendr\u00e1 lugar el ensayo general que se har\u00e1 en el Auditorio Joaqu\u00edn Rodrigo.<\/p>\n<p>HORA DE SALIDA DESDE EL CENTRO. 09:10 HORAS<\/p>\n<p>Una vez acabado el ensayo, el alumnado ser\u00e1 recogido por las familias a las 12:30 horas, en el C.C. Isabel de Farnesio, en la salida en C\/ REY, donde estar\u00e1n esperando en la acera junto al profesorado de apoyo.<\/p>\n<p>&nbsp;<\/p>\n<p>EXCEPTO:<\/p>\n<p>\u00b7 Alumnado usuario del servicio de comedor escolar, que volver\u00e1 junto al profesorado al Centro a partir de las 12:15 horas.<\/p>\n<p>\u00b7 Alumnado usuario del servicio de Transporte Escolar, que volver\u00e1 junto al profesorado al Centro a partir de las 12:15 horas.<\/p>\n<p>\u00b7 Alumnado que tiene autorizaci\u00f3n para volver s\u00f3lo a sus casas, que volver\u00e1 junto al profesorado al Centro a partir de las 12:15 horas, para a las 13:00 horas salir del centro a sus respectivos domicilios.<\/p>\n<p>&nbsp;<\/p>\n<p>ACTO DE GRADUACI\u00d3N.<\/p>\n<p>El alumnado de 6\u00ba de E. Primaria, deber\u00e1 estar en el hall del C.C. Isabel de Farnesio a las 17.30 horas del mi\u00e9rcoles 07 de junio de 2023,<\/p>\n<p>\u00b7 Vestidos con el atuendo que utilizar\u00e1n en el Teatro Musical \u201cAranjuez\u201d.<\/p>\n<p>\u00b7 Llevar\u00e1n en una bolsa debidamente etiquetada con su nombre (el uniforme escolar y la beca que utilizar\u00e1n para el acto de graduaci\u00f3n).<\/p>\n<p>\u00b7 En el hall ser\u00e1n recibidos por sus Tutores\/as para subir al Auditorio.<\/p>\n<p>El personal encargado del Auditorio, abrir\u00e1n sus puertas a los familiares del alumnado a partir de las 18:00 horas, para que a partir de las 18:30 horas podamos dar comienzo al inicio de la actuaci\u00f3n musical.<\/p>\n<p>La salida del alumnado, una vez terminado el Acto de Graduaci\u00f3n, se har\u00e1 en el hall del C.C. Isabel de Farnesio, en la escalera de bajada donde se ubica la biblioteca.<\/p>\n<p>&nbsp;<\/p>\n<p>Agradecemos vuestra colaboraci\u00f3n.<\/p>\n<p style=\"text-align: right;\">E. DIRECTIVO Y E. DOCENTE.<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/06\/CIRCULAR-ENSAYO-GENERAL-Y-ACTO-DE-GRADUACION-2022-2023-1.pdf\">CIRCULAR ENSAYO GENERAL Y ACTO DE GRADUACI\u00d3N 2022-2023<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 6 de junio de 2023. Estimadas familias: Como ya les hemos comunicado al alumnado, a trav\u00e9s de sus Tutores\/as y en una \u00faltima reuni\u00f3n en el d\u00eda de hoy, con todo el nivel de 6\u00ba de E. Primaria, ma\u00f1ana d\u00eda 07 de junio por la ma\u00f1ana tendr\u00e1 lugar el ensayo general del Teatro Musical &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/06\/06\/comunicado-a-las-familias-de-6o-de-e-primaria-ensayo-general\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO A LAS FAMILIAS DE 6\u00ba DE E. PRIMARIA.  ENSAYO GENERAL\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"post_folder":[],"class_list":["post-11710","post","type-post","status-publish","format-standard","hentry","category-6-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/6-primaria\/\" rel=\"category tag\">6\u00ba Primaria<\/a>","rttpg_excerpt":"Aranjuez, 6 de junio de 2023. Estimadas familias: Como ya les hemos comunicado al alumnado, a trav\u00e9s de sus Tutores\/as y en una \u00faltima reuni\u00f3n en el d\u00eda de hoy, con todo el nivel de 6\u00ba de E. Primaria, ma\u00f1ana d\u00eda 07 de junio por la ma\u00f1ana tendr\u00e1 lugar el ensayo general del Teatro Musical&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=11710"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11710\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=11710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=11710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=11710"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=11710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}