{"id":11899,"date":"2023-09-07T11:05:32","date_gmt":"2023-09-07T09:05:32","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=11899"},"modified":"2023-09-07T11:05:32","modified_gmt":"2023-09-07T09:05:32","slug":"deporte-escolar-curso-2023-2024","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/09\/07\/deporte-escolar-curso-2023-2024\/","title":{"rendered":"DEPORTE ESCOLAR CURSO 2023-2024"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11900\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/CARTEL-INICIO-DE-ENTRENAMIENTOS-DEPORTE-ESCOLAR-23-24.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/CARTEL-INICIO-DE-ENTRENAMIENTOS-DEPORTE-ESCOLAR-23-24.jpg 960w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/CARTEL-INICIO-DE-ENTRENAMIENTOS-DEPORTE-ESCOLAR-23-24-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/CARTEL-INICIO-DE-ENTRENAMIENTOS-DEPORTE-ESCOLAR-23-24-768x576.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>Estimadas familias:<\/p>\n<p>Con la finalidad de poder agilizar y formar los equipos que representen a nuestro colegio, en los Juegos Escolares 2023\/24, desde el AMPA del CEIP Carlos III, os invita a que apunt\u00e9is a vuestros hijos\/as al deporte que le guste de los que ofertamos. A continuaci\u00f3n, os indicamos los horarios de entrenamiento (<strong>PROVISIONALES, quedando sujetos a modificaciones acorde con las actividades extraescolares o a petici\u00f3n de los entrenadores<\/strong>). Hemos solicitado al ayuntamiento comenzar los<strong> entrenamientos el lunes 18 de septiembre<\/strong>, los entrenadores comunicar\u00e1n a los ni\u00f1os\/as inscritos la hora y el d\u00eda de inicio. <strong>Rogamos inscriban a los ni\u00f1os\/as antes del 15 de septiembre para poder confeccionar y organizar los equipos.\u00a0<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11902\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/CUADRO-DE-ENTRENAMIENTOS-2023-2024-AGOSTO-2023.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/CUADRO-DE-ENTRENAMIENTOS-2023-2024-AGOSTO-2023.jpg 960w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/CUADRO-DE-ENTRENAMIENTOS-2023-2024-AGOSTO-2023-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/CUADRO-DE-ENTRENAMIENTOS-2023-2024-AGOSTO-2023-768x576.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p><strong><u>BALONCESTO<\/u><\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"476\">Mini micro mixto (1\u00ba y 2\u00ba primaria) \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0JULIANA<\/td>\n<td width=\"316\">Martes y jueves de 16 a 17h.<\/td>\n<\/tr>\n<tr>\n<td width=\"476\">Micro benjam\u00edn mixto (3\u00ba primaria)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 FRAN Y ALBA<\/td>\n<td width=\"316\">Martes y jueves de 16 a 17h<\/td>\n<\/tr>\n<tr>\n<td width=\"476\">Micro benjam\u00edn mixto (4\u00ba primaria)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SERGIO\u00a0\u00a0\u00a0\u00a0\u00a0 Y MARIANO<\/td>\n<td width=\"316\">Lunes y mi\u00e9rcoles de 16 a 17h.<\/td>\n<\/tr>\n<tr>\n<td width=\"476\">Mini alev\u00edn mixto (5\u00ba y 6\u00ba primaria)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 IV\u00c1N Y EMILIO<\/td>\n<td width=\"316\">Lunes y mi\u00e9rcoles de 17 a 18 h<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>.<strong><u>F\u00daTBOL<\/u><\/strong><\/p>\n<table width=\"862\">\n<tbody>\n<tr>\n<td width=\"626\">Renacuajo Iniciaci\u00f3n (1\u00ba primaria) \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0SERGIO Y MERCEDES<\/td>\n<td width=\"236\">Lunes y mi\u00e9rcoles \u00a0de 17 a 18h.<\/td>\n<\/tr>\n<tr>\n<td width=\"626\">Renacuajo Competici\u00f3n (2\u00ba primaria)\u00a0\u00a0\u00a0\u00a0 SAMUEL Y JOS\u00c9<\/td>\n<td width=\"236\">Lunes y mi\u00e9rcoles de 16 a 17h<\/td>\n<\/tr>\n<tr>\n<td width=\"626\">Benjam\u00edn (3\u00ba primaria) \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0ALBERTO<\/td>\n<td width=\"236\">Martes \u00a0y jueves \u00a0de 17 a 18 h<\/td>\n<\/tr>\n<tr>\n<td width=\"626\">Benjam\u00edn (4\u00ba primaria)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0IV\u00c1N Y JUAN<\/td>\n<td width=\"236\">Martes y jueves de 16 a 17 h.<\/td>\n<\/tr>\n<tr>\n<td width=\"626\">F\u00fatbol 7 (5\u00ba primaria) \u00a0Campos Enrique Moreno \u201cLalo\u201d (Pinar)\u00a0\u00a0\u00a0 SAMU<\/td>\n<td width=\"236\">Martes \u00a0y jueves de 16 a 17 h<\/td>\n<\/tr>\n<tr>\n<td width=\"626\">F\u00fatbol 7 (6\u00ba primaria) \u00a0Campos Enrique Moreno \u201cLalo\u201d (Pinar)\u00a0 ALBERTO Y JAVI<\/td>\n<td width=\"236\">Lunes y mi\u00e9rcoles de 17 a 18h.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"425\">INICIACI\u00d3N DEPORTIVA 5A\u00d1OS (MULTIDEPORTE)\u00a0 \u00a0SAMU<\/td>\n<td width=\"260\">Martes y jueves de 17 a 17:45 h<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Si est\u00e1is interesados en que vuestro hijo\/a participe en alguno de estos deportes, tan solo ten\u00e9is que rellenar la parte inferior de esta hoja y enviarla al correo <a href=\"mailto:carlosiiideportes@gmail.com\"><strong>carlosiiideportes@gmail.com<\/strong><\/a>. Importante <strong>rellenar todos los datos<\/strong><strong>.<\/strong><\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/hoja-inscripcion-deportes-2023-24-AGOSTO-2023.pdf\">HOJA DE INSCRIPCI\u00d3N DEPORTE ESCOLAR CARLOS III 2023-24 AGOSTO 2023<\/a><\/p>\n<p>A propuesta de los entrenadores (f\u00fatbol y baloncesto) con el fin de que cada equipo pueda disponer de balones, red, petos, botiqu\u00edn\u2026. Habr\u00e1 una <strong>cuota anual de 10 \u20ac para los NO Socios del AMPA y 5\u20ac para los Socios.<\/strong><\/p>\n<p>Gracias por vuestra colaboraci\u00f3n.<\/p>\n<p style=\"text-align: right;\">JUNTA DIRECTIVA AMPA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: Con la finalidad de poder agilizar y formar los equipos que representen a nuestro colegio, en los Juegos Escolares 2023\/24, desde el AMPA del CEIP Carlos III, os invita a que apunt\u00e9is a vuestros hijos\/as al deporte que le guste de los que ofertamos. A continuaci\u00f3n, os indicamos los horarios de entrenamiento (PROVISIONALES, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/09\/07\/deporte-escolar-curso-2023-2024\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDEPORTE ESCOLAR CURSO 2023-2024\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"post_folder":[],"class_list":["post-11899","post","type-post","status-publish","format-standard","hentry","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"Estimadas familias: Con la finalidad de poder agilizar y formar los equipos que representen a nuestro colegio, en los Juegos Escolares 2023\/24, desde el AMPA del CEIP Carlos III, os invita a que apunt\u00e9is a vuestros hijos\/as al deporte que le guste de los que ofertamos. A continuaci\u00f3n, os indicamos los horarios de entrenamiento (PROVISIONALES,&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=11899"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11899\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=11899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=11899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=11899"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=11899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}