{"id":11949,"date":"2023-09-13T15:22:20","date_gmt":"2023-09-13T13:22:20","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=11949"},"modified":"2023-09-13T15:22:20","modified_gmt":"2023-09-13T13:22:20","slug":"escuela-de-chreeleaders-colegio-carlos-iii","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/09\/13\/escuela-de-chreeleaders-colegio-carlos-iii\/","title":{"rendered":"ESCUELA DE CHEERLEADERS COLEGIO CARLOS III"},"content":{"rendered":"<div class=\"column dt-sc-one-half first\">\n<p style=\"text-align: justify;\">La\u00a0<strong>actividad extraescolar \u00abSCHOOL CHEERLEADERS CARLOS III\u00bb <\/strong>es lo que popularmente se conoce como\u00a0<strong>equipo de animadoras\/es<\/strong>. Tradicionalmente se le ha dado un papel secundario a este deporte, simplemente un entretenimiento en los descansos del partido. Ahora sabemos que esta modalidad es reconocida como un\u00a0<strong>deporte que requiere de grandes habilidades y destrezas motoras y cognitivas, trabajo en equipo y gran dedicaci\u00f3n<\/strong>. Una actividad distinta, que ya est\u00e1 al alcance de todos\/as y no solo en las pel\u00edculas.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11950\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/CARTEL-CHEERLEADERS.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/CARTEL-CHEERLEADERS.jpg 960w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/CARTEL-CHEERLEADERS-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/CARTEL-CHEERLEADERS-768x576.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p style=\"text-align: justify;\">Ofrecemos la\u00a0<strong>actividad extraescolar school cheerleaders<\/strong>\u00a0como un deporte muy atractivo, donde la\u00a0<strong>m\u00fasica, el baile, la coordinaci\u00f3n, las coreograf\u00edas<\/strong>\u00a0e incluso la vestimenta son esenciales para que funcione. Una\u00a0<strong>extraescolar con ritmo<\/strong>, que motivar\u00e1 a todos\/as a hacer deporte.<\/p>\n<\/div>\n<div class=\"column dt-sc-one-half \">\n<p style=\"text-align: justify;\">La\u00a0<strong>actividad extraescolar school cheerleaders<\/strong>\u00a0es una actividad que requiere el\u00a0<strong>trabajo en equipo<\/strong>. Ayudar\u00e1 a mantener un\u00a0<strong>buen estado de salud f\u00edsica<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Ejercitar\u00e1 los\u00a0<strong>m\u00fasculos, la velocidad, agilidad y la coordinaci\u00f3n<\/strong>. Tambi\u00e9n estar\u00e1n muy presentes las\u00a0<strong>capacidades cognitivas<\/strong>\u00a0como son la\u00a0<strong>concentraci\u00f3n, atenci\u00f3n o la memoria<\/strong>. Como toda actividad deportiva, mejorar\u00e1 el\u00a0<strong>estado de \u00e1nimo<\/strong>\u00a0y ofrecer\u00e1 el valor de compa\u00f1erismo.<\/p>\n<p style=\"text-align: justify;\">Las\u00a0<strong>acrobacias, pir\u00e1mides, saltos o coreograf\u00edas<\/strong>\u00a0son algo esencial en este deporte, por lo que aprender\u00e1n todas\u00a0<strong>las habilidades, t\u00e9cnicas y estrategias<\/strong>\u00a0para poder realizarlas. El\u00a0<strong>esfuerzo y la motivaci\u00f3n<\/strong>\u00a0por lograr una meta ser\u00e1n fundamentales.<\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11973 alignleft\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/WhatsApp-Image-2023-09-11-at-19.36.24.jpeg\" alt=\"\" width=\"250\" height=\"333\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/WhatsApp-Image-2023-09-11-at-19.36.24.jpeg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/WhatsApp-Image-2023-09-11-at-19.36.24-225x300.jpeg 225w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/WhatsApp-Image-2023-09-11-at-19.36.24-300x400.jpeg 300w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/>Esta actividad extraescolar ser\u00e1 impartida por Marina Carrascosa C\u00e1ceres<\/strong>, una joven graduada en el <u>Grado de Educaci\u00f3n Primaria<\/u> (2019-2023) por la UCM, en posesi\u00f3n de la Beca Extraordinaria de Excelencia en los cursos 2018-2019 y 2022-2023, dispuesta a hacer de la actividad de <em>Cheerleaders,<\/em>un espacio seguro en el que todos los alumnos\/as puedan disfrutar y aprender a la vez.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s del\u00a0propio grado en relaci\u00f3n con la infancia, su experiencia de m\u00e1s de <u>siete a\u00f1os otorgando clases particulares<\/u> la permite conocer herramientas para trabajar con los m\u00e1s peque\u00f1os. A su vez, tiene experiencia en eventos puntuales de ocio y tiempo libre, como en la organizaci\u00f3n de cumplea\u00f1os.<\/p>\n<p style=\"text-align: justify;\">En lo referido al baile, su trayectoria como monitora de Zumba y bailes latinos de los \u00faltimos seis a\u00f1os en gimnasios valida el conocimiento de diferentes estilos de m\u00fasica, baile y dinamizaci\u00f3n de clases colectivas. En el a\u00f1o 2018, consigui\u00f3 la <u>titulaci\u00f3n oficial como Instructora de Zumba Zin<\/u>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La\u00a0actividad extraescolar \u00abSCHOOL CHEERLEADERS CARLOS III\u00bb es lo que popularmente se conoce como\u00a0equipo de animadoras\/es. Tradicionalmente se le ha dado un papel secundario a este deporte, simplemente un entretenimiento en los descansos del partido. Ahora sabemos que esta modalidad es reconocida como un\u00a0deporte que requiere de grandes habilidades y destrezas motoras y cognitivas, trabajo en &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/09\/13\/escuela-de-chreeleaders-colegio-carlos-iii\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abESCUELA DE CHEERLEADERS COLEGIO CARLOS III\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"post_folder":[],"class_list":["post-11949","post","type-post","status-publish","format-standard","hentry","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"La\u00a0actividad extraescolar \u00abSCHOOL CHEERLEADERS CARLOS III\u00bb es lo que popularmente se conoce como\u00a0equipo de animadoras\/es. Tradicionalmente se le ha dado un papel secundario a este deporte, simplemente un entretenimiento en los descansos del partido. Ahora sabemos que esta modalidad es reconocida como un\u00a0deporte que requiere de grandes habilidades y destrezas motoras y cognitivas, trabajo en&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=11949"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11949\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=11949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=11949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=11949"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=11949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}