{"id":11990,"date":"2023-09-15T12:57:03","date_gmt":"2023-09-15T10:57:03","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=11990"},"modified":"2023-09-15T12:57:03","modified_gmt":"2023-09-15T10:57:03","slug":"actividades-extraescolares-del-ayuntamiento-de-aranjuez-curso-2023-2024","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/09\/15\/actividades-extraescolares-del-ayuntamiento-de-aranjuez-curso-2023-2024\/","title":{"rendered":"ACTIVIDADES EXTRAESCOLARES DEL AYUNTAMIENTO DE ARANJUEZ (CURSO 2023-2024)"},"content":{"rendered":"<p>Ya est\u00e1 publicado en la p\u00e1gina web del Ayuntamiento de Aranjuez, la propuesta de actividades extraescolares para nuestro Centro organizadas gestionadas por Delegaci\u00f3n de Educaci\u00f3n. Pod\u00e9is pinchar en el siguiente enlace para acceder a la informaci\u00f3n publicada.<\/p>\n<p><a href=\"https:\/\/www.aranjuez.es\/educacion\/actividades-dias-lectivos\">https:\/\/www.aranjuez.es\/educacion\/actividades-dias-lectivos<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11991\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/Diapositiva1-1-1.jpg\" alt=\"\" width=\"720\" height=\"960\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/Diapositiva1-1-1.jpg 720w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/Diapositiva1-1-1-225x300.jpg 225w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/Diapositiva1-1-1-300x400.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11992\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/Diapositiva2-1-1.jpg\" alt=\"\" width=\"720\" height=\"960\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/Diapositiva2-1-1.jpg 720w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/Diapositiva2-1-1-225x300.jpg 225w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2023\/09\/Diapositiva2-1-1-300x400.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p>Gracias por vuestra colaboraci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1 publicado en la p\u00e1gina web del Ayuntamiento de Aranjuez, la propuesta de actividades extraescolares para nuestro Centro organizadas gestionadas por Delegaci\u00f3n de Educaci\u00f3n. Pod\u00e9is pinchar en el siguiente enlace para acceder a la informaci\u00f3n publicada. https:\/\/www.aranjuez.es\/educacion\/actividades-dias-lectivos Gracias por vuestra colaboraci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,29,30],"tags":[],"post_folder":[],"class_list":["post-11990","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias","category-noticias","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"Ya est\u00e1 publicado en la p\u00e1gina web del Ayuntamiento de Aranjuez, la propuesta de actividades extraescolares para nuestro Centro organizadas gestionadas por Delegaci\u00f3n de Educaci\u00f3n. Pod\u00e9is pinchar en el siguiente enlace para acceder a la informaci\u00f3n publicada. https:\/\/www.aranjuez.es\/educacion\/actividades-dias-lectivos Gracias por vuestra colaboraci\u00f3n.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=11990"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/11990\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=11990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=11990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=11990"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=11990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}