{"id":12079,"date":"2023-09-28T15:15:53","date_gmt":"2023-09-28T13:15:53","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=12079"},"modified":"2026-03-12T17:09:10","modified_gmt":"2026-03-12T16:09:10","slug":"actividades-extraescolares-ampa-y-ayuntamiento-curso-2023-2024","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/09\/28\/actividades-extraescolares-ampa-y-ayuntamiento-curso-2023-2024\/","title":{"rendered":"ACTIVIDADES EXTRAESCOLARES 2025\/2026"},"content":{"rendered":"<div>\n<div style=\"text-align: left;\">Estimadas familias:<\/div>\n<div><\/div>\n<div>Las actividades extraescolares son ofertadas por el AFA (Asociaci\u00f3n de Familias de Alumnos) y por el Ayuntamiento de Aranjuez. A continuaci\u00f3n os facilitamos enlaces para consultar dichas actividades, as\u00ed como su precio y d\u00eda de realizaci\u00f3n:<\/div>\n<\/div>\n<div aria-hidden=\"true\"><\/div>\n<ul>\n<li aria-hidden=\"true\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2026\/03\/INSCRIPCION-ACTIVIDADES-EXTRAESCOLARES-CURSO-2025-26.pdf\" target=\"_blank\" rel=\"noopener\">Extraescolares del AFA<\/a><\/li>\n<li aria-hidden=\"true\"><a href=\"https:\/\/spsociales.com\/aranjuez_extraescolares\/\" target=\"_blank\" rel=\"noopener\">Extraescolares del Ayuntamiento<\/a><\/li>\n<\/ul>\n<div aria-hidden=\"true\"><\/div>\n<div aria-hidden=\"true\"><\/div>\n<div aria-hidden=\"true\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: Las actividades extraescolares son ofertadas por el AFA (Asociaci\u00f3n de Familias de Alumnos) y por el Ayuntamiento de Aranjuez. A continuaci\u00f3n os facilitamos enlaces para consultar dichas actividades, as\u00ed como su precio y d\u00eda de realizaci\u00f3n: Extraescolares del AFA Extraescolares del Ayuntamiento<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,69,29,30],"tags":[],"post_folder":[],"class_list":["post-12079","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias","category-ampa","category-noticias","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/ampa\/\" rel=\"category tag\">AMPA<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"Estimadas familias: Las actividades extraescolares son ofertadas por el AFA (Asociaci\u00f3n de Familias de Alumnos) y por el Ayuntamiento de Aranjuez. A continuaci\u00f3n os facilitamos enlaces para consultar dichas actividades, as\u00ed como su precio y d\u00eda de realizaci\u00f3n: Extraescolares del AFA Extraescolares del Ayuntamiento","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/12079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=12079"}],"version-history":[{"count":4,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/12079\/revisions"}],"predecessor-version":[{"id":13798,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/12079\/revisions\/13798"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=12079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=12079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=12079"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=12079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}