{"id":12131,"date":"2023-10-13T16:31:17","date_gmt":"2023-10-13T14:31:17","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=12131"},"modified":"2023-10-13T16:31:17","modified_gmt":"2023-10-13T14:31:17","slug":"acta-ii-asamblea-pitufos-28-de-septiembre-de-2023","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/10\/13\/acta-ii-asamblea-pitufos-28-de-septiembre-de-2023\/","title":{"rendered":"ACTA II ASAMBLEA PITUFOS 28 DE SEPTIEMBRE DE 2023"},"content":{"rendered":"<p>D\u00cdA: 28 DE SPETIEMBRE\u00a0 HORA: 11:20-10:50 \u00a0\u00a0 LUGAR: pabell\u00f3n<\/p>\n<p>PARTICIPAN: 6\u00baA, 6\u00baB, 6\u00baC, 5\u00baA, 5\u00baB, 4\u00baA, 4\u00baB, 4\u00baC, 4\u00baD, 2\u00baA Y 2\u00baB<\/p>\n<ul>\n<li>Entrega de listados de alumnos voluntarios de 5\u00ba Primaria (Divertipatio) y 6\u00ba de Primaria (Alumnos\/as Convivencia, Radio Escolar y Jueces Voluntarios\/as para la Charlie League).<\/li>\n<\/ul>\n<p>6\u00baC entrega lista de volunatrios\/as para la Radio Escolar: Adriana Sard\u00f3n, Silvia Monreal, Abril Pinto y Luc\u00eda Zato.<\/p>\n<p>5\u00baA entrega lista de voluntarios\/as Divertipatio \u00a0Milene, Jana, Martina, Leyre, \u00c1frica, \u00c1lvaro, Ingrid, Lluvia, Irene, Zaka, Nerea, Jimena y David T.<\/p>\n<p>6\u00baC entrega lista de voluntarios para hacer de gu\u00eda con los Auxiliares de Conversaci\u00f3n.<\/p>\n<p>Las clases de 4\u00ba no aportan ning\u00fan listado de canciones aptas para la mini disco y melod\u00eda de las ma\u00f1anas.<\/p>\n<ul>\n<li>Informaci\u00f3n del d\u00eda de la Bicicleta (Domingo 8 de octubre). Inscripciones telem\u00e1ticas.<\/li>\n<\/ul>\n<p>Se informa de la actividad del d\u00eda de la bicicleta y que las inscripciones son telem\u00e1ticamente.<\/p>\n<ul>\n<li>Elaboraci\u00f3n del calendario de la Charlie League.<\/li>\n<\/ul>\n<p>Por ahora, no hay volunatarios\/as de 6\u00ba de Primaria para arbitrar la Charlie League, por lo tanto no empieza.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Organizaci\u00f3n Charlie Points (elegir los criterios por lo que se conceden puntos y cuantos y seleccionar los premios que se otorgan).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Participaci\u00f3n en actividades de centro<\/p>\n<p>2 puntos para la clase por participante.<\/p>\n<p>D\u00eda de la Bici (2)<\/p>\n<p>Convivencia (21 puntos semanales)<\/p>\n<p>Limpieza orden de la clase (-1\/1 punto diario o -5\/5 semanales).<\/p>\n<p>Estado de las zonas comunes (ba\u00f1os, patios, pasillos) -10 a 10.<\/p>\n<p>Desplazamientos en silencio y en fila de -3 a 3.<\/p>\n<p>Participaci\u00f3n en equipos del colegio +3<\/p>\n<p>Concursos, crosses +2<\/p>\n<p>Actos significativos que mejoren la convivencia +10<\/p>\n<p>Colaboraci\u00f3n en el fomento de la convivencia (asistir a reuniones de Pitufos, participar en Divertipatio, alumnos\/as de convivencia, \u2026) +3<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>PREMIOS PARA CANJEAR POR PUNTOS<\/p>\n<p>M\u00e1s tiempo de patio 100 puntos<\/p>\n<p>Un bal\u00f3n extra por clase 200 puntos<\/p>\n<p>Taller de globofexia o chapas 300 puntos<\/p>\n<p>Merienda especial 400 puntos<\/p>\n<p>Juego de mesa 500 puntos (uno, virus o similar).<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Ruegos y preguntas.<\/li>\n<\/ul>\n<p>Los representantes de 4\u00baA dicen que el reloj de clase no funciona, se comunica que ser\u00e1n las pilas, que pueden mirar si ese es el problema y pedirlas en secretar\u00eda.<\/p>\n<p>Piden una red de v\u00f3ley para el recreo. Se ver\u00e1 posibilidades.<\/p>\n<p>&nbsp;<\/p>\n<p>DEBERES:<\/p>\n<p>Entregar\u00a0 (aquellos que no lo hayan hecho) lista de voluntarios\/as:<\/p>\n<p>6\u00ba de jueces de Charlie League, Alumnado Convivencia y Radio Escolar.<\/p>\n<p>5\u00ba Divertipatio<\/p>\n<p>4\u00ba y 3\u00ba Canciones mini disco y entradas ma\u00f1ana.<\/p>\n<p>Todos las clases listado de alumnos\/as:<\/p>\n<ul>\n<li>Que juegan en los equipos del colegio (f\u00fatbol y baloncesto).<\/li>\n<li>Participaron en el D\u00eda de la Bicicleta.<\/li>\n<li>Alumnos\/as inscritos para el cross del Deleite.<\/li>\n<\/ul>\n<p>PR\u00d3XIMA ASAMBLEA: 19 DE COTUBRE A LA HORA DEL RECREO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00cdA: 28 DE SPETIEMBRE\u00a0 HORA: 11:20-10:50 \u00a0\u00a0 LUGAR: pabell\u00f3n PARTICIPAN: 6\u00baA, 6\u00baB, 6\u00baC, 5\u00baA, 5\u00baB, 4\u00baA, 4\u00baB, 4\u00baC, 4\u00baD, 2\u00baA Y 2\u00baB Entrega de listados de alumnos voluntarios de 5\u00ba Primaria (Divertipatio) y 6\u00ba de Primaria (Alumnos\/as Convivencia, Radio Escolar y Jueces Voluntarios\/as para la Charlie League). 6\u00baC entrega lista de volunatrios\/as para la Radio &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2023\/10\/13\/acta-ii-asamblea-pitufos-28-de-septiembre-de-2023\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abACTA II ASAMBLEA PITUFOS 28 DE SEPTIEMBRE DE 2023\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[],"post_folder":[],"class_list":["post-12131","post","type-post","status-publish","format-standard","hentry","category-actas-y-convocatorias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/pitufos-asamblea-de-alumnos-2\/actas-y-convocatorias\/\" rel=\"category tag\">Actas y Convocatorias<\/a>","rttpg_excerpt":"D\u00cdA: 28 DE SPETIEMBRE\u00a0 HORA: 11:20-10:50 \u00a0\u00a0 LUGAR: pabell\u00f3n PARTICIPAN: 6\u00baA, 6\u00baB, 6\u00baC, 5\u00baA, 5\u00baB, 4\u00baA, 4\u00baB, 4\u00baC, 4\u00baD, 2\u00baA Y 2\u00baB Entrega de listados de alumnos voluntarios de 5\u00ba Primaria (Divertipatio) y 6\u00ba de Primaria (Alumnos\/as Convivencia, Radio Escolar y Jueces Voluntarios\/as para la Charlie League). 6\u00baC entrega lista de volunatrios\/as para la Radio&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/12131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=12131"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/12131\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=12131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=12131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=12131"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=12131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}