{"id":1216,"date":"2016-11-29T10:31:39","date_gmt":"2016-11-29T10:31:39","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1216"},"modified":"2016-11-29T10:31:39","modified_gmt":"2016-11-29T10:31:39","slug":"la-ciudad-sostenible-milk-cartons-houses-grade-4-art-and-crafts-2","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/11\/29\/la-ciudad-sostenible-milk-cartons-houses-grade-4-art-and-crafts-2\/","title":{"rendered":"LA CIUDAD SOSTENIBLE: MILK CARTONS HOUSES. GRADE 4 ART AND CRAFTS"},"content":{"rendered":"<p>Los alumnos y alumnas de 4\u00ba de Primaria en las clases de Art and Crafts han construido una Ciudad Sostenible, utilizando elementos reciclados (los cartones vac\u00edos de leche).<\/p>\n<p>A continuaci\u00f3n ten\u00e9is una breve explicaci\u00f3n de los pasos que han tenido que seguir para la elaboraci\u00f3n de esta manualidad.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/v\/t1.0-9\/15253542_1275748469149500_2762453013327218629_n.jpg?oh=8b767261a8d0b32bebc58df18bd918de&amp;oe=58B80682\" alt=\"\" width=\"165\" height=\"293\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/t31.0-8\/15168908_1275748542482826_7029011154674329635_o.jpg\" alt=\"\" width=\"519\" height=\"292\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos y alumnas de 4\u00ba de Primaria en las clases de Art and Crafts han construido una Ciudad Sostenible, utilizando elementos reciclados (los cartones vac\u00edos de leche). A continuaci\u00f3n ten\u00e9is una breve explicaci\u00f3n de los pasos que han tenido que seguir para la elaboraci\u00f3n de esta manualidad.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"post_folder":[],"class_list":["post-1216","post","type-post","status-publish","format-standard","hentry","category-proyecto-bilinguee"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/bilingueismo\/proyecto-bilinguee\/\" rel=\"category tag\">Proyecto Biling\u00fce<\/a>","rttpg_excerpt":"Los alumnos y alumnas de 4\u00ba de Primaria en las clases de Art and Crafts han construido una Ciudad Sostenible, utilizando elementos reciclados (los cartones vac\u00edos de leche). A continuaci\u00f3n ten\u00e9is una breve explicaci\u00f3n de los pasos que han tenido que seguir para la elaboraci\u00f3n de esta manualidad.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1216"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1216\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1216"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}