{"id":1225,"date":"2016-12-07T12:40:34","date_gmt":"2016-12-07T12:40:34","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1225"},"modified":"2016-12-07T12:40:34","modified_gmt":"2016-12-07T12:40:34","slug":"dibujos-seleccionados-por-los-pitufos-mejora-tu-colegio","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/12\/07\/dibujos-seleccionados-por-los-pitufos-mejora-tu-colegio\/","title":{"rendered":"DIBUJOS SELECCIONADOS POR LOS PITUFOS. MEJORA TU COLEGIO"},"content":{"rendered":"<p>En la 6\u00aa Asamblea de Delegados y Representantes de Alumnos\/as, que se ha celebrado el mi\u00e9rcoles 7 de diciembre de 2016, a las 12:00, en la sala de profesores de Primaria, se han seleccionado dos dibujos del Concurso Mejora tu Colegio \u00abPor una Escuela m\u00e1s Sostenible y con mejor clima de Convivencia\u00bb, hechos por Gina y Jimena, ambas de 5\u00baA.<\/p>\n<p>Estos dibujos, ser\u00e1n utilizados para elaborar carteles y otros elementos, con el fin de mejorar la Convivencia y la Sostenibilidad del Colegio.<\/p>\n<p>A continuaci\u00f3n pod\u00e9is ver los dibujos seleccionados, por los alumnos y alumnas miembros de los Pitufos.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/scontent.fmad3-2.fna.fbcdn.net\/v\/t1.0-0\/s480x480\/15268084_1287267001330980_7422880604801126923_n.jpg?oh=6160aefddafb79395e3d6288f0b04339&amp;oe=58F38DDD\" alt=\"\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent.fmad3-2.fna.fbcdn.net\/t31.0-8\/s960x960\/15304274_1287267177997629_56492079880133611_o.jpg\" alt=\"\" width=\"338\" height=\"478\" \/><\/p>\n<p>Todos los dibujos presentados ser\u00e1n utilizados para realizar un libro\/cuadernillo para la Biblioteca del Colegio.\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la 6\u00aa Asamblea de Delegados y Representantes de Alumnos\/as, que se ha celebrado el mi\u00e9rcoles 7 de diciembre de 2016, a las 12:00, en la sala de profesores de Primaria, se han seleccionado dos dibujos del Concurso Mejora tu Colegio \u00abPor una Escuela m\u00e1s Sostenible y con mejor clima de Convivencia\u00bb, hechos por Gina &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/12\/07\/dibujos-seleccionados-por-los-pitufos-mejora-tu-colegio\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDIBUJOS SELECCIONADOS POR LOS PITUFOS. MEJORA TU COLEGIO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"post_folder":[],"class_list":["post-1225","post","type-post","status-publish","format-standard","hentry","category-otras-iniciativas"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/pitufos-asamblea-de-alumnos-2\/otras-iniciativas\/\" rel=\"category tag\">Otras iniciativas<\/a>","rttpg_excerpt":"En la 6\u00aa Asamblea de Delegados y Representantes de Alumnos\/as, que se ha celebrado el mi\u00e9rcoles 7 de diciembre de 2016, a las 12:00, en la sala de profesores de Primaria, se han seleccionado dos dibujos del Concurso Mejora tu Colegio \u00abPor una Escuela m\u00e1s Sostenible y con mejor clima de Convivencia\u00bb, hechos por Gina&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1225"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1225\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1225"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}