{"id":1253,"date":"2016-12-19T08:43:49","date_gmt":"2016-12-19T08:43:49","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1253"},"modified":"2016-12-19T08:43:49","modified_gmt":"2016-12-19T08:43:49","slug":"fiesta-de-navidad-de-infantil","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/12\/19\/fiesta-de-navidad-de-infantil\/","title":{"rendered":"FIESTA DE NAVIDAD DE INFANTIL"},"content":{"rendered":"<p>Estimadas familias:<\/p>\n<p>\u00a0<\/p>\n<p>El pr\u00f3ximo jueves\u00a0 22 de diciembre celebraremos la fiesta de Navidad. Los ni\u00f1os pueden venir disfrazados de motivos navide\u00f1os, sin complementos.<\/p>\n<p>Para desayunar tomaremos chocolate con churros.<\/p>\n<p>\u00a0<\/p>\n<p>Muchas gracias.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0El equipo de infantil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: \u00a0 El pr\u00f3ximo jueves\u00a0 22 de diciembre celebraremos la fiesta de Navidad. Los ni\u00f1os pueden venir disfrazados de motivos navide\u00f1os, sin complementos. Para desayunar tomaremos chocolate con churros. \u00a0 Muchas gracias. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/12\/19\/fiesta-de-navidad-de-infantil\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abFIESTA DE NAVIDAD DE INFANTIL\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"post_folder":[],"class_list":["post-1253","post","type-post","status-publish","format-standard","hentry","category-infantil"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/\" rel=\"category tag\">Infantil<\/a>","rttpg_excerpt":"Estimadas familias: \u00a0 El pr\u00f3ximo jueves\u00a0 22 de diciembre celebraremos la fiesta de Navidad. Los ni\u00f1os pueden venir disfrazados de motivos navide\u00f1os, sin complementos. Para desayunar tomaremos chocolate con churros. \u00a0 Muchas gracias. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1253"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1253\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1253"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}