{"id":1272,"date":"2016-12-24T07:21:08","date_gmt":"2016-12-24T07:21:08","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1272"},"modified":"2016-12-24T07:21:08","modified_gmt":"2016-12-24T07:21:08","slug":"creamos-juegos-de-patio-para-los-pequenos","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/12\/24\/creamos-juegos-de-patio-para-los-pequenos\/","title":{"rendered":"CREAMOS JUEGOS DE PATIO PARA LOS PEQUE\u00d1OS"},"content":{"rendered":"<p>Los alumnos y alumnas de Educaci\u00f3n C\u00edvica y valores de 4\u00ba de Primaria, dibujaron para los ni\u00f1os y ni\u00f1as de 1\u00ba y 2\u00ba de Primaria (en su patio), circuitos y juegos diversos. Unos dise\u00f1os previamente planeados y realizados en sus cuadernos. Eran provisionales, as\u00ed que los hicieron con tizas y almacenaron un bote con tapones para utilizarlos como chapas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3363\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033.jpg\" alt=\"\" width=\"287\" height=\"383\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033.jpg 972w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-225x300.jpg 225w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-768x1024.jpg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-300x400.jpg 300w\" sizes=\"auto, (max-width: 287px) 100vw, 287px\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3364\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0032.jpg\" alt=\"\" width=\"288\" height=\"384\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0032.jpg 972w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0032-225x300.jpg 225w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0032-768x1024.jpg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0032-300x400.jpg 300w\" sizes=\"auto, (max-width: 288px) 100vw, 288px\" \/> \u00a0 \u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos y alumnas de Educaci\u00f3n C\u00edvica y valores de 4\u00ba de Primaria, dibujaron para los ni\u00f1os y ni\u00f1as de 1\u00ba y 2\u00ba de Primaria (en su patio), circuitos y juegos diversos. Unos dise\u00f1os previamente planeados y realizados en sus cuadernos. Eran provisionales, as\u00ed que los hicieron con tizas y almacenaron un bote con tapones &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/12\/24\/creamos-juegos-de-patio-para-los-pequenos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCREAMOS JUEGOS DE PATIO PARA LOS PEQUE\u00d1OS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":3363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63],"tags":[],"post_folder":[],"class_list":["post-1272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-4-primaria"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033.jpg",972,1296,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033.jpg",972,1296,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033.jpg",972,1296,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-225x300.jpg",225,300,true],"large":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-768x1024.jpg",525,700,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033.jpg",375,500,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033.jpg",972,1296,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033.jpg",972,1296,false],"twentyseventeen-featured-image":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-972x1200.jpg",972,1200,true],"twentyseventeen-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-100x100.jpg",100,100,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033.jpg",357,476,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033.jpg",180,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2016\/12\/IMG-20161223-WA0033.jpg",972,1296,false]},"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/4-primaria\/\" rel=\"category tag\">4\u00ba Primaria<\/a>","rttpg_excerpt":"Los alumnos y alumnas de Educaci\u00f3n C\u00edvica y valores de 4\u00ba de Primaria, dibujaron para los ni\u00f1os y ni\u00f1as de 1\u00ba y 2\u00ba de Primaria (en su patio), circuitos y juegos diversos. Unos dise\u00f1os previamente planeados y realizados en sus cuadernos. Eran provisionales, as\u00ed que los hicieron con tizas y almacenaron un bote con tapones&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1272"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1272\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media\/3363"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1272"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}