{"id":130,"date":"2013-10-22T15:55:12","date_gmt":"2013-10-22T15:55:12","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=130"},"modified":"2013-10-22T15:55:12","modified_gmt":"2013-10-22T15:55:12","slug":"comunicado-a-las-familias-huelga-24-de-octubre-de-2013","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2013\/10\/22\/comunicado-a-las-familias-huelga-24-de-octubre-de-2013\/","title":{"rendered":"Comunicado a las familias huelga 24 de Octubre de 2013"},"content":{"rendered":"<p>Mediante escrito que suscriben las organizaciones sindicales FREM-CCOO, FETE-UGT, STEM , CGT,ANPE y CSI-F,\u00a0 con independencia de alg\u00fan peque\u00f1o matiz en los \u00e1mbitos de la convocatoria, convocan a todo el personal docente y no docente de la ense\u00f1anza p\u00fablica en la Comunidad de Madrid a la huelga que tendr\u00e1 lugar durante <span style=\"text-decoration: underline;\">la jornada del d\u00eda 24 de octubre de 2013, comenzando a las 00.00 horas y terminando a las 24.00 horas.<\/span><\/p>\n<p>\u00a0<\/p>\n<p>El d\u00eda 18 de octubre del corriente a\u00f1o se ha celebrado una reuni\u00f3n a la que han asistido las organizaciones convocantes, con el fin de acordar los servicios m\u00ednimos que deben ser fijados para el mantenimiento de los servicios esenciales el d\u00eda 24 de octubre de 2013, con motivo de la huelga convocada. El acuerdo suscrito en la reuni\u00f3n entre la representaci\u00f3n de la Administraci\u00f3n y el comit\u00e9 de huelga cuenta, en consecuencia, con la conformidad en todos sus t\u00e9rminos, de las organizaciones sindicales FREM- CC OO, FETE- UGT, STEM, CSI-F y ANPE, convocantes de la huelga.<\/p>\n<p>Servicios m\u00ednimos que de acuerdo con las caracter\u00edsticas de nuestro centro se subrayan en los art\u00edculos<strong> de la Orden de la Consejer\u00eda de Educaci\u00f3n, Juventud y Deporte por la que se establecen los servicios m\u00ednimos esenciales en los centros docentes p\u00fablicos de ense\u00f1anzas no universitarias de la Comunidad de Madrid, con ocasi\u00f3n de la huelga convocada para el d\u00eda 24 de octubre de 2013 y <\/strong>que se detallan a continuaci\u00f3n:<\/p>\n<p>\u00a0<\/p>\n<p><em>2.1. <span style=\"text-decoration: underline;\">Para todos los centros docentes p\u00fablicos<\/span>: <\/em><\/p>\n<p><strong><em><span style=\"text-decoration: underline;\">Director y Jefe de Estudios<\/span><\/em><\/strong><em>. Adem\u00e1s, el <strong><span style=\"text-decoration: underline;\">Secretario<\/span><\/strong> del centro docente para todos aquellos centros educativos con Educaci\u00f3n Infantil y Primaria y un Diplomado Universitario en Enfermer\u00eda (DUE) en aquellos centros donde exista este personal por alumnos con necesidades sanitarias.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>2.2. <span style=\"text-decoration: underline;\">En centros ordinarios que atiendan a alumnos con necesidades educativas especiales<\/span>:<\/em><\/p>\n<p><em>Adem\u00e1s de los establecidos con car\u00e1cter general para todos los centros, un profesor de las especialidades de Educaci\u00f3n Especial por cada 50 alumnos con dichas necesidades o fracci\u00f3n, y un tercio del personal no docente con atenci\u00f3n directa a los alumnos, excluidos los de las categor\u00edas de fisioterapeuta y terapeuta ocupacional.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>2.9. <\/em><strong><span style=\"text-decoration: underline;\">Servicio de comedor<\/span><\/strong><span style=\"text-decoration: underline;\"> en centros educativos p\u00fablicos, prestados por empresas<\/span><em>:<\/em><\/p>\n<p><strong><em>Se garantizar\u00e1n los servicios de comedor a los alumnos de Educaci\u00f3n Infantil de cero a tres a\u00f1os y a los alumnos de Educaci\u00f3n Especial.<\/em><\/strong><\/p>\n<p>\u00a0<\/p>\n<p>Desde la direcci\u00f3n como es obvio, no conocemos el seguimiento de la convocatoria de huelga\u00a0 del\u00a0 personal de los distintos sectores del centro y por lo tanto no podemos garantizar el funcionamiento normal\u00a0 de todos\u00a0 los servicios\u00a0 y actividades habituales: profesores, monitores, personal de limpieza\u2026 etc. Por lo que se prev\u00e9 el car\u00e1cter excepcional de la jornada que se organizar\u00e1 en funci\u00f3n del personal que no siga la huelga y los servicios m\u00ednimos.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mediante escrito que suscriben las organizaciones sindicales FREM-CCOO, FETE-UGT, STEM , CGT,ANPE y CSI-F,\u00a0 con independencia de alg\u00fan peque\u00f1o matiz en los \u00e1mbitos de la convocatoria, convocan a todo el personal docente y no docente de la ense\u00f1anza p\u00fablica en la Comunidad de Madrid a la huelga que tendr\u00e1 lugar durante <span style=\"text-decoration: underline;\">la jornada del d\u00eda 24 de octubre de 2013, comenzando a las 00.00 horas y terminando a las 24.00 horas.<\/span><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"post_folder":[],"class_list":["post-130","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Mediante escrito que suscriben las organizaciones sindicales FREM-CCOO, FETE-UGT, STEM , CGT,ANPE y CSI-F,\u00a0 con independencia de alg\u00fan peque\u00f1o matiz en los \u00e1mbitos de la convocatoria, convocan a todo el personal docente y no docente de la ense\u00f1anza p\u00fablica en la Comunidad de Madrid a la huelga que tendr\u00e1 lugar durante la jornada del d\u00eda&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=130"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/130\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=130"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}