{"id":1356,"date":"2017-02-09T10:08:10","date_gmt":"2017-02-09T10:08:10","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1356"},"modified":"2017-02-09T10:08:10","modified_gmt":"2017-02-09T10:08:10","slug":"las-primerizas-colaboran-con-el-carnaval","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/02\/09\/las-primerizas-colaboran-con-el-carnaval\/","title":{"rendered":"LAS \u00abPRIMERIZAS\u00bb COLABORAN CON EL CARNAVAL"},"content":{"rendered":"<p>Las madres de 3 a\u00f1os, las \u00abprimerizas\u00bb, han empezado hoy los talleres para elaborar los disfraces para el carnaval del Colegio, de sus hijos e hijas. Con la misma ilusi\u00f3n y emoci\u00f3n por la novedad, que sus peque\u00f1os, est\u00e1n creando los trajes para la actividad de Centro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3479\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003.jpg\" alt=\"\" width=\"346\" height=\"260\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003.jpg 1600w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-1024x768.jpg 1024w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-768x576.jpg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3480\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0002.jpg\" alt=\"\" width=\"344\" height=\"258\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0002.jpg 1600w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0002-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0002-1024x768.jpg 1024w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0002-768x576.jpg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0002-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 344px) 100vw, 344px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 14pt;\">Gracias \u00abmamis\u00bb de 3 a\u00f1os.<\/span><\/strong><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las madres de 3 a\u00f1os, las \u00abprimerizas\u00bb, han empezado hoy los talleres para elaborar los disfraces para el carnaval del Colegio, de sus hijos e hijas. Con la misma ilusi\u00f3n y emoci\u00f3n por la novedad, que sus peque\u00f1os, est\u00e1n creando los trajes para la actividad de Centro. Gracias \u00abmamis\u00bb de 3 a\u00f1os. \u00a0<\/p>\n","protected":false},"author":3,"featured_media":3479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"post_folder":[],"class_list":["post-1356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3-anos"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003.jpg",1600,1200,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003.jpg",1600,1200,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003.jpg",1600,1200,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-300x225.jpg",300,225,true],"large":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-1024x768.jpg",525,394,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003.jpg",500,375,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-1536x1152.jpg",1536,1152,true],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003.jpg",1600,1200,false],"twentyseventeen-featured-image":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003.jpg",1600,1200,false],"twentyseventeen-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-100x100.jpg",100,100,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003.jpg",360,270,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003.jpg",320,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0003.jpg",1600,1200,false]},"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/3-anos\/\" rel=\"category tag\">3 A\u00f1os<\/a>","rttpg_excerpt":"Las madres de 3 a\u00f1os, las \u00abprimerizas\u00bb, han empezado hoy los talleres para elaborar los disfraces para el carnaval del Colegio, de sus hijos e hijas. Con la misma ilusi\u00f3n y emoci\u00f3n por la novedad, que sus peque\u00f1os, est\u00e1n creando los trajes para la actividad de Centro. Gracias \u00abmamis\u00bb de 3 a\u00f1os. \u00a0","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1356"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media\/3479"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1356"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}