{"id":1359,"date":"2017-02-10T10:41:11","date_gmt":"2017-02-10T10:41:11","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1359"},"modified":"2017-02-10T10:41:11","modified_gmt":"2017-02-10T10:41:11","slug":"educacion-postural-por-el-colegio-de-fisioterapeutas-de-madrid","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/02\/10\/educacion-postural-por-el-colegio-de-fisioterapeutas-de-madrid\/","title":{"rendered":"EDUCACI\u00d3N POSTURAL POR EL COLEGIO DE FISIOTERAPEUTAS DE MADRID"},"content":{"rendered":"<h3 class=\"resumen\">\u00a0<\/h3>\n<div class=\"formato-texto-seccion\">\n<p>Es semana y la que viene, los alumnos y alumnas de 4 a\u00f1os, 5 a\u00f1os, 2\u00ba de Primaria y 3\u00ba de Primaria van a recibir unas charlas sobre la actitud postural. Para ello un miembro del Colegio de Fisioterapeutas de Madrid, ser\u00e1 la encargada de realizarlas.<\/p>\n<p>Esta charlas tienen como objetivo, la prevenci\u00f3n\u00a0del dolor de espalda en escolares; un 25 % de los ni\u00f1os de edades comprendidas entre los 8 &#8211; 9 a\u00f1os se quejan a sus padres que sufren dolor de espalda, m\u00e1s frecuentemente la zona lumbar. Sin embargo, en el \u00e1mbito escolar, los alumnos se quejan a sus profesores en m\u00e1s de 40%\u00a0 que sufren problemas de espalda.<\/p>\n<p>La campa\u00f1a tiene como fin convertir a los m\u00e1s peque\u00f1os de la casa en los \u00abvigilantes\u00bb de los buenos h\u00e1bitos posturales con el fin que el adulto tambi\u00e9n recuerde y siga estos buenos h\u00e1bitos en su vida diaria. Y es que es m\u00e1s f\u00e1cil educar a un ni\u00f1o, que reeducar a un adulto un actitud postural incorrecta, dado que lo que se aprenden a estas edades, este buen h\u00e1bito se reproducir\u00e1 en la edad adulta.\u00a0<\/p>\n<p>M\u00e1s informaci\u00f3n en la web del Colegio Profesional de FISIOTERAPEUTAS \u00a0de la Comunidad de Madrid:<\/p>\n<p><a href=\"https:\/\/www.cfisiomad.org\/PrevencionEscolares\/\" target=\"_blank\" rel=\"alternate noopener noreferrer\">https:\/\/www.cfisiomad.org\/PrevencionEscolares\/<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.colegiofisio-clm.org\/imagenes\/noticias\/imagen_noticia_232.1461826092.jpg\" alt=\"Campa\u00f1a de higiene postural escolar en colaboraci\u00f3n con el Colegio de Madrid\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3486\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0007.jpg\" alt=\"\" width=\"324\" height=\"432\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0007.jpg 1200w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0007-225x300.jpg 225w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0007-768x1024.jpg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0007-300x400.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0007-1152x1536.jpg 1152w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><\/p>\n<p>Para los alumnos de Infantil, Blanca la Fisioterapeuta destinada a nuestro Colegio, introduce el tema, con un marciano que nos quiere transmitir el mensaje de advertencia sobre los dolores de espalda por malas posturas.<\/p>\n<p>A continuaci\u00f3n ten\u00e9is algunas fotos de la actividad.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3487\" src=\"http:\/\/quieropaginaweb.es\/wp\/wp-content\/uploads\/2017\/02\/20170210_093957-scaled.jpg\" alt=\"\" width=\"466\" height=\"262\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3488\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0009.jpg\" alt=\"\" width=\"467\" height=\"350\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0009.jpg 1600w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0009-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0009-1024x768.jpg 1024w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0009-768x576.jpg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0009-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 467px) 100vw, 467px\" \/><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<h3 class=\"resumen\">\u00a0<\/h3>\n<div class=\"formato-texto-seccion\">\n<p>Es semana y la que viene, los alumnos y alumnas de 4 a\u00f1os, 5 a\u00f1os, 2\u00ba de Primaria y 3\u00ba de Primaria van a recibir unas charlas sobre la actitud postural. Para ello un miembro del Colegio de Fisioterapeutas de Madrid, ser\u00e1 la encargada de realizarlas.<\/p>\n<p>Esta charlas tienen como objetivo, la prevenci\u00f3n\u00a0del dolor de espalda en escolares; un 25 % de los ni\u00f1os de edades comprendidas entre los 8 &#8211; 9 a\u00f1os se quejan a sus padres que sufren dolor de espalda, m\u00e1s frecuentemente la zona lumbar. Sin embargo, en el \u00e1mbito escolar, los alumnos se quejan a sus profesores en m\u00e1s de 40%\u00a0 que sufren problemas de espalda.<\/p>\n<p>La campa\u00f1a tiene como fin convertir a los m\u00e1s peque\u00f1os de la casa en los \u00abvigilantes\u00bb de los buenos h\u00e1bitos posturales con el fin que el adulto tambi\u00e9n recuerde y siga estos buenos h\u00e1bitos en su vida diaria. Y es que es m\u00e1s f\u00e1cil educar a un ni\u00f1o, que reeducar a un adulto un actitud postural incorrecta, dado que lo que se aprenden a estas edades, este buen h\u00e1bito se reproducir\u00e1 en la edad adulta.\u00a0<\/p>\n<p>M\u00e1s informaci\u00f3n en la web del Colegio Profesional de FISIOTERAPEUTAS \u00a0de la Comunidad de Madrid:<\/p>\n<p><a href=\"https:\/\/www.cfisiomad.org\/PrevencionEscolares\/\" target=\"_blank\" rel=\"alternate noopener noreferrer\">https:\/\/www.cfisiomad.org\/PrevencionEscolares\/<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.colegiofisio-clm.org\/imagenes\/noticias\/imagen_noticia_232.1461826092.jpg\" alt=\"Campa\u00f1a de higiene postural escolar en colaboraci\u00f3n con el Colegio de Madrid\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3486\" src=\"http:\/\/quieropaginaweb.es\/wp\/wp-content\/uploads\/2017\/02\/IMG-20170209-WA0007.jpg\" alt=\"\" width=\"324\" height=\"432\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0007.jpg 1200w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0007-225x300.jpg 225w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0007-768x1024.jpg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0007-300x400.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170209-WA0007-1152x1536.jpg 1152w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"post_folder":[],"class_list":["post-1359","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"\u00a0 Es semana y la que viene, los alumnos y alumnas de 4 a\u00f1os, 5 a\u00f1os, 2\u00ba de Primaria y 3\u00ba de Primaria van a recibir unas charlas sobre la actitud postural. Para ello un miembro del Colegio de Fisioterapeutas de Madrid, ser\u00e1 la encargada de realizarlas. Esta charlas tienen como objetivo, la prevenci\u00f3n\u00a0del dolor&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1359"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1359\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1359"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}