{"id":13637,"date":"2025-09-11T15:57:52","date_gmt":"2025-09-11T13:57:52","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/?p=13637"},"modified":"2025-09-11T16:08:21","modified_gmt":"2025-09-11T14:08:21","slug":"deporte-escolar-curso-2025-2026","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2025\/09\/11\/deporte-escolar-curso-2025-2026\/","title":{"rendered":"DEPORTE ESCOLAR CURSO 2025-2026"},"content":{"rendered":"<p class=\"v1elementToProof\">Estimadas familias:<\/p>\n<p class=\"v1elementToProof\">El AMPA Carlos III es la encargada de organizar los equipos de los Juegos Escolares, son diversas competiciones y actividades deportivas, que desde hace d\u00e9cadas, la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez organiza, dirigidos a deportistas en edad escolar, e integrados en el Programa de Deporte Infantil de la Comunidad como una de sus fases locales, constituyen un elemento fundamental en la promoci\u00f3n del deporte en nuestro municipio.<\/p>\n<p class=\"v1elementToProof\">El AMPA del CEIP Carlos III invita a que apunt\u00e9is a vuestros hijos\/as a los equipos del Colegio, para poder mantener esta competici\u00f3n que fomenta el deporte base y pone al alcance de todos los ni\u00f1os y ni\u00f1as la actividad f\u00edsica y todos los valores positivos que el deporte en equipo fomenta.<\/p>\n<div class=\"v1elementToProof\">Con la finalidad de poder agilizar y formar los equipos que representen a nuestro colegio, en los Juegos Escolares 2025\/26, desde el AMPA del CEIP Carlos III, os invitamos a que apunt\u00e9is a vuestros hijos\/as al\u00a0deporte\u00a0que le guste de los que ofertamos.<\/div>\n<div><\/div>\n<div class=\"v1elementToProof\">En la hoja de inscripci\u00f3n que os adjuntamos al final, os indicamos los horarios de entrenamiento <b>PROVISIONALES (quedando sujetos a modificaciones acorde con las actividades extraescolares o a petici\u00f3n de los entrenadores)<\/b>. Todos aquellos familiares o conocidos que quieran colaborar entrenando a los equipos del Colegio, no duden en ponerse en contacto con el AMPA.<\/div>\n<div><\/div>\n<div class=\"v1elementToProof\">Si est\u00e1is interesados en que vuestro hijo\/a participe en alguno de estos\u00a0deportes, tan solo ten\u00e9is que rellenar la parte inferior de esta hoja y enviarla al correo\u00a0<b><a id=\"v1OWA93ca314e-6199-8c37-eadd-fffb866f81df\" class=\"v1x_x_x_OWAAutoLink\" title=\"mailto:carlosiiideportes@gmail.com\" href=\"mailto:carlosiiideportes@gmail.com\" rel=\"noreferrer\">carlosiiideportes@gmail.com<\/a><\/b>.<\/div>\n<div class=\"v1elementToProof\">Y enviar justificante de pago de la aportaci\u00f3n \u00fanica de 5\u20ac para socios y 10\u20ac para no socios al correo del AMPA ampacarlosiii@hotmail.es, en el momento de la inscripci\u00f3n.<\/div>\n<div><\/div>\n<div class=\"v1elementToProof\">Con el fin de que cada equipo pueda disponer de m\u00e1s material para la pr\u00e1ctica deportiva (balones, red, petos, conos, botiqu\u00edn&#8230;.). Habr\u00e1 una\u00a0<b>aportaci\u00f3n \u00fanica anual de 10 \u20ac para los NO Socios del AMPA y 5\u20ac para los Socios.<\/b> (Este pago debe realizarse en el momento de la inscripci\u00f3n, mediante transferencia bancaria y enviando justificante de pago al correo del AMPA:<b> ampacarlosiii@hotmail.es)<\/b><\/div>\n<div><\/div>\n<h2 class=\"v1elementToProof\"><b>Datos bancarios:<\/b><\/h2>\n<div class=\"v1elementToProof\">Titular: AMPA Carlos III, IBAN: ES4100491815162410399331<\/div>\n<div class=\"v1elementToProof\">Indicar en el concepto del pago: apellidos y nombre del alumno y el\u00a0deporte\u00a0elegido.<\/div>\n<div class=\"v1elementToProof\">\u00a1\u00a1Os esperamos en nuestros equipos!!<\/div>\n<div class=\"v1elementToProof\">Cualquier duda nos pod\u00e9is escribir a este mail o llamar al tel\u00e9fono del AMPA: 693005635<\/div>\n<div class=\"v1elementToProof\">Saludos,<\/div>\n<div class=\"v1elementToProof\">Junta Directiva AMPA Carlos III<\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: center;\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2025\/09\/INSCRIPCION-DEPORTES.pdf\">INSCRIPCION DEPORTES<\/a><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: El AMPA Carlos III es la encargada de organizar los equipos de los Juegos Escolares, son diversas competiciones y actividades deportivas, que desde hace d\u00e9cadas, la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez organiza, dirigidos a deportistas en edad escolar, e integrados en el Programa de Deporte Infantil de la Comunidad como una &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2025\/09\/11\/deporte-escolar-curso-2025-2026\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDEPORTE ESCOLAR CURSO 2025-2026\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-13637","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"Estimadas familias: El AMPA Carlos III es la encargada de organizar los equipos de los Juegos Escolares, son diversas competiciones y actividades deportivas, que desde hace d\u00e9cadas, la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez organiza, dirigidos a deportistas en edad escolar, e integrados en el Programa de Deporte Infantil de la Comunidad como una&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/13637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=13637"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/13637\/revisions"}],"predecessor-version":[{"id":13646,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/13637\/revisions\/13646"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=13637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=13637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=13637"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=13637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}