{"id":1370,"date":"2017-02-16T09:03:44","date_gmt":"2017-02-16T09:03:44","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1370"},"modified":"2017-02-16T09:03:44","modified_gmt":"2017-02-16T09:03:44","slug":"charla-de-actitud-postural-a-los-ninos-del-colegio","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/02\/16\/charla-de-actitud-postural-a-los-ninos-del-colegio\/","title":{"rendered":"CHARLA DE ACTITUD POSTURAL A LOS NI\u00d1OS Y NI\u00d1AS DE 2\u00ba Y 3\u00ba DE PRIMARIA"},"content":{"rendered":"<p>Los ni\u00f1os y ni\u00f1as de 2\u00ba y 3\u00ba de Primaria han participado en unas charlas sobre actitud postural. El objetivo principal de esta actividad es prevenir, desde la infancia, lesiones m\u00fasculo-esquel\u00e9ticas provocadas por malas posturas.<\/p>\n<p>\u00a0<\/p>\n<p>A continuaci\u00f3n os presentamos los comentarios y dibujos realizados por los alumnos\/as sobre esta actividad.<\/p>\n<p>Hoy hemos entrado al cole. A la 2\u00aa hora nos tocaba Matem\u00e1ticas y ha venido una se\u00f1ora y nos ha dicho que nos vayamos \u00a1ya! Nos ha dicho Marta Patricia que en orden de lista y yo me he puesto la n\u00famero 20 y eso. Nos hemos ido a la clase de ordenadores y esa se\u00f1ora que se llamaba Blanca, nos ha empezado a hablar de como sentarnos bien y luego ha tra\u00eddo dos mochilas, una de Leyre y otra de V\u00edctor, y a Antonio le ha dicho que se imaginar\u00e1 unas escaleras que van subiendo y le ha preguntado \u00bfC\u00f3mo subir\u00edas la mochila de V\u00edctor? Luego con la mochila de Leyre nos ha explicado c\u00f3mo nos ponemos la mochila. Y todos lo hac\u00edamos mal y lo que estaba bien era ponerse la mochila en lo alto de una mesa, que te la coja una persona y m\u00e1s cosas de esas. Tambi\u00e9n nos ha puesto un v\u00eddeo de Zgmrtsglub, lo s\u00e9 es un nombre muy raro, porque es un extraterrestre.<\/p>\n<p>Al final nos han dado un sobre y ella lo ten\u00eda abierto y nos lo ha ense\u00f1ado, es muy guay, me ha encantado. Adi\u00f3s.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3499\" src=\"http:\/\/quieropaginaweb.es\/wp\/wp-content\/uploads\/2017\/02\/21136-12-scaled.jpg\" alt=\"\" width=\"215\" height=\"304\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3500\" src=\"http:\/\/quieropaginaweb.es\/wp\/wp-content\/uploads\/2017\/02\/21136-11-scaled.jpg\" alt=\"\" width=\"215\" height=\"304\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3501\" src=\"http:\/\/quieropaginaweb.es\/wp\/wp-content\/uploads\/2017\/02\/20170215_105717-scaled.jpg\" alt=\"\" width=\"447\" height=\"252\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3502\" src=\"http:\/\/quieropaginaweb.es\/wp\/wp-content\/uploads\/2017\/02\/21134-3-scaled.jpg\" alt=\"\" width=\"452\" height=\"639\" \/><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ni\u00f1os y ni\u00f1as de 2\u00ba y 3\u00ba de Primaria han participado en unas charlas sobre actitud postural. El objetivo principal de esta actividad es prevenir, desde la infancia, lesiones m\u00fasculo-esquel\u00e9ticas provocadas por malas posturas.<\/p>\n<p>\u00a0<\/p>\n<p>A continuaci\u00f3n os presentamos los comentarios y dibujos realizados por los alumnos\/as sobre esta actividad.<\/p>\n<p>Hoy hemos entrado al cole. A la 2\u00aa hora nos tocaba Matem\u00e1ticas y ha venido una se\u00f1ora y nos ha dicho que nos vayamos \u00a1ya! Nos ha dicho Marta Patricia que en orden de lista y yo me he puesto la n\u00famero 20 y eso. Nos hemos ido a la clase de ordenadores y esa se\u00f1ora que se llamaba Blanca, nos ha empezado a hablar de como sentarnos bien y luego ha tra\u00eddo dos mochilas, una de Leyre y otra de V\u00edctor, y a Antonio le ha dicho que se imaginar\u00e1 unas escaleras que van subiendo y le ha preguntado \u00bfC\u00f3mo subir\u00edas la mochila de V\u00edctor? Luego con la mochila de Leyre nos ha explicado c\u00f3mo nos ponemos la mochila. Y todos lo hac\u00edamos mal y lo que estaba bien era ponerse la mochila en lo alto de una mesa, que te la coja una persona y m\u00e1s cosas de esas. Tambi\u00e9n nos ha puesto un v\u00eddeo de Zgmrtsglub, lo s\u00e9 es un nombre muy raro, porque es un extraterrestre.<\/p>\n<p>Al final nos han dado un sobre y ella lo ten\u00eda abierto y nos lo ha ense\u00f1ado, es muy guay, me ha encantado. Adi\u00f3s.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3499\" src=\"http:\/\/quieropaginaweb.es\/wp\/wp-content\/uploads\/2017\/02\/21136-12-scaled.jpg\" alt=\"\" width=\"215\" height=\"304\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3500\" src=\"http:\/\/quieropaginaweb.es\/wp\/wp-content\/uploads\/2017\/02\/21136-11-scaled.jpg\" alt=\"\" width=\"215\" height=\"304\" \/><\/p>\n","protected":false},"author":3,"featured_media":3498,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"post_folder":[],"class_list":["post-1370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3-primaria"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1.jpg",1810,2560,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1.jpg",1810,2560,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1.jpg",1810,2560,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1-212x300.jpg",212,300,true],"large":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1-724x1024.jpg",525,743,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1.jpg",354,500,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1-1086x1536.jpg",1086,1536,true],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1-1448x2048.jpg",1448,2048,true],"twentyseventeen-featured-image":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1-1810x1200.jpg",1810,1200,true],"twentyseventeen-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1-100x100.jpg",100,100,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1.jpg",337,476,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1.jpg",170,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21136-12-scaled-1.jpg",1810,2560,false]},"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/3-primaria\/\" rel=\"category tag\">3\u00ba Primaria<\/a>","rttpg_excerpt":"Los ni\u00f1os y ni\u00f1as de 2\u00ba y 3\u00ba de Primaria han participado en unas charlas sobre actitud postural. El objetivo principal de esta actividad es prevenir, desde la infancia, lesiones m\u00fasculo-esquel\u00e9ticas provocadas por malas posturas. \u00a0 A continuaci\u00f3n os presentamos los comentarios y dibujos realizados por los alumnos\/as sobre esta actividad. Hoy hemos entrado al&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1370"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media\/3498"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1370"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}