{"id":1382,"date":"2017-02-22T13:46:50","date_gmt":"2017-02-22T13:46:50","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1382"},"modified":"2017-02-22T13:46:50","modified_gmt":"2017-02-22T13:46:50","slug":"diptico-convocatoria-de-participacion-en-el-programa-municipal-de-libros","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/02\/22\/diptico-convocatoria-de-participacion-en-el-programa-municipal-de-libros\/","title":{"rendered":"D\u00cdPTICO CONVOCATORIA DE PARTICIPACI\u00d3N EN EL PROGRAMA MUNICIPAL DE LIBROS"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3506\" src=\"http:\/\/quieropaginaweb.es\/wp\/wp-content\/uploads\/2017\/02\/21344-2-scaled.jpg\" alt=\"\" width=\"691\" height=\"488\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3507\" src=\"http:\/\/quieropaginaweb.es\/wp\/wp-content\/uploads\/2017\/02\/21344-1-scaled.jpg\" alt=\"\" width=\"687\" height=\"486\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":3505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"post_folder":[],"class_list":["post-1382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2-tramo"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1.jpg",2560,1810,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1.jpg",2560,1810,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1.jpg",2560,1810,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1-300x212.jpg",300,212,true],"large":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1-1024x724.jpg",525,371,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1.jpg",500,354,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1-1536x1086.jpg",1536,1086,true],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1-2048x1448.jpg",2048,1448,true],"twentyseventeen-featured-image":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1-2000x1200.jpg",2000,1200,true],"twentyseventeen-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1-100x100.jpg",100,100,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1.jpg",360,255,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1.jpg",339,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/21344-2-scaled-1.jpg",2560,1810,false]},"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/2-tramo\/\" rel=\"category tag\">2\u00ba Tramo<\/a>","rttpg_excerpt":null,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1382"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1382\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media\/3505"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1382"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}