{"id":1383,"date":"2017-02-22T13:53:47","date_gmt":"2017-02-22T13:53:47","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1383"},"modified":"2017-02-22T13:53:47","modified_gmt":"2017-02-22T13:53:47","slug":"recogida-de-documentacion-ex-alumnos","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/02\/22\/recogida-de-documentacion-ex-alumnos\/","title":{"rendered":"RECOGIDA DE DOCUMENTACI\u00d3N EX-ALUMNOS"},"content":{"rendered":"<p>Estimadas familias de 6\u00ba de Educaci\u00f3n Primaria. Curso Escolar 2015-2016<\/p>\n<p>Os informamos que el plazo de RECOGIDA DE DOCUMENTACI\u00d3N pendiente referente a vuestros hijos\/as, ser\u00e1 del D\u00cdA 27 DE FEBRERO AL 3 DE MARZO DE 2017.<\/p>\n<p>Entre la documentaci\u00f3n a entregar se encuentra:<\/p>\n<p>&#8211; Historial Acad\u00e9mico (Original para las familias).<\/p>\n<p>&#8211; Carpeta Documentaci\u00f3n (Copia Historial Acad\u00e9mico y otros documentos para el IES en el que est\u00e1n cursando 1\u00baESO).<\/p>\n<p>\u00a0<\/p>\n<p>LUGAR: \u00a0 \u00a0 \u00a0 \u00a0SECRETAR\u00cdA DEL CENTRO<\/p>\n<p>HORARIO: \u00a0 De 09:00 a 14:00 horas.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0EQUIPO DIRECTIVO<\/p>\n<p>\u00a0<\/p>\n<p>Nota: La documentaci\u00f3n debe ser recogida por los padres\/madres\/tutores legales o en su defecto adulto debidamente autorizado con copia de DNI, pues deben firmar el RECIB\u00cd a la entrega de la documentaci\u00f3n arriba indicada.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias de 6\u00ba de Educaci\u00f3n Primaria. Curso Escolar 2015-2016 Os informamos que el plazo de RECOGIDA DE DOCUMENTACI\u00d3N pendiente referente a vuestros hijos\/as, ser\u00e1 del D\u00cdA 27 DE FEBRERO AL 3 DE MARZO DE 2017. Entre la documentaci\u00f3n a entregar se encuentra: &#8211; Historial Acad\u00e9mico (Original para las familias). &#8211; Carpeta Documentaci\u00f3n (Copia Historial &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/02\/22\/recogida-de-documentacion-ex-alumnos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abRECOGIDA DE DOCUMENTACI\u00d3N EX-ALUMNOS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"post_folder":[],"class_list":["post-1383","post","type-post","status-publish","format-standard","hentry","category-ex-alumnos"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/ex-alumnos\/\" rel=\"category tag\">Ex-Alumnos<\/a>","rttpg_excerpt":"Estimadas familias de 6\u00ba de Educaci\u00f3n Primaria. Curso Escolar 2015-2016 Os informamos que el plazo de RECOGIDA DE DOCUMENTACI\u00d3N pendiente referente a vuestros hijos\/as, ser\u00e1 del D\u00cdA 27 DE FEBRERO AL 3 DE MARZO DE 2017. Entre la documentaci\u00f3n a entregar se encuentra: &#8211; Historial Acad\u00e9mico (Original para las familias). &#8211; Carpeta Documentaci\u00f3n (Copia Historial&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1383"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1383\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1383"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}