{"id":1390,"date":"2017-02-24T06:06:40","date_gmt":"2017-02-24T06:06:40","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1390"},"modified":"2017-02-24T06:06:40","modified_gmt":"2017-02-24T06:06:40","slug":"photocall-de-mardi-gras","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/02\/24\/photocall-de-mardi-gras\/","title":{"rendered":"PHOTOCALL DE MARDI GRAS"},"content":{"rendered":"<p>Una clase de infantil ha elaborado un photocall para que todos podamos hacernos fotos vestidos de arquel\u00edn, a continuaci\u00f3n pod\u00e9is ver el proceso de construcci\u00f3n y algunas de las primeras fotos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3514\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032.jpg\" alt=\"\" width=\"275\" height=\"487\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3515\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0031.jpg\" alt=\"\" width=\"275\" height=\"489\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0031.jpg 900w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0031-169x300.jpg 169w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0031-576x1024.jpg 576w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0031-768x1365.jpg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0031-864x1536.jpg 864w\" sizes=\"auto, (max-width: 275px) 100vw, 275px\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3516\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0008.jpg\" alt=\"\" width=\"550\" height=\"733\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0008.jpg 1200w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0008-225x300.jpg 225w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0008-768x1024.jpg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0008-300x400.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0008-1152x1536.jpg 1152w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una clase de infantil ha elaborado un photocall para que todos podamos hacernos fotos vestidos de arquel\u00edn, a continuaci\u00f3n pod\u00e9is ver el proceso de construcci\u00f3n y algunas de las primeras fotos.<\/p>\n","protected":false},"author":3,"featured_media":3514,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"post_folder":[],"class_list":["post-1390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-centro"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032.jpg",900,1600,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032.jpg",900,1600,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032.jpg",900,1600,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032-169x300.jpg",169,300,true],"large":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032-576x1024.jpg",525,933,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032.jpg",281,500,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032-864x1536.jpg",864,1536,true],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032.jpg",900,1600,false],"twentyseventeen-featured-image":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032-900x1200.jpg",900,1200,true],"twentyseventeen-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032-100x100.jpg",100,100,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032.jpg",268,476,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032.jpg",135,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/02\/IMG-20170223-WA0032.jpg",900,1600,false]},"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/centro\/\" rel=\"category tag\">Centro<\/a>","rttpg_excerpt":"Una clase de infantil ha elaborado un photocall para que todos podamos hacernos fotos vestidos de arquel\u00edn, a continuaci\u00f3n pod\u00e9is ver el proceso de construcci\u00f3n y algunas de las primeras fotos.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1390"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1390\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media\/3514"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1390"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}