{"id":1411,"date":"2017-03-07T13:40:44","date_gmt":"2017-03-07T13:40:44","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1411"},"modified":"2017-03-07T13:40:44","modified_gmt":"2017-03-07T13:40:44","slug":"visita-de-ex-alumnos-as-de-4-mas-empresas","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/03\/07\/visita-de-ex-alumnos-as-de-4-mas-empresas\/","title":{"rendered":"VISITA DE EX-ALUMNOS\/AS DE 4\u00ba M\u00c1S EMPRESAS"},"content":{"rendered":"<p>Del 27 al 31 de marzo, vamos a recibir la visita de 7 antiguos alumnos\/as del colegio, dentro del programa de la Conserjer\u00eda de Educaci\u00f3n 4\u00aa ESO + Empresa. Este programa tiene el fin de acercar el sistema educativo y el mundo laboral, facilitando mediante estancias educativas en empresas e instituciones que los j\u00f3venes est\u00e9n mejor preparados para tomar decisiones sobre su futuro acad\u00e9mico y profesional.<\/p>\n<p>Las estancias educativas consisten b\u00e1sicamente en la asistencia durante unos d\u00edas a las instalaciones de una empresa para observar c\u00f3mo se desarrolla la actividad y pueden incluir el desarrollo de tareas o funciones por parte de un estudiante de 4\u00ba ESO, enfatizando aspectos educativos de todo el proceso. \u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 27 al 31 de marzo, vamos a recibir la visita de 7 antiguos alumnos\/as del colegio, dentro del programa de la Conserjer\u00eda de Educaci\u00f3n 4\u00aa ESO + Empresa. Este programa tiene el fin de acercar el sistema educativo y el mundo laboral, facilitando mediante estancias educativas en empresas e instituciones que los j\u00f3venes est\u00e9n &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/03\/07\/visita-de-ex-alumnos-as-de-4-mas-empresas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abVISITA DE EX-ALUMNOS\/AS DE 4\u00ba M\u00c1S EMPRESAS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"post_folder":[],"class_list":["post-1411","post","type-post","status-publish","format-standard","hentry","category-ex-alumnos"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/ex-alumnos\/\" rel=\"category tag\">Ex-Alumnos<\/a>","rttpg_excerpt":"Del 27 al 31 de marzo, vamos a recibir la visita de 7 antiguos alumnos\/as del colegio, dentro del programa de la Conserjer\u00eda de Educaci\u00f3n 4\u00aa ESO + Empresa. Este programa tiene el fin de acercar el sistema educativo y el mundo laboral, facilitando mediante estancias educativas en empresas e instituciones que los j\u00f3venes est\u00e9n&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1411"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1411\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1411"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}