{"id":1450,"date":"2017-03-25T08:07:23","date_gmt":"2017-03-25T08:07:23","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1450"},"modified":"2017-03-25T08:07:23","modified_gmt":"2017-03-25T08:07:23","slug":"reunion-comite-organizador-charlie-league","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/03\/25\/reunion-comite-organizador-charlie-league\/","title":{"rendered":"REUNI\u00d3N COMIT\u00c9 ORGANIZADOR CHARLIE LEAGUE"},"content":{"rendered":"<p>El viernes 24 de marzo, se reuni\u00f3 el Comit\u00e9 organizador de la Charlie League con el fin de revisar la competici\u00f3n y coordinar los siguientes torneo.<\/p>\n<p>\u00a0<\/p>\n<p>Se analiza lo que llevamos de Liga:<\/p>\n<p>\u00a0\u00a0 En 4\u00ba y 5\u00ba se desarrolla con normalidad, las \u00fanicas incidencias han ocurrido cuando por necesidad ha arbitrado alg\u00fan partido alguien que no estaba en el Comit\u00e9 y se ha accedido en el tiempo no juego.<\/p>\n<p>Para solventar este problema, vamos a designar varios \u00e1rbitros (ni\u00f1os y ni\u00f1as que practiquen este deporte con regularidad y que sean respetados por todos sus compa\u00f1eros) por deporte desde el inicio, los alumnos\/as sexto que les toque arbitrar, hablar\u00e1n con Jos\u00e9 Luis varios d\u00edas antes y ver\u00e1n su necesidad en el ensayo del musical de 6\u00ba en caso de que lo hubiera. Tambi\u00e9n decidimos comunicarles a las clases, que deben respetar las decisiones de los \u00e1rbitros y entender que Jugamos para divertirnos.<\/p>\n<p>\u00a0\u00a0 En 6\u00ba y despu\u00e9s de la eliminaci\u00f3n del torneo de f\u00fatbol, vuelven a participar en baloncesto. Se les da una segunda oportunidad,\u00a0 con el compromiso de todos aquellos que quieran participar de cumplir las normas de Juego Limpio, que firmaron.<\/p>\n<p>\u00a0<\/p>\n<p>Tambi\u00e9n se comenta que a partir de la Charlie League, est\u00e1n jugando entre las clases otros d\u00edas, con mayor normalidad y que parece que hay menos conflictos jugando o que se resuelven con normalidad.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Organizaci\u00f3n de los siguientes torneos:<\/p>\n<p>\u00a0<\/p>\n<p>Se decide acelerar los torneos y jugar a dos campeonatos por mes, para poder realizar todas las competiciones.<\/p>\n<p>Los siguientes, seg\u00fan lo decidido ser\u00e1n baloncesto y balonmano.<\/p>\n<p>Se habla de organizar a la vez el torneo de tenis de mesa, pero no somos los suficientes para gestionarlo y hay muchas propuestas de actividades para el recreo (Radio Escolar, Banda de Rock, Musical de 6\u00ba, Pitufos, Eco-patrullas,\u00a0 \u2026.), lo que har\u00eda que se solapar\u00e1n m\u00e1s cosas y se complicar\u00e1 la organizaci\u00f3n.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Reglas de baloncesto:<\/p>\n<p>\u00a0\u00a0 7 minutos sin parar el reloj, para que se puedan jugar los 3 partidos del torneo.\u00a0<\/p>\n<p>\u00a0\u00a0 Se juegan los 3 partidos seguidos.<\/p>\n<p>\u00a0\u00a0 8 jugadores en pista m\u00e1ximo por equipo, las clases que tengan menos de ese n\u00famero tendr\u00e1n que jugar en inferioridad. \u00a0<\/p>\n<p>\u00a0\u00a0 Salvo los pasos, los 3 segundos en la zona, los dobles y el manejo, que se ser\u00e1 poco riguroso con estas infracciones, las dem\u00e1s reglas ser\u00e1n las normales.<\/p>\n<p>\u00a0\u00a0 No hay triple, ya que la l\u00ednea no est\u00e1 se\u00f1alada en la pista.<\/p>\n<p>\u00a0\u00a0 \u00c1rbitros: Nacho C., Marcos Y., Diego R., Gonzalo, Sof\u00eda, Marcos S. y Luc\u00eda N.<\/p>\n<p>\u00a0\u00a0 Los partidos comenzar\u00e1n a las 12:03. La mejor forma de pedir puntualidad a los profesores, es comportarnos bien, bajar en orden y en silencio, \u2026.. \u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Calendario Torneo de Baloncesto:<\/p>\n<p>Martes 28 de marzo (\u00e1rbitros Nacho, Diego y Luc\u00eda) 4\u00baA vs 4\u00baC\u00a0\u00a0 4\u00baB vs 4\u00baC\u00a0\u00a0\u00a0 4\u00baA vs 4\u00baB<\/p>\n<p>Mi\u00e9rcoles 29 de marzo (Marcos Y, Marcos S., Diego y Luc\u00eda) 5\u00baA vs 5\u00baC\u00a0\u00a0 5\u00baB vs 5\u00baC\u00a0\u00a0 5\u00baA vs 5\u00baB<\/p>\n<p>Jueves 30 de marzo (Sof\u00eda, Nacho y Diego)\u00a0 6\u00baA vs 6\u00baC\u00a0 6\u00baB vs 6\u00baC\u00a0\u00a0 6\u00baA vs 6\u00baB<\/p>\n<p>\u00a0<\/p>\n<p>Calendario Torneo de Balonmano (arbitran Ana y Roc\u00edo):<\/p>\n<p>Martes 25 de abril: 4\u00baA vs 4\u00baC\u00a0\u00a0 4\u00baB vs 4\u00baC\u00a0\u00a0\u00a0 4\u00baA vs 4\u00baB<\/p>\n<p>Mi\u00e9rcoles 26 de abril: 5\u00baA vs 5\u00baC\u00a0\u00a0 5\u00baB vs 5\u00baC\u00a0\u00a0 5\u00baA vs 5\u00baB<\/p>\n<p>Jueves 27 de abril: 6\u00baA vs 6\u00baC\u00a0 6\u00baB vs 6\u00baC\u00a0\u00a0 6\u00baA vs 6\u00baB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viernes 24 de marzo, se reuni\u00f3 el Comit\u00e9 organizador de la Charlie League con el fin de revisar la competici\u00f3n y coordinar los siguientes torneo.<\/p>\n<p>\u00a0<\/p>\n<p>Se analiza lo que llevamos de Liga:<\/p>\n<p>\u00a0\u00a0 En 4\u00ba y 5\u00ba se desarrolla con normalidad, las \u00fanicas incidencias han ocurrido cuando por necesidad ha arbitrado alg\u00fan partido alguien que no estaba en el Comit\u00e9 y se ha accedido en el tiempo no juego.<\/p>\n<p>Para solventar este problema, vamos a designar varios \u00e1rbitros (ni\u00f1os y ni\u00f1as que practiquen este deporte con regularidad y que sean respetados por todos sus compa\u00f1eros) por deporte desde el inicio, los alumnos\/as sexto que les toque arbitrar, hablar\u00e1n con Jos\u00e9 Luis varios d\u00edas antes y ver\u00e1n su necesidad en el ensayo del musical de 6\u00ba en caso de que lo hubiera. Tambi\u00e9n decidimos comunicarles a las clases, que deben respetar las decisiones de los \u00e1rbitros y entender que Jugamos para divertirnos.<\/p>\n<p>\u00a0\u00a0 En 6\u00ba y despu\u00e9s de la eliminaci\u00f3n del torneo de f\u00fatbol, vuelven a participar en baloncesto. Se les da una segunda oportunidad,\u00a0 con el compromiso de todos aquellos que quieran participar de cumplir las normas de Juego Limpio, que firmaron.<\/p>\n<p>\u00a0<\/p>\n<p>Tambi\u00e9n se comenta que a partir de la Charlie League, est\u00e1n jugando entre las clases otros d\u00edas, con mayor normalidad y que parece que hay menos conflictos jugando o que se resuelven con normalidad.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"post_folder":[],"class_list":["post-1450","post","type-post","status-publish","format-standard","hentry","category-otras-iniciativas"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/pitufos-asamblea-de-alumnos-2\/otras-iniciativas\/\" rel=\"category tag\">Otras iniciativas<\/a>","rttpg_excerpt":"El viernes 24 de marzo, se reuni\u00f3 el Comit\u00e9 organizador de la Charlie League con el fin de revisar la competici\u00f3n y coordinar los siguientes torneo. \u00a0 Se analiza lo que llevamos de Liga: \u00a0\u00a0 En 4\u00ba y 5\u00ba se desarrolla con normalidad, las \u00fanicas incidencias han ocurrido cuando por necesidad ha arbitrado alg\u00fan partido&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1450"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1450\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1450"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}